{"id":218788,"date":"2023-07-20T12:25:00","date_gmt":"2023-07-20T10:25:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218788"},"modified":"2023-07-20T16:01:11","modified_gmt":"2023-07-20T14:01:11","slug":"maldarizzi-automotive-torna-in-campo-con-la-ssc-bari","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/20\/maldarizzi-automotive-torna-in-campo-con-la-ssc-bari\/","title":{"rendered":"MALDARIZZI AUTOMOTIVE TORNA IN CAMPO CON LA SSC BARI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1066\" class=\"wp-image-218789\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Maldarizzi-e-Bari-Calcio.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Maldarizzi-e-Bari-Calcio.jpeg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Maldarizzi-e-Bari-Calcio-300x200.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Maldarizzi-e-Bari-Calcio-1024x682.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Maldarizzi-e-Bari-Calcio-768x512.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Maldarizzi-e-Bari-Calcio-1536x1023.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p><strong>Rinnovata la partnership con la squadra biancorossa per la stagione sportiva 2023\/2024<\/strong><\/p>\n\n\n\n<p>BARI &#8211; Maldarizzi Automotive rinnova la sua partnership con la SSC Bari. Dopo aver accompagnato la squadra biancorossa nella stagione sportiva 2022\/2023, Maldarizzi Automotive S.p.A. diventa automotive partner per il 2023\/2024.<\/p>\n\n\n\n<p>Come punto di riferimento per la mobilit\u00e0, Maldarizzi dota la squadra di una flotta di veicoli per tutte le esigenze. Una scelta che abbraccia la sostenibilit\u00e0, attraverso anche l\u2019utilizzo di veicoli elettrici, entrando cos\u00ec nel secondo anno di collaborazione.<\/p>\n\n\n\n<p>Maldarizzi Automotive, nata nel 1979 nel Sud Italia e affermatasi come una delle pi\u00f9 importanti realt\u00e0 italiane del mercato automobilistico, con sedi dislocate tra la Puglia e la Basilicata, \u00e8 leader nella vendita di auto nuove, usate, km0, nei servizi di assistenza post-vendita, noleggio a medio e lungo termine, mobilit\u00e0 a 360\u00b0 e nell\u2019assistenza e ricambistica dei pi\u00f9 importanti marchi automobilistici. Maldarizzi Automotive costruisce cultura sul tema della mobilit\u00e0 per rendere consapevole il consumatore rispetto al servizio offerto, creando innovazione e ispirandosi ai trend di mercato internazionali Le concessionarie ufficiali: Lamborghini, Mercedes-Benz, AMG Performance Center e Mercedes-Benz V e Vans, BMW, MINI, Smart e smart #1, MG Motor, Ineos Grenadier, FIAT e Fiat Professional, Abarth, Alfa Romeo, JEEP, Lancia. Le divisioni: Maldarizzi Multibrand per l&#8217;usato garantito e per vetture km0, Maldarizzi 4Business per veicoli commerciali, allestiti e flotte, Maldarizzi Rent per noleggio a medio e lungo termine.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/20\/maldarizzi-automotive-torna-in-campo-con-la-ssc-bari\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/20\/maldarizzi-automotive-torna-in-campo-con-la-ssc-bari\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Rinnovata la partnership con la squadra biancorossa per la stagione sportiva 2023\/2024 BARI &#8211; Maldarizzi Automotive rinnova la sua partnership con la SSC Bari. Dopo aver accompagnato la squadra biancorossa nella stagione sportiva 2022\/2023, Maldarizzi Automotive S.p.A. diventa automotive partner per il 2023\/2024. Come punto di riferimento per la mobilit\u00e0, Maldarizzi dota la squadra di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218789,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218788"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218788"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218788\/revisions"}],"predecessor-version":[{"id":218790,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218788\/revisions\/218790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218789"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}