{"id":218802,"date":"2023-07-20T14:03:00","date_gmt":"2023-07-20T12:03:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218802"},"modified":"2023-07-20T15:58:52","modified_gmt":"2023-07-20T13:58:52","slug":"massima-esplosione-a-case-minime","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/20\/massima-esplosione-a-case-minime\/","title":{"rendered":"ESPLOSIONE MASSIMA A CASE MINIME"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"266\" height=\"189\" class=\"wp-image-218803\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/download-13.jpg\" alt=\"\"><\/p>\n\n\n\n<p>(e.l.) ______  Questa mattina c&#8217;\u00e8 stata una forte esplosione a Lecce rione San Pio, in via Sozy Carafa, sul balcone di un appartamento del complesso di case abbandonate dette &#8216;case minime&#8217; (nella foto). Ne \u00e8 seguito un principio di incendio subito domato dai Vigili del Fuoco accorsi sul posto. E&#8217; esplosa una bombola di gas, lasciata esposta al sole cocente e alle elevate temperature di questi giorni. Non ci sono feriti. La zona dello scoppio \u00e8 stata messa in sicurezza, in attesa della demolizione dell&#8217;intero complesso  prevista da tempo.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/20\/massima-esplosione-a-case-minime\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/20\/massima-esplosione-a-case-minime\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Questa mattina c&#8217;\u00e8 stata una forte esplosione a Lecce rione San Pio, in via Sozy Carafa, sul balcone di un appartamento del complesso di case abbandonate dette &#8216;case minime&#8217; (nella foto). Ne \u00e8 seguito un principio di incendio subito domato dai Vigili del Fuoco accorsi sul posto. E&#8217; esplosa una bombola di gas, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218803,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218802"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218802"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218802\/revisions"}],"predecessor-version":[{"id":218805,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218802\/revisions\/218805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218803"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}