{"id":218948,"date":"2023-07-24T13:30:50","date_gmt":"2023-07-24T11:30:50","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=218948"},"modified":"2023-07-24T13:32:12","modified_gmt":"2023-07-24T11:32:12","slug":"presunto-rapinatore-finisce-in-carcere-5","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/24\/presunto-rapinatore-finisce-in-carcere-5\/","title":{"rendered":"IN CARCERE PRESUNTO RAPINATORE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"938\" class=\"wp-image-218949\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Fotocomm.to-Gallipoli-.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Fotocomm.to-Gallipoli-.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Fotocomm.to-Gallipoli--300x176.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Fotocomm.to-Gallipoli--1024x600.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Fotocomm.to-Gallipoli--768x450.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/07\/Fotocomm.to-Gallipoli--1536x900.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p>(e.l.) ______  Agenti della Polizia di Stato del Commissariato di Gallipoli (nella foto), all&#8217;esito delle indagini intraprese per un mese, hanno arrestato un giovane di 39 anni, del quale non sono state rese note le generalit\u00e0. Secondo il gip del Tribunale diLecce che ha firmato un&#8217;ordinanza di custodia cautelare in carcere, richiesta dal pm della Procura della Repubblica, \u00e8 lui l&#8217;autore di una rapina avvenuta a giugno a Tuglie in un esercizio commerciale di spedizioni, sotto la minaccia di un coltello e con un bottino di 1.200 euro.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>condotteAvrebbe creato apprensione nella comunit\u00e0 di Tuglie, dopo aver perpetrato, poco pi\u00f9 di un mese fa, una rapina all\u2019interno di un esercizio commerciale addetto alle spedizioni, puntando un coltello alla gola di un dipendente in servizio allo sportello e con il volto parzialmente travisato.<\/p>\n\n\n\n<p>Sarebbe scappato a piedi portando con s\u00e9 la somma arraffata di circa 1.200,00 euro.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/24\/presunto-rapinatore-finisce-in-carcere-5\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/07\/24\/presunto-rapinatore-finisce-in-carcere-5\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Agenti della Polizia di Stato del Commissariato di Gallipoli (nella foto), all&#8217;esito delle indagini intraprese per un mese, hanno arrestato un giovane di 39 anni, del quale non sono state rese note le generalit\u00e0. Secondo il gip del Tribunale diLecce che ha firmato un&#8217;ordinanza di custodia cautelare in carcere, richiesta dal pm della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":218949,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218948"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=218948"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218948\/revisions"}],"predecessor-version":[{"id":218951,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/218948\/revisions\/218951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/218949"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=218948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=218948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=218948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}