{"id":219345,"date":"2023-08-03T16:19:24","date_gmt":"2023-08-03T14:19:24","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=219345"},"modified":"2023-08-03T16:22:53","modified_gmt":"2023-08-03T14:22:53","slug":"basta-guerra-e-chiudere-cerano-a-brindisi-due-manifestazioi-di-protesta-e-di-proposta-venerdi-4-in-mattinata","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/03\/basta-guerra-e-chiudere-cerano-a-brindisi-due-manifestazioi-di-protesta-e-di-proposta-venerdi-4-in-mattinata\/","title":{"rendered":"BASTA GUERRA, E CHIUDERE CERANO. A BRINDISI DUE MANIFESTAZIOI DI PROTESTA E DI PROPOSTA VENERDI&#8217; 4 IN MATTINATA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"288\" height=\"175\" class=\"wp-image-219346\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/download-3.jpg\" alt=\"\">(Rdl)\u00a0______ Nell&#8217;abito dell&#8217; \u2019Ostuni Climate Camp 2023&#8242;, che si sta svolgendo in localit\u00e0 Santa Lucia, Costa Merlata, Ostuni,  venerd\u00ec 4 agosto a Brindisi in mattinata sono previsti due sit in a tema:<\/p>\n\n\n\n<p>&#8211; ore 9,00 \u00a0\u00a0davanti al Castello di Federico II, alla sede del Comando della Marina Militare in via de Mille (nella foto) per dire NO a tutte le guerre<\/p>\n\n\n\n<p>-ore 10,00 davati il Comune di Brindisi in piazza Matteotti per dire NO alla decisione del Sindaco, Pino Marchionna, di appoggiare il progetto di un pericoloso deposito GNL di Edison nel porto di Brindisi, e per chiedere di non accettare le compensazioni elemosina di TAP\/SNAM per Torre Rossa, perch\u00e9 si \u00e8 trattato di danno ambientale per l\u2019intercettazione della falda di San Paolo. Ancora per chiedere al sindaco la fine della emergenza energetica con cui hanno riavviato i gruppi di produzione a carbone alla centrale Enel di Cerano conseguente alla guerra ucraina.<\/p>\n\n\n\n<p>Di questo rapporto Guerra \u2013 Energia si parler\u00e0 poi nel dibattito serale al Camp <em>\u201cGuerra e Energia: due temi che si incrociano\u201d<\/em>. A seguire il concerto del cantautore Mimmo Cavallo.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/03\/basta-guerra-e-chiudere-cerano-a-brindisi-due-manifestazioi-di-protesta-e-di-proposta-venerdi-4-in-mattinata\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/03\/basta-guerra-e-chiudere-cerano-a-brindisi-due-manifestazioi-di-protesta-e-di-proposta-venerdi-4-in-mattinata\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)\u00a0______ Nell&#8217;abito dell&#8217; \u2019Ostuni Climate Camp 2023&#8242;, che si sta svolgendo in localit\u00e0 Santa Lucia, Costa Merlata, Ostuni, venerd\u00ec 4 agosto a Brindisi in mattinata sono previsti due sit in a tema: &#8211; ore 9,00 \u00a0\u00a0davanti al Castello di Federico II, alla sede del Comando della Marina Militare in via de Mille (nella foto) per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":219346,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219345"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=219345"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219345\/revisions"}],"predecessor-version":[{"id":219349,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219345\/revisions\/219349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/219346"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=219345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=219345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=219345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}