{"id":219425,"date":"2023-08-05T19:02:43","date_gmt":"2023-08-05T17:02:43","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=219425"},"modified":"2023-08-05T19:02:47","modified_gmt":"2023-08-05T17:02:47","slug":"una-farsa-inutile-peggiorativa-ai-sindacati-non-piace-la-nuova-organizzazione-dellunisalento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/05\/una-farsa-inutile-peggiorativa-ai-sindacati-non-piace-la-nuova-organizzazione-dellunisalento\/","title":{"rendered":"\u201dUna farsa. Inutile. Peggiorativa\u201d. AI SINDACATI NON PIACE LA NUOVA ORGANIZZAZIONE DELL&#8217;UNISALENTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"512\" height=\"340\" class=\"wp-image-219426\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/unnamed-4.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/unnamed-4.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/unnamed-4-300x199.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. I sotto elencati delegati sindacali ci mandano il seguente counicato stampa con una dura presa di posizione riguardo la nuova organizzazione dell<strong>&#8216;<\/strong>Universit\u00e0 del Salento. Nella nostra foto, il rettore Fabio Pollice, definito, dopo quattro anni dall<strong>&#8216;<\/strong>\u00a0entrata in carica, eleento di continuit\u00e0 con le passate gestioni fallimentari, nonostante le promesse con cui si era presentato. ____________<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Con la delibera del Consiglio di Amministrazione di Unisalento, di approvazione del Modello di macro-organizzazione dell\u2019apparato tecnico amministrativo dell\u2019Ateneo, riteniamo che si sia conclusa quella che, se non ci fossero aspetti tragici, potrebbe essere a buon titolo definita una \u201cfarsa\u201d.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>Una farsa a pi\u00f9 atti. Il primo allorch\u00e9 l\u2019Amministrazione ha convocato le parti sindacali che avevano chiesto delucidazioni in merito senza per\u00f2 fornire loro uno \u201cstraccio\u201d di informazione. Il secondo rappresentato da una prima delibera del CdA di approvazione del Modello con l\u2019impegno ad ascoltare le osservazioni dei rappresentanti sindacali ed eventualmente recepirne le pi\u00f9 importanti. <\/p>\n\n\n\n<p>Il terzo ed ultimo atto \u00e8 la delibera del 25 luglio u.s. con la quale il CdA ha approvato definitivamente il Modello di riorganizzazione ignorando totalmente le osservazioni sindacali che recepivano le istanze pervenute dai lavoratori telematicamente ed emerse nel corso di un\u2019assemblea sindacale convocata da tutti i sindacati di Ateneo.<\/p>\n\n\n\n<p>Gli aspetti tragici, oltre al deterioramento delle relazioni sindacali, sono rappresentati dall\u2019inutilit\u00e0 del suddetto Modello in termini di miglioramento della funzionalit\u00e0 dei servizi offerti, dei processi e delle attivit\u00e0 da svolgere. Anzi si pu\u00f2 tranquillamente parlare di un peggioramento grazie alla maggiore confusione ed irragionevolezza che lo stesso Modello si avvia ad ingenerare.<\/p>\n\n\n\n<p>L\u2019archetipo del modello di macro organizzazione, si ispira, per ammissione della stessa Amministrazione, a fantomatici altri Modelli in uso presso altre Universit\u00e0, non si sa quali, pertanto non \u00e8 dato sapere l\u2019attinenza con le dinamiche e le esigenze del nostro Ateneo. Come risultato si sono ottenuti accorpamenti che non rispondono a criteri di logica e razionalit\u00e0. Gi\u00e0 in passato si era ritenuto di dover accoppiare l\u2019area tecnologica con quella tecnica e presto si era potuto riscontrare l\u2019irrazionalit\u00e0 di questa scelta. Ma perseverare nell\u2019errore per questa Amministrazione non \u00e8 diabolico bens\u00ec una \u201cvirt\u00f9\u201d.\u00a0 Infatti, sono state accorpate la ripartizione finanziaria con quella delle risorse umane creando in questo modo un gran \u201ccalderone\u201d di settori con le loro precise specificit\u00e0, di processi e procedure differenti, di professionalit\u00e0 ben distinte fra loro. Ma questo non \u00e8 l\u2019unico caso, si mescolano Didattica, Ricerca e Terzo settore in un grande \u201cminestrone\u201d a scapito dell\u2019efficacia e dell\u2019efficienza e delle tante professionalit\u00e0 acquisite sul campo. Viceversa, l\u2019accorpamento dell\u2019area legale con quella negoziale, a parte il possibile conflitto di interessi, sembra pi\u00f9 ispirato ad altre logiche di carrierismo.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>Si sancisce la chiusura delle Biblioteche dipartimentali, eliminandole dai dipartimenti insieme al personale bibliotecario. Vengono declassate al mero ruolo di &#8220;servizi per gli utenti&#8221;, ignorando la loro funzione principale e storica di sostegno alla ricerca e alla didattica in stretto legame con i settori scientifico disciplinari dei Dipartimenti. Vengono collocate in un&#8217;ampia struttura, interrompendo il legame e la funzionalit\u00e0 che le aveva originariamente incardinate nei Dipartimenti. Questa decisione cerca di porre rimedio vanamente a politiche e scelte fallimentari adottate negli ultimi 15 anni dall&#8217;Ateneo, caratterizzate da fondi insufficienti per la gestione e gli acquisti, cos\u00ec come da carenza di personale bibliotecario assegnato a tali strutture.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>Sebbene da tempo si parlasse della volont\u00e0 dell\u2019Amministrazione di addivenire ad un\u2019organizzazione di tipo orizzontale il risultato che \u00e8 scaturito da questo Modello \u00e8 un \u201cpateracchio\u201d. Di fatto rimangono le 4 Ripartizioni anche se ora vengono nominate diversamente con i 4 Dirigenti gi\u00e0 previsti prima; non si prevedono i necessari presidi (o aree come li si voglia chiamare) per garantire quell\u2019orizzontalit\u00e0 delle attivit\u00e0 che assicurerebbe un\u2019organizzazione del lavoro pi\u00f9 snella e meno burocratizzata e quindi pi\u00f9 efficace ed efficiente.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>\u00c8 stata completamente dimenticata la funzione della sicurezza ma in compenso c\u2019\u00e8 una duplicazione di altri coordinamenti e servizi. Nonostante le previsioni contrattuali si pensa di poter effettuare una riorganizzazione dell\u2019apparato a costo zero e questo \u00e8 gi\u00e0 molto significativo cos\u00ec come esigue sono le risorse che si vogliono mettere a disposizione per il potenziamento necessario degli organici che risultano ad oggi tra i pi\u00f9 carenti delle Universit\u00e0 italiane.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>Nel complesso le scriventi RSU e OO.SS. non possono che esprimere un giudizio totalmente negativo sul Modello di riorganizzazione approvato, in piena continuit\u00e0 con gli errori del passato, e si rammaricano per l\u2019occasione perduta anche da parte dell\u2019attuale Rettore.<\/p>\n\n\n\n<p>Lecce, 5 agosto 2023<\/p>\n\n\n\n<p>SNALS\/Confsal \u2013 Angela Mercuri (Delegata aziendale Universit\u00e0 Snals \/Confsal)<\/p>\n\n\n\n<p>ANIEF \u2013 Manfredi De Pascalis (Delegato aziendale Universit\u00e0 ANIEF)<\/p>\n\n\n\n<p>FLC\/CGIL \u2013 Giuseppe Taccarelli (Delegato aziendale Universit\u00e0 FLC\/CGIL)<\/p>\n\n\n\n<p>CISL FSUR \u2013 Giovanni Candela (Delegato aziendale Universit\u00e0 CISL FSUR)<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/05\/una-farsa-inutile-peggiorativa-ai-sindacati-non-piace-la-nuova-organizzazione-dellunisalento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/05\/una-farsa-inutile-peggiorativa-ai-sindacati-non-piace-la-nuova-organizzazione-dellunisalento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. I sotto elencati delegati sindacali ci mandano il seguente counicato stampa con una dura presa di posizione riguardo la nuova organizzazione dell&#8216;Universit\u00e0 del Salento. Nella nostra foto, il rettore Fabio Pollice, definito, dopo quattro anni dall&#8216;\u00a0entrata in carica, eleento di continuit\u00e0 con le passate gestioni fallimentari, nonostante le promesse con cui [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":219426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,31,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219425"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=219425"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219425\/revisions"}],"predecessor-version":[{"id":219427,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219425\/revisions\/219427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/219426"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=219425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=219425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=219425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}