{"id":219428,"date":"2023-08-06T00:03:00","date_gmt":"2023-08-05T22:03:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=219428"},"modified":"2023-08-05T19:26:25","modified_gmt":"2023-08-05T17:26:25","slug":"moda-mode-hamburger-e-sneakers","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/06\/moda-mode-hamburger-e-sneakers\/","title":{"rendered":"MODA \/ MODE \u2013\u00a0HAMBURGER E SNEAKERS"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1066\" class=\"wp-image-219429\" style=\"width: 2100px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/sba.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/sba.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/sba-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/sba-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/sba-768x512.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/sba-1536x1023.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p>di <strong>Elena Vada<\/strong> ______<\/p>\n\n\n\n<p>In giro per la citt\u00e0 in occasione dei saldi, la mia amica Lella ed io ci accorgiamo che gli articoli in svendita non sono i medesimi di quelli visti pochi giorni prima, in vetrina.&nbsp;<\/p>\n\n\n\n<p>&#8220;&#8230; Il modello che ha provato marted\u00ec?? Finito, finito. Esaurito subito!&#8221;<\/p>\n\n\n\n<p>Non ne siamo molto convinte, ma che replicare&#8230; sappiamo bene che alcuni negozi di Griffes importanti, sostituiscono abiti ed accessori, con collezioni create apposta per i saldi, o con giacenze di magazzino.<\/p>\n\n\n\n<p>Vabb\u00e8, non ne moriremo&#8230; anzi.<\/p>\n\n\n\n<p>&#8220;Elena, ma tu li assumi gli<em>&nbsp;<strong>antociani<\/strong>?&#8221;&nbsp;<\/em>mi chiede d&#8217;improvviso Lella, mentre mangiamo un gelato.<\/p>\n\n\n\n<p>&#8220;<em>I CHEEE?&nbsp;<\/em>i turchi di Antiochia? e che hanno di speciale?&#8230;<\/p>\n\n\n\n<p>&#8220;Ma no, i&nbsp;<strong>mirtilli,&nbsp;<\/strong>e<strong>&nbsp;tutti i frutti di bosco,&nbsp;<\/strong>quelli che hanno le antocianine, li mangi?&#8221;<\/p>\n\n\n\n<p>&#8221; Oddio, quale guru della dietetica stai seguendo in questo periodo? Ormai ci basterebbe evitare gelati come questo che stiamo gustando e saremmo gi\u00e0 a posto&#8230; &#8220;<\/p>\n\n\n\n<p>&#8220;Lo sai che la nostra Premier mangia molta carne, dicono, di tutti i tipi: bistecche, pollo e perfino gli&nbsp;<strong><em>hamburger<\/em><\/strong>&#8230;&#8221;<\/p>\n\n\n\n<p>&#8220;Perch\u00e9 dici &#8220;perfino&#8221; &#8230; gli &#8220;hamburger&#8221; che hanno di male&#8230;???&#8221;<\/p>\n\n\n\n<p>&#8220;&#8230; sono americani, sono stranieri e da quando ci sono Lei (la Meloni) e suo cognato Lollobrigida, al Governo, non si pu\u00f2 pi\u00f9 neanche masticare il chewingum, il cicles, la &#8220;gomma americana&#8221;, insomma&#8230;!&#8221;<\/p>\n\n\n\n<p>&#8220;Davvero?!?&#8230; Senti Lella, ma dove ascolti o leggi queste notizie, fanno degli inserti apposta nelle riviste che compri? &#8230;&#8221;<\/p>\n\n\n\n<p>&#8220;Ma sono cose risapute!&nbsp;<\/p>\n\n\n\n<p>Come il fatto che &#8220;sbevazza&#8221; vino ros\u00e8 o rosso frizzantino pugliese,&nbsp; dell&#8217;amico Vespa&#8230;&nbsp;<\/p>\n\n\n\n<p>Alla Casa Bianca, in America dal presidente Biden&#8230; (lo sai che ci \u00e8 andata e sono amiconi) non ha voluto il vino di Macron&#8230; il francese&#8230;&#8221;<\/p>\n\n\n\n<p>&#8220;Ma non mi dire?! Certo che non si finisce mai di imparare! Altro che tasse, salari e via discorrendo&#8230; Stanotte, al pensiero, non dormir\u00f2&#8230; Ma c&#8217;\u00e8&nbsp; altro&#8230;?&#8221;<\/p>\n\n\n\n<p>&#8220;Tu lo sai benissimo&#8230; siccome &#8220;Lei&#8221; \u00e8&nbsp; abituata a calzare sneakers e simili,&nbsp; prima di mettere le scarpe d\u00e9collet\u00e9 con gli abiti&nbsp; eleganti (come le hai consigliato tu), le fa portare a sua sorella Arianna, per due giorni&#8230; cos\u00ec&nbsp; non le vengono pi\u00f9 le vesciche, come l&#8217;ultima volta in tv, ricordi no???&#8230;&#8221;<\/p>\n\n\n\n<p>&#8220;Benissimo (?!). Certo che segui davvero&nbsp; molto le vicende politiche, del nostro paese. Brava! Questi si, che sono i veri problemi cui dedicarsi, altro che Reddito di Cittadinanza, eccetera&#8230;&#8221;<\/p>\n\n\n\n<p>&#8220;Ma non l&#8217;hanno mica tolto, quello! \u00c8 stata solo una finta&#8230;&#8221;<\/p>\n\n\n\n<p>&#8220;Basta, basta&#8230;\u00a0oggi ne ho abbastanza di politica.\u00a0 torniamo agli\u00a0<em>antociani<\/em>\u00a0cio\u00e8 ai mirtilli nella dieta quotidiana. Quelli almeno fanno bene alla salute&#8221;<\/p>\n\n\n\n<p>&#8220;&#8230; ma solo se italiani. Come dice il ministro dei&nbsp;<em>&#8220;Beni Culturali&#8221;&nbsp;<\/em>Lollobrigida&#8221;<\/p>\n\n\n\n<p>&#8220;<em>Beni Culturali?&nbsp;<\/em><strong>Sovranit\u00e0 Alimentare,&nbsp;<\/strong>vorrai dire!&#8221;<\/p>\n\n\n\n<p>&#8220;&#8230; e non \u00e8&nbsp; la stessa cosa?&#8221;<\/p>\n\n\n\n<p><strong>VIVA L&#8217;ITALIA!<\/strong><\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/06\/moda-mode-hamburger-e-sneakers\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/06\/moda-mode-hamburger-e-sneakers\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Elena Vada ______ In giro per la citt\u00e0 in occasione dei saldi, la mia amica Lella ed io ci accorgiamo che gli articoli in svendita non sono i medesimi di quelli visti pochi giorni prima, in vetrina.&nbsp; &#8220;&#8230; Il modello che ha provato marted\u00ec?? Finito, finito. Esaurito subito!&#8221; Non ne siamo molto convinte, ma [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":219429,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219428"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=219428"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219428\/revisions"}],"predecessor-version":[{"id":219430,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219428\/revisions\/219430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/219429"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=219428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=219428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=219428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}