{"id":219439,"date":"2023-08-06T11:37:39","date_gmt":"2023-08-06T09:37:39","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=219439"},"modified":"2023-08-06T11:39:26","modified_gmt":"2023-08-06T09:39:26","slug":"unaltra-truffa-ad-un-anziano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/06\/unaltra-truffa-ad-un-anziano\/","title":{"rendered":"UN\u2019ALTRA TRUFFA AD UN\u2019ANZIANA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"563\" class=\"wp-image-219440\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/anziana-al-telefono-2-1647463520555.jpg-.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/anziana-al-telefono-2-1647463520555.jpg-.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/anziana-al-telefono-2-1647463520555.jpg--300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/anziana-al-telefono-2-1647463520555.jpg--768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\n\n\n<p>di <strong>Fabio Coppola <\/strong>&nbsp;______&nbsp;<\/p>\n\n\n\n<p>Durante l\u2019estate i centri urbani si svuotano, restano a casa molti anziani spesso soli. Situazione ideale per truffare i pi\u00f9 vulnerabili.<\/p>\n\n\n\n<p>Nella mattinata di gioved\u00ec scorso \u00e8 successo ad una signora di 85 anni di Arnesano. La vittima \u00e8 stata contattata telefonicamente da un sedicente maresciallo dei carabinieri, per comunicare che un nipote della donna era stato coinvolto in un grave sinistro stradale, e che aveva urgente bisogno di denaro per affrontare spese legali. Inoltre sarebbe passato da casa un altro carabiniere per prelevare i soldi.<\/p>\n\n\n\n<p>Mentre la telefonata era ancora in corso, si presenta alla porta un uomo in borghese, giovanissimo, statura medio-alta, longilineo, capelli neri e lisci, che si \u00e8 qualificato come un carabiniere. La donna ha chiesto perch\u00e9 non indossasse la divisa, ma l\u2019uomo ha dato come motivazione l\u2019urgenza della situazione. Pertanto la signora disorientata dalla sorpresa e preoccupata per il nipote, ha consegnato il contante che aveva a disposizione. Prima di lasciare l\u2019abitazione, il delinquente ha comunicato al suo complice che era ancora in linea al telefono di aver preso in consegna il denaro. Solo qualche minuto dopo la donna ha avuto la lucidit\u00e0 di contattare i familiari, per rendersi conto di essere stata raggirata.<\/p>\n\n\n\n<p>La signora ha sporto denuncia presso il Comando Stazione Carabinieri di Monteroni, dove \u00e8 stato preso in carico il caso.<\/p>\n\n\n\n<p>Purtroppo eventi frequenti in questo periodo, che oltre al danno economico lasciano nella vittima paura, tristezza, rabbia, umiliazione, senso di insicurezza, e diffidenza nei confronti del prossimo.&nbsp; ______&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>L&nbsp;<strong>\u2019<\/strong>APPROFONDIMENTO nel nostro articolo del 10 maggio scorso<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"UFTZXMxusI\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/10\/possiamo-aiutarvi-i-carabinieri-al-fianco-degli-anziani\/\">POSSIAMO AIUTARVI! I CARABINIERI AL FIANCO DEGLI ANZIANI PER PREVENIRE LE TRUFFE<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;POSSIAMO AIUTARVI! I CARABINIERI AL FIANCO DEGLI ANZIANI PER PREVENIRE LE TRUFFE&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/05\/10\/possiamo-aiutarvi-i-carabinieri-al-fianco-degli-anziani\/embed\/#?secret=vYTvDJqa8T#?secret=UFTZXMxusI\" data-secret=\"UFTZXMxusI\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/06\/unaltra-truffa-ad-un-anziano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/06\/unaltra-truffa-ad-un-anziano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Fabio Coppola &nbsp;______&nbsp; Durante l\u2019estate i centri urbani si svuotano, restano a casa molti anziani spesso soli. Situazione ideale per truffare i pi\u00f9 vulnerabili. Nella mattinata di gioved\u00ec scorso \u00e8 successo ad una signora di 85 anni di Arnesano. La vittima \u00e8 stata contattata telefonicamente da un sedicente maresciallo dei carabinieri, per comunicare che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":219440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219439"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=219439"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219439\/revisions"}],"predecessor-version":[{"id":219444,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219439\/revisions\/219444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/219440"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=219439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=219439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=219439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}