{"id":219562,"date":"2023-08-09T14:51:00","date_gmt":"2023-08-09T12:51:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=219562"},"modified":"2023-08-09T18:32:17","modified_gmt":"2023-08-09T16:32:17","slug":"arrestato-giovane-violento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/09\/arrestato-giovane-violento\/","title":{"rendered":"ARRESTATO IMMIGRATO VIOLENTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"702\" height=\"336\" class=\"wp-image-219563\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/carcere-taranto-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/carcere-taranto-1.jpg 702w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/carcere-taranto-1-300x144.jpg 300w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/p>\n\n\n\n<p>(e.l.) ______\u00a0 Questa mattina una Volante della Polizia di Stato in servizio di controllo del territorio a Taranto ha notato in centro due uomini litigare ed un terzo impegnato nel tentativo di separarli.<br>Gli agenti, pertanto, si sono avvicinati con l\u2019intento di ristabilire la calma, ma uno dei due visibilmente ubriaco, ha opposto una forte resistenza.<br>Solo dopo alcuni minuti quest\u2019ultimo, poi identificato, un giovane di 28 anni di nazionalit\u00e0 afgana, \u00e8 stato immobilizzato con non poche difficolt\u00e0 e nonostante i suoi violenti tentativi, \u00e8 stato fatto salire a bordo dell\u2019auto di servizio.<br>Nei momenti successivi, gli agenti hanno provato ad accertare l\u2019accaduto ed hanno ascoltato le dichiarazioni dell\u2019altro uomo coinvolto nella violenta lite, titolare di un esercizio commerciale ubicato in quelle vicinanze.<br>Il commerciante, un pakistano di 56 anni, ha raccontato che il suo contendente nel corso della serata pi\u00f9 volte era entrato nel locale e visibilmente alterato dall\u2019assunzione di sostanze alcoliche aveva preteso in maniera violenta del denaro, richieste poi sfociate nell\u2019aggressione.<\/p>\n\n\n\n<p>Il giovane \u00e8 stato arrestato con l<strong>&#8216;<\/strong>\u00a0accusa di tentata rapina e di resistenza a Pubblico Ufficiale.<\/p>\n\n\n\n<p>Come disposto dal pm di turno presso la Procura della Repubblica, si trova ora presso la locale Casa Circondariale (nella foto).<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/09\/arrestato-giovane-violento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/09\/arrestato-giovane-violento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0 Questa mattina una Volante della Polizia di Stato in servizio di controllo del territorio a Taranto ha notato in centro due uomini litigare ed un terzo impegnato nel tentativo di separarli.Gli agenti, pertanto, si sono avvicinati con l\u2019intento di ristabilire la calma, ma uno dei due visibilmente ubriaco, ha opposto una forte resistenza.Solo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":219563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219562"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=219562"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219562\/revisions"}],"predecessor-version":[{"id":219565,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219562\/revisions\/219565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/219563"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=219562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=219562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=219562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}