{"id":219609,"date":"2023-08-11T14:16:26","date_gmt":"2023-08-11T12:16:26","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=219609"},"modified":"2023-08-11T14:18:54","modified_gmt":"2023-08-11T12:18:54","slug":"arrestato-presunto-spacciatore-7","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/11\/arrestato-presunto-spacciatore-7\/","title":{"rendered":"ARRESTATO PRESUNTO SPACCIATORE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"678\" height=\"381\" class=\"wp-image-219610\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/cc-droga-2-e1691743714581-678x381-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/cc-droga-2-e1691743714581-678x381-1.jpg 678w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/08\/cc-droga-2-e1691743714581-678x381-1-300x169.jpg 300w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/p>\n\n\n\n<p>(e.l.)\u00a0______ I Carabinieri del Nucleo Operativo del Comando Compagnia di Taranto hanno arrestato in flagranza di reato, con l<strong>&#8216;<\/strong>accusa di detenzione ai fini di spaccio di sostanze stupefacenti, un giovane di 21 anni, del quale non sono state rese note le generalit\u00e0.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>I militari lo hanno notato nelle vie del quartiere Salinella  in un via vai sospetto di giovani a piedi o in macchina e lo  hanno quindi tenuto sotto controllo. <\/p>\n\n\n\n<p>Sono cos\u00ec arrivati sotto ad una palazzina del quartiere dove, al culmine del servizio di osservazione e di pedinamento, hanno deciso di eseguire una perquisizione.<\/p>\n\n\n\n<p>Cos\u00ec in vari punti della casa sono stati trovati centosettanta  grammi di hashish e marijuana., oltre a un bilancino di precisione, a un coltello da cucina per il taglio e il confezionamento delle dosi, e 2.480 euro in banconote di vario taglio, ritenuti provento di spaccio. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Il pm di turno presso la Procura della Repubblica ha disposto i domiciliari.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/11\/arrestato-presunto-spacciatore-7\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/08\/11\/arrestato-presunto-spacciatore-7\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)\u00a0______ I Carabinieri del Nucleo Operativo del Comando Compagnia di Taranto hanno arrestato in flagranza di reato, con l&#8216;accusa di detenzione ai fini di spaccio di sostanze stupefacenti, un giovane di 21 anni, del quale non sono state rese note le generalit\u00e0. I militari lo hanno notato nelle vie del quartiere Salinella in un via [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":219610,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219609"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=219609"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219609\/revisions"}],"predecessor-version":[{"id":219611,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/219609\/revisions\/219611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/219610"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=219609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=219609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=219609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}