{"id":22142,"date":"2013-11-22T10:15:01","date_gmt":"2013-11-22T10:15:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22142"},"modified":"2013-11-22T10:15:01","modified_gmt":"2013-11-22T10:15:01","slug":"proposta-indecente-altro-che-film","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/22\/proposta-indecente-altro-che-film\/","title":{"rendered":"PROPOSTA INDECENTE , ALTRO CHE FILM!"},"content":{"rendered":"<p>Da chi cerca un minimamente dignitoso posto di lavoro,sia pure precario,mi \u00e8 stata passata una richiesta,presente su internet,che trovo indicativa di tante cose.<br \/>\nSi ricerca(va) in provincia di Catania un assistente per disabile con orario di lavoro\u00a0 7,30-13,pausa,16-20. Totale giornaliero di ore lavorate,nove e mezzo (in cifra 9,30).<br \/>\nRetribuzione ? 350 euro. Ovviamente per sei giorni settimanali,la domenica i buoni cristiani riposano e fanno riposare. Quanto viene all&#8217;ora ? 1,568 euro ogni 60 minuti di &#8220;assistenza&#8221; (potrei pure sbagliare,ma di poco). Beh,si sa che l&#8217;Italia ha come fondamento principale della propria costituzione il lavoro. Ma mica si deve determinarne il costo. Quello era un retaggio della contrattazione collettiva e delle tutele individuali che un bieco regime aveva iniziato ad introdurre nel nostro paese. E poi non dobbiamo aprirci tutti all&#8217;Europa,al globalismo liberale ed al capitalismo avanzato ? Oltrech\u00e9,naturalmente,al solidarismo mondiale ? Signori miei che (gentilmente) pubblicate e leggete queste mie considerazioni,si pu\u00f2 mai pretendere che un lavoratore presti la propria opera ad un prezzo superiore di quanto guadagni non dico un cinese (quelli si offendono,giustamente) ma uno del Myanmar o Birmania che dir si voglia ? Certo che no. Infatti la &#8220;offerta&#8221; di lavoro in questione segue legittimamente la linea della corsa al ribasso delle retribuzioni. Rigorosamente in nero,come libero costume. Lo sanno benissimo,purtroppo,giovani e meno giovani che quotidianamente vagano di persona o su internet alla disperata ricerca di una opportunit\u00e0. Se per &#8220;accompagnamento&#8221; di chi ne ha diritto lo stato versa 499,62 euro,si presume che un lavoratore che &#8220;assista&#8221; una persona disabile svolga una mansione pi\u00fa impegnativa. Tranne che faccia la bella statuina per 9,30 ore giornaliere e che,nella pausa pranzo,non debba fare andata e ritorno per ingurgitare qualcosa (ma con 1,568 euro cosa compra,un caffe ?). Ciascuno allarghi l&#8217;esempio a quel che sa per conoscenza diretta o per sentito dire. Vogliamo davvero che i nostri figli e nipoti finiscano nel &#8220;quarto mondo&#8221; ? Possiamo supinamente accettarlo ? E,con grandissima preoccupazione,davvero giovani e giovanissimi permetteranno che questo avvenga ?<\/p>\n<p>Vincenzo Mannello<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/22\/proposta-indecente-altro-che-film\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/22\/proposta-indecente-altro-che-film\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Da chi cerca un minimamente dignitoso posto di lavoro,sia pure precario,mi \u00e8 stata passata una richiesta,presente su internet,che trovo indicativa di tante cose. Si ricerca(va) in provincia di Catania un assistente per disabile con orario di lavoro\u00a0 7,30-13,pausa,16-20. Totale giornaliero di ore lavorate,nove e mezzo (in cifra 9,30). Retribuzione ? 350 euro. Ovviamente per sei [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22142"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22142"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22142\/revisions"}],"predecessor-version":[{"id":22143,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22142\/revisions\/22143"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}