{"id":22148,"date":"2013-11-23T09:14:20","date_gmt":"2013-11-23T09:14:20","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22148"},"modified":"2013-11-23T09:15:26","modified_gmt":"2013-11-23T09:15:26","slug":"voci-contro-vento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/23\/voci-contro-vento\/","title":{"rendered":"VOCI CONTRO VENTO"},"content":{"rendered":"<h3><span class=\"Apple-style-span\" style=\"font-size: 13px;font-weight: normal\"><img decoding=\"async\" src=\"http:\/\/www.lorien.it\/images\/ImmNews\/voci_contro_vento-cop.jpg\" alt=\"\" \/><\/span><\/h3>\n<p align=\"justify\">Per conoscere la storia della Destra degli anni &#8217;70 \u00e8 indispensabile conoscere anche la musica alternativa, le canzoni che scrivevano i giovani militanti, che venivano trasmesse dalle radio di destra e che venivano cantate prima o dopo i comizi o in manifestazioni varie, come i Campi Hobbit.<br \/>\nQuesto libro + cd consente di conoscere la stagione della musica alternativa (e la giovane destra degli anni &#8217;70) ripercorrendone la storia attraverso testimonianze (poche), interviste e articoli dell&#8217;epoca (molti) e soprattutto le canzoni (380 testi nel volume e 150 brani in formato mp3 nell&#8217;indispensabile cd allegato). Una storia illustrata (pi\u00f9 di 200 tra foto, copertine, manifesti e giornali) delle canzoni scritte da militanti del Fronte della Giovent\u00f9 e del Fuan tra il 1974 e i primi anni Ottanta (pi\u00f9 qualche predecessore negli anni Sessanta), per raccontare la cronaca e la vita quotidiana nella stagione degli &#8220;anni di piombo&#8221; e della &#8220;guerra civile&#8221; a bassa intensit\u00e0, divisi fra l&#8217;impegno politico e i sentimenti di amore e di rabbia, i morti da piangere e le inchieste giudiziarie, le speranze e i sogni, l&#8217;anticomunismo e l&#8217;Europa Nazione.<\/p>\n<p>\u20ac 20 euro brossurato cm 17&#215;24 cm pp.496 + CD 150 MP3<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/23\/voci-contro-vento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/11\/23\/voci-contro-vento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Per conoscere la storia della Destra degli anni &#8217;70 \u00e8 indispensabile conoscere anche la musica alternativa, le canzoni che scrivevano i giovani militanti, che venivano trasmesse dalle radio di destra e che venivano cantate prima o dopo i comizi o in manifestazioni varie, come i Campi Hobbit. Questo libro + cd consente di conoscere la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22148"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22148"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22148\/revisions"}],"predecessor-version":[{"id":22150,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22148\/revisions\/22150"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}