{"id":221892,"date":"2023-10-13T14:29:02","date_gmt":"2023-10-13T12:29:02","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=221892"},"modified":"2023-10-13T14:30:11","modified_gmt":"2023-10-13T12:30:11","slug":"provvedimenti-della-questura-di-lecce-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/13\/provvedimenti-della-questura-di-lecce-2\/","title":{"rendered":"PROVVEDIMENTI QUESTURA DI LECCE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1280\" height=\"853\" class=\"wp-image-221893\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/Degrado-Questura-di-Lecce.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/Degrado-Questura-di-Lecce.jpg 1280w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/Degrado-Questura-di-Lecce-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/Degrado-Questura-di-Lecce-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/Degrado-Questura-di-Lecce-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>(e.l.)&nbsp;&nbsp;______Tra il 15 settembre 2023, giorno di entrata in vigore del c.d. decreto Caivano che ha dato un giro di vite alla normativa vigente, ed il 13 ottobre 2023, nell\u2019ambito dell\u2019attivit\u00e0 di prevenzione e controllo del territorio, la Questura di Lecce, ha emesso:<\/p>\n\n\n\n<p><strong>CINQUE AVVISI ORALI<\/strong> &#8211; provvedimenti amministrativi con cui il Questore avvisa i responsabili di condotte <em>contra-legem<\/em> a tenere una condotta conforme alla legge;<\/p>\n\n\n\n<p><strong>SETTE D.A.SPO<\/strong>. &#8211; provvedimenti amministrativi con cui il Questore inibisce alle persone ritenute pericolose per l\u2019ordine e la sicurezza pubblica, l\u2019accesso alle manifestazioni sportive per un periodo variabile da un minimo di 1 anno ad un massimo di 10 anni, a seconda delle condotte tenute;<\/p>\n\n\n\n<p><strong>CINQUE FOGLI DI VIA OBBLIGATORIO E DIVIETO DI RITORNO<\/strong> &#8211; provvedimenti amministrativi con cui il Questore allontana, da un minimo di sei mesi ad un massimo di quattro anni, dal territorio di un determinato Comune coloro che, non&nbsp; avendo interessi legittimi nel territorio, sono stati sorpresi a delinquere.<\/p>\n\n\n\n<p>In particolare, in tale lasso di tempo il Questore di Lecce ha emesso il provvedimento di Avviso Orale a 5cinqaue persone, segnalate dall\u2019Ufficio Prevenzione Generale e Soccorso Pubblico e da altre Forze di Polizia che effettuano controllo del Territorio, ritenute sulla base di elementi di fatto, dedite alla commissione di reati che mettono in pericolo l\u2019incolumit\u00e0 e la sicurezza pubblica, invitandoli a tenere una condotta conforme alla legge.<\/p>\n\n\n\n<p>Dei sette DASPO, <strong>quattro<\/strong> (della durata di: 1 di otto \u2013 2 da tre&nbsp; e 1 da uno) hanno raggiunto i tifosi del Nard\u00f2, i quali, durante l\u2019incontro amichevole di calcio disputatosi a Nard\u00f2 il 19.8.2023, tra le compagini del Nardo\u2019 e Ugento, si sono resi responsabili di condotte violente nei confronti dei giocatori della squadra ospite;&nbsp; <strong>un<\/strong> provvedimento D.A.Spo., (della durata di 3 anni) ha raggiunto un tifoso della squadra del Maglie, resosi responsabile di oltraggio, violenza e resistenza a pubblico ufficiale in occasione della partita &nbsp;Toma Maglie-Mesagne, &nbsp;disputatasi il 19.09.2023; <strong>un<\/strong> provvedimento D.A.Spo., (della durata di 1 anno) ha raggiunto un tifoso della squadra del Lecce, resosi responsabile di utilizzo di materiale pericoloso in occasione della partita Lecce-Lazio, disputatasi il 20.08.2023; <strong>uno<\/strong> (della durata di 1 anno) ha raggiunto un tifoso, minore degli anni diciotto, della squadra del Lecce, resosi responsabile del lancio di materiale pericoloso nei confronti della tifoseria ospite, in occasione della partita Lecce-Salernitana, disputatasi il 3.09.2023.<\/p>\n\n\n\n<p>Per quanto riguarda altres\u00ec la misura di prevenzione del Foglio di Via Obbligatorio e Divieto di Ritorno sono stati emessi a cinque soggetti sorpresi a delinquere in Comuni in cui non avevano la residenza o altri interessi legittimi, diffidandoli a lasciare il territorio ove sono accaduti i reati e a non farvi rientro per un periodo determinato; in particolare \u00e8 stato emesso <strong>un<\/strong> provvedimento di F.V.O. ad un soggetto, segnalato dalla Sezione Volanti della Questura, denunciato per rissa aggravata commessa in data 24.09.2023 a Lecce presso la villa comunale; <strong>tre<\/strong> provvedimenti di F.V.O. a soggetti denunciati, in date diverse a Melendugno e Novoli, per furto ed <strong>un<\/strong> provvedimento di F.V.O. ad un soggetto arrestato in flagranza di reato, in data 16.09.2023 a Melissano, per&nbsp; resistenza, violenza o minaccia a pubblico ufficiale, lesioni e detenzione illegale di oggetti atti ad offendere.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/13\/provvedimenti-della-questura-di-lecce-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/13\/provvedimenti-della-questura-di-lecce-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)&nbsp;&nbsp;______Tra il 15 settembre 2023, giorno di entrata in vigore del c.d. decreto Caivano che ha dato un giro di vite alla normativa vigente, ed il 13 ottobre 2023, nell\u2019ambito dell\u2019attivit\u00e0 di prevenzione e controllo del territorio, la Questura di Lecce, ha emesso: CINQUE AVVISI ORALI &#8211; provvedimenti amministrativi con cui il Questore avvisa i [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":221893,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221892"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=221892"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221892\/revisions"}],"predecessor-version":[{"id":221895,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221892\/revisions\/221895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/221893"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=221892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=221892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=221892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}