{"id":221919,"date":"2023-10-14T15:22:00","date_gmt":"2023-10-14T13:22:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=221919"},"modified":"2023-10-14T15:51:04","modified_gmt":"2023-10-14T13:51:04","slug":"la-polizia-di-stato-intensifica-i-controlli-contro-chi-guida-ubriaco-o-drogato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/14\/la-polizia-di-stato-intensifica-i-controlli-contro-chi-guida-ubriaco-o-drogato\/","title":{"rendered":"LA POLIZIA DI STATO INTENSIFICA I CONTROLLI CONTRO CHI GUIDA UBRIACO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"563\" class=\"wp-image-221920\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/controlli-pol-stradale.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/controlli-pol-stradale.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/controlli-pol-stradale-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/controlli-pol-stradale-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>(e.l.)&nbsp;&nbsp;______ Questa notte a Mesagne, nell\u2019ambito della campagna nazionale, rivolta al contrasto del fenomeno della guida in stato di ebbrezza alcoolica o di alterazione dopo aver assunto sostanze stupefacenti o psicotrope, che rappresenta una delle aree di intervento pubblico sulla quale l\u2019Unione Europea ritiene debba essere concentrata l\u2019attenzione degli Stati membri per ridurre sensibilmente l\u2019incidentalit\u00e0 stradale negli anni a venire, la Sezione Polizia Stradale di Brindisi ed il Commissariato di Mesagne, ha intensificato i controlli con l\u2019impiego di un considerevole numero di pattuglie.<\/p>\n\n\n\n<p>L\u2019accertamento dell\u2019eventuale alterazione psicofisica dovuta all\u2019assunzione di alcool \u00e8 avvenuta con precursori ed etilometri in uso alla Polizia Stradale.<\/p>\n\n\n\n<p>L\u2019attivit\u00e0 di accertamento delle condizioni psico-fisiche dei conducenti dovuta all\u2019eventuale assunzione di sostanze stupefacenti \u00e8 avvenuta utilizzando test qualitativi monouso per la ricerca di tracce di droghe nella saliva dei conducenti. I controlli sono avvenuti a bordo di idoneo automezzo della Polizia di Stato per eseguire con la dovuta riservatezza gli accertamenti clinici analitici con apparecchi portatili, a lettura automatica e con stampa del risultato, su campioni di saliva prelevati, in modo non invasivo, direttamente sulla strada. Il prelievo di ogni campione biologico da sottoporre ad analisi nell\u2019apparecchiatura \u00e8 stato svolto a cura del personale medico-sanitario della Polizia di Stato. <\/p>\n\n\n\n<p>Il protocollo prevede che in caso di esito positivo dei test rapidi di screening, ulteriori aliquote di campioni di saliva prelevate, con le garanzie medico-legali richieste dalla vigente normativa, siano trasmessi presso il Centro Ricerche di Laboratorio e Tossicologia Forense della Polizia di Stato di Roma, dove saranno analizzati con metodiche di secondo livello di elevata precisione ed affidabilit\u00e0. In caso di esito positivo dell\u2019esame di conferma, la Sezione Polizia Stradale di Brindisi proceder\u00e0 alla contestazione dell\u2019illecito, alla trasmissione della patente di guida alla Prefettura competente e al sequestro del veicolo  finalizzato alla successiva confisca qualora il trasgressore risultasse anche proprietario del veicolo.<\/p>\n\n\n\n<p>Nel corso del servizio <strong>&nbsp;113<\/strong> conducenti sono stati sottoposti al test di screening per l\u2019assunzione di alcool con precursori che valutano la presenza di alcool nell\u2019aria espirata; i conducenti positivi al precursore sono stati sottoposti alla prova dell\u2019etilometro.<\/p>\n\n\n\n<p>Un conducente \u00e8 risultato positivo agli accertamenti alcolemici per i quali&nbsp; si \u00e8 proceduto al ritiro della patente di guida ai fini della sospensione, nessun conducente \u00e8 risultato positivo ai test di accertamento per alterazione alla guida dovuta all\u2019assunzione di sostanze stupefacenti.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/14\/la-polizia-di-stato-intensifica-i-controlli-contro-chi-guida-ubriaco-o-drogato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/14\/la-polizia-di-stato-intensifica-i-controlli-contro-chi-guida-ubriaco-o-drogato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)&nbsp;&nbsp;______ Questa notte a Mesagne, nell\u2019ambito della campagna nazionale, rivolta al contrasto del fenomeno della guida in stato di ebbrezza alcoolica o di alterazione dopo aver assunto sostanze stupefacenti o psicotrope, che rappresenta una delle aree di intervento pubblico sulla quale l\u2019Unione Europea ritiene debba essere concentrata l\u2019attenzione degli Stati membri per ridurre sensibilmente l\u2019incidentalit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":221920,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221919"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=221919"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221919\/revisions"}],"predecessor-version":[{"id":221922,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221919\/revisions\/221922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/221920"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=221919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=221919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=221919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}