{"id":221923,"date":"2023-10-14T15:20:00","date_gmt":"2023-10-14T13:20:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=221923"},"modified":"2023-10-14T16:01:09","modified_gmt":"2023-10-14T14:01:09","slug":"controlli-della-guardia-di-finanza-di-lecce-sul-lavoro-in-nero","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/14\/controlli-della-guardia-di-finanza-di-lecce-sul-lavoro-in-nero\/","title":{"rendered":"CONTROLLI DELLA GUARDIA DI FINANZA DI LECCE SUL LAVORO IN NERO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" class=\"wp-image-221924\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/14102023_093451_foto-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/14102023_093451_foto-1.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/14102023_093451_foto-1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/14102023_093451_foto-1-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/10\/14102023_093451_foto-1-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>(e.l.)&nbsp;&nbsp;______ Continuano i controlli delle Fiamme Gialle del Comando Provinciale di Lecce finalizzati a prevenire e contrastare il fenomeno del lavoro irregolare.<\/p>\n\n\n\n<p>Nei giorni scorsi, bei comuni di Arnesano e Cannole. i militari hanno effettuato alcuni interventi ispettivi nei confronti di pubblici esercizi nel settore della ristorazione e di attivit\u00e0 dedite al trasporto di merci su strada, che hanno consentito di individuare complessivamente dodici persone intente a prestare la propria attivit\u00e0 lavorativa totalmente in nero.<\/p>\n\n\n\n<p>Tre datori di lavoro sono stati segnalati all\u2019Ispettorato Territoriale del Lavoro per le conseguenti valutazioni sulla sospensione dell\u2019attivit\u00e0 imprenditoriale.<\/p>\n\n\n\n<p>Nei confronti degli stessi sono in corso di esecuzione gli approfondimenti di natura fiscale al fine di accertare la posizione per il reddito dichiarato.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/14\/controlli-della-guardia-di-finanza-di-lecce-sul-lavoro-in-nero\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/10\/14\/controlli-della-guardia-di-finanza-di-lecce-sul-lavoro-in-nero\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)&nbsp;&nbsp;______ Continuano i controlli delle Fiamme Gialle del Comando Provinciale di Lecce finalizzati a prevenire e contrastare il fenomeno del lavoro irregolare. Nei giorni scorsi, bei comuni di Arnesano e Cannole. i militari hanno effettuato alcuni interventi ispettivi nei confronti di pubblici esercizi nel settore della ristorazione e di attivit\u00e0 dedite al trasporto di merci [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":221924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221923"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=221923"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221923\/revisions"}],"predecessor-version":[{"id":221926,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/221923\/revisions\/221926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/221924"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=221923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=221923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=221923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}