{"id":22303,"date":"2013-12-04T11:43:17","date_gmt":"2013-12-04T11:43:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22303"},"modified":"2013-12-04T11:46:41","modified_gmt":"2013-12-04T11:46:41","slug":"gli-agenti-del-commissariato-di-otranto-rinvengono-un-panetto-di-marijuana-abbandonato-da-ignoti-scafisti-durante-una-fuga","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/04\/gli-agenti-del-commissariato-di-otranto-rinvengono-un-panetto-di-marijuana-abbandonato-da-ignoti-scafisti-durante-una-fuga\/","title":{"rendered":"GLI AGENTI DEL COMMISSARIATO DI OTRANTO RINVENGONO UN PANETTO DI MARIJUANA ABBANDONATO DA IGNOTI SCAFISTI DURANTE UNA FUGA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/04\/gli-agenti-del-commissariato-di-otranto-rinvengono-un-panetto-di-marijuana-abbandonato-da-ignoti-scafisti-durante-una-fuga\/3-vacanze-frassanito-puglia-2\/\" rel=\"attachment wp-att-22304\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/3-vacanze-frassanito-puglia-2-150x150.jpg\" alt=\"\" title=\"Mare Spiaggia vacanze frassanito\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-22304\" \/><\/a>Nelle prime ore di questa mattina, personale del Commissariato di PS di Otranto in servizio anti immigrazione, in localit\u00e0 Frassanito, ha trovato un gommone di grosse dimensioni spiaggiato e con l\u2019elica rotta. Poco distante dal gommone, abbandonato sulla riva, un panetto di marijuana del peso di 1 kg.<\/p>\n<p>Gli agenti ipotizzano che a causa della rottura dell\u2019elica, i trafficanti siano stati costretti ad abbandonare il gommone e che durante la rapida fuga abbiano dimenticato il panetto di droga.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/04\/gli-agenti-del-commissariato-di-otranto-rinvengono-un-panetto-di-marijuana-abbandonato-da-ignoti-scafisti-durante-una-fuga\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/04\/gli-agenti-del-commissariato-di-otranto-rinvengono-un-panetto-di-marijuana-abbandonato-da-ignoti-scafisti-durante-una-fuga\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nelle prime ore di questa mattina, personale del Commissariato di PS di Otranto in servizio anti immigrazione, in localit\u00e0 Frassanito, ha trovato un gommone di grosse dimensioni spiaggiato e con l\u2019elica rotta. Poco distante dal gommone, abbandonato sulla riva, un panetto di marijuana del peso di 1 kg. Gli agenti ipotizzano che a causa della [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22304,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22303"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22303"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22303\/revisions"}],"predecessor-version":[{"id":22309,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22303\/revisions\/22309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/22304"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}