{"id":223257,"date":"2023-11-14T03:03:50","date_gmt":"2023-11-14T02:03:50","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=223257"},"modified":"2023-11-14T03:16:11","modified_gmt":"2023-11-14T02:16:11","slug":"il-convegno-di-galatone-il-punto-di-riparteza-per-ripensare-la-xylella","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/11\/14\/il-convegno-di-galatone-il-punto-di-riparteza-per-ripensare-la-xylella\/","title":{"rendered":"IL CONVEGNO DI GALATONE, IL PUNTO DI RIPARTENZA PER RIPENSARE LA XYLELLA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"526\" height=\"526\" class=\"wp-image-223258\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/11\/401747665_10230573824031479_225861326836175395_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/11\/401747665_10230573824031479_225861326836175395_n.jpg 526w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/11\/401747665_10230573824031479_225861326836175395_n-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/11\/401747665_10230573824031479_225861326836175395_n-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/11\/401747665_10230573824031479_225861326836175395_n-60x60.jpg 60w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>(g.p.)\u00a0______ Siamo in teatro, e un<strong>&#8216;<\/strong>attrice e regista teatrale quale <strong>Maria Antionietta Vacca<\/strong>, chiamata dagli organizzatori, in  qualit\u00e0 di presidente della societ\u00e0 editrice di leccecroaca.it, a condurre la serata, \u00e8 perfettamente a suo agio. Trasforma un convegno tendenzialmente monotono e prolisso come possono essere monotoni se non noiosi tutti i convegni, specie quelli scientifici, in un talk show avvincente, un talk show di quelli buoni insomma, quelli che non ci sono pi\u00f9, alla Maurizio Costanzo buonanima, tanto per capirci.<\/p>\n\n\n\n<p>Si comincia in ritardo, per aspettare l<strong>&#8216;<\/strong>arrivo dell<strong>&#8216;<\/strong>assessore regionale (della quale diremo alla fine), ma quando si comincia, senza che l<strong>&#8216;<\/strong>&nbsp;assessore sia arrivata, il tempo vola, inseguito dalla partecipata attenzione dei presenti che riempiono la grande sala. Pi\u00f9 di due ore, e alla fine c<strong>&#8216;<\/strong>era ancora la coda degli interventi del pubblico, di chi voleva confrontarsi con i relatori.<\/p>\n\n\n\n<p>Siamo a Galatone, per questa lodevole iniziativa del presidente del consiglio comunale<strong> Maurizio Pinca<\/strong>, il quale, compunto ed elegante, salta dappertutto, sempre affabile da un posto all<strong>&#8216;<\/strong>&nbsp;altro, da questo a quello. Sul palco sale poi per i doverosi saluti istituzionali il sindaco <strong>Flavio Filoni<\/strong>, in versione casual, informale, che si percepisce svolga il suo compito in maniera non formale, bens\u00ec autentica.<\/p>\n\n\n\n<p>A proposito, volevo informare il signor sindaco, nel caso egli non lo sappia e voglia lamentarsene  con i produttori, che l<strong>&#8216;<\/strong>&nbsp;assistente vocale della Mercedes, che si chiama anch<strong>&#8216;<\/strong>ella Mercedes, come l<strong>&#8216;<\/strong>&nbsp;automobile   su cui, gentilmente ospitato, ho fatto il tragitto andata  e ritorno da Lecce, si ostina a pronunciare il nome del paese Galat\u00f2ne, e non c<strong>&#8216;<\/strong>\u00e8 stato modo di farle cambiare idea&#8230;<\/p>\n\n\n\n<p>La prima notizia vera e propria emersa da questa serata, la d\u00e0 <strong>Crocifisso Aloisi<\/strong>, a nome delle quarantuno, al momento, ma il numero \u00e8 destinato a crescere ancora, associazioni che l<strong>&#8216;<\/strong>hanno firmato<strong>:<\/strong> il documento di sintesi, di proposta, in spirito costruttivo, di partecipazione, di condivisione e di concordia, sull<strong>&#8216;<\/strong>intera questione Xylella che sar\u00e0 diffuso quanto prima  a poliitici, scienziati, studiosi, enti istituzioali edi ricerca, regionali, nazionali e interazionali. Ben fatto.<\/p>\n\n\n\n<p>La seconda, la d\u00e0 il professor <strong>Marco Scortichini<\/strong>, attestando che le piante che si sono rigenerate contengono un alto numero di batteri, ma questo non ha impedito loro di rivegetare e di tornare a produrre. Con la Xylella dunque si pu\u00f2 convivere, si deve convivere. E poi, confermando e spiegando scientificamente che tanti ullivi si sono ripresi, sia quelli sottoposti a specifici protocolli di cura, sia quelli in che ci sono riusciti in maniera del tutto spontanea.<\/p>\n\n\n\n<p>Mi scuso con i tanti qualificati e prestigiosi intervenuti suii quali ometto di riferire, ma qui io devo fare un agile pezzo giornalistico, non un prolisso trattato accademico, il tempo di citare solo per la profondit\u00e0 e il valore dei suoi studi gli interventi densi di dati e di significati della professoressa <strong>Margherita Ciervo<\/strong>, e mi avvio rapidamente alle conclusioni. Non per il passato, ma per il futuro.<\/p>\n\n\n\n<p>A mio modo di intendere, le conclusioni della serata in estrema sintesi sono&nbsp;le seguenti richieste venute dai relatori e dagli organizzatori del convegno<strong>:<\/strong> una mappatura completa dei campi dove gli ulivi si sono ripresi<strong>;<\/strong> concessione di contributi economici della Regione ai loro proprietari<strong>;<\/strong> una moratoria immediata ad abbattimenti di ulivi e ad irrorazioni di veleni chimici nei campi.<\/p>\n\n\n\n<p>E l<strong>&#8216;<\/strong>assessore? Ah gi\u00e0, l<strong>&#8216;<\/strong>assessore&#8230; <strong>Anna Grazia Maraschio<\/strong>, assessore all<strong>&#8216;<\/strong>Ambiente della Regione Puglia e che quindi rappresentava comunque il presidente Michele Emiliano e l<strong>&#8216;<\/strong>intero esecutivo regionale, \u00e8 arrivata con un<strong>&#8216;<\/strong>ora di ritardo, \u00e8 stata cinque minuti, ha parlato per tre minuti, senza dire nulla di rilevante, e se ne \u00e8 andata via un<strong>&#8216;<\/strong>&nbsp;ora prima.  <\/p>\n\n\n\n<p>Una mancanza di sensibilit\u00e0 e di acume politico, che sconfinano nella supponenza e nella maleducazione.<\/p>\n\n\n\n<p> <\/p>\n\n\n\n<p>&nbsp;   <\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/11\/14\/il-convegno-di-galatone-il-punto-di-riparteza-per-ripensare-la-xylella\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/11\/14\/il-convegno-di-galatone-il-punto-di-riparteza-per-ripensare-la-xylella\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.)\u00a0______ Siamo in teatro, e un&#8216;attrice e regista teatrale quale Maria Antionietta Vacca, chiamata dagli organizzatori, in qualit\u00e0 di presidente della societ\u00e0 editrice di leccecroaca.it, a condurre la serata, \u00e8 perfettamente a suo agio. Trasforma un convegno tendenzialmente monotono e prolisso come possono essere monotoni se non noiosi tutti i convegni, specie quelli scientifici, in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":223258,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,75,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/223257"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=223257"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/223257\/revisions"}],"predecessor-version":[{"id":223262,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/223257\/revisions\/223262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/223258"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=223257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=223257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=223257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}