{"id":22384,"date":"2013-12-07T23:28:41","date_gmt":"2013-12-07T23:28:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22384"},"modified":"2013-12-07T22:30:11","modified_gmt":"2013-12-07T22:30:11","slug":"rubrica-di-contro-informazione-a-cura-di-bepi-anguilla","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/07\/rubrica-di-contro-informazione-a-cura-di-bepi-anguilla\/","title":{"rendered":"RUBRICA DI CONTRO \u2013 INFORMAZIONE a cura di Bepi Anguilla"},"content":{"rendered":"<p>\u201cItalia sott\u2019occhio, mondo col cannocchiale\u201d<\/p>\n<p>L\u2019Islanda aiuta i cittadini al posto delle banche &#8211;\u00a0<a href=\"http:\/\/www.effedieffe.com\/index.php?option=com_content&amp;view=article&amp;id=83260:gaulliste-libre&amp;catid=38&amp;Itemid=100015\"><strong>Gaulliste Libre<\/strong><\/a>04 Dicembre 2013 &#8211;\u00a0Quando sono gli Stati che dettano legge alla finanza.<br \/>\nDecisamente\u00a0<a href=\"http:\/\/www.gaullistelibre.com\/2012\/09\/islande-lexemple-venu-du-froid.html\">gli Islandesi non si comportano come gli altri<\/a>. Non solo\u00a0<a href=\"http:\/\/www.gaullistelibre.com\/2013\/02\/lislande-continue-defier-la-finance.html\">hanno deciso democraticamente di non far pagare al popolo per rimediare agli errori delle banche<\/a>, ma oltre a ci\u00f2, mantengono le loro promesse elettorali. L\u2019ultimo esempio \u00e8\u00a0<a href=\"http:\/\/www.lemonde.fr\/economie\/article\/2013\/11\/30\/l-islande-va-annuler-jusqu-a-24-000-euros-de-dettes-par-menage_3523345_3234.html\">una riduzione sul debito immobiliare delle famiglie<\/a>!<br \/>\nUn provvedimento che costa il 9% del PIL.<br \/>\n\u00c8 un provvedimento che sembra assolutamente stravagante se confrontato con le politiche portate avanti nella zona euro.\u00a0<a href=\"http:\/\/www.lemonde.fr\/economie\/article\/2013\/11\/30\/l-islande-va-annuler-jusqu-a-24-000-euros-de-dettes-par-menage_3523345_3234.html\">Il governo ha deciso di alleggerire i bilanci famigliari di una parte dei loro debiti immobiliari<\/a>. In effetti, in Islanda la maggior parte dei prestiti sono indicizzati sull\u2019inflazione ed a causa del forte ribasso della corona nel 2009,\u00a0<a href=\"http:\/\/fr.global-rates.com\/statistiques-economiques\/inflation\/indice-des-prix-a-la-consommation\/ipc\/islande.aspx\">l\u2019aumento dell\u2019inflazione<\/a>\u00a0ha fatto aumentare il peso del debito delle famiglie \u2013 attualmente pari al 108% del PIL \u2013 che, su scala europea, \u00e8 un livello alto. Questo alleggerimento del debito dipender\u00e0 dal volume totale della massa presa in prestito ed avr\u00e0 un tetto massimo di 4 milioni di corone, cio\u00e8 di circa 24.400 euro [a famiglia].<\/p>\n<p><a href=\"http:\/\/www.lemonde.fr\/economie\/article\/2013\/11\/30\/l-islande-va-annuler-jusqu-a-24-000-euros-de-dettes-par-menage_3523345_3234.html\"><br \/>\nIl costo totale del provvedimento non dovr\u00e0 superare i 900 milioni di euro nell\u2019arco di 4 anni<\/a>. Pu\u00f2 sembrare poco, ma date le piccole dimensioni dell\u2019Islanda, \u00e8 enorme dato che il suo PIL non supera i 10 miliardi di euro. Dunque si tratta di un provvedimento che\u00a0vale\u00a0il 9% del PIL dell\u2019isola, spalmato su 4 anni. \u00c8 come se la Francia decidesse di destinare 180 miliardi di euro per ridurre i debiti delle famiglie!\u00a0<a href=\"http:\/\/www.gaullistelibre.com\/2012\/08\/paul-krugman-propose-un-nouveau-plan-de.html\">Si tratta di un provvedimento invocato negli USA da Paul Krugman<\/a>, ma senza successo. Occorre sottolineare che per quanto concerne la soluzione su finanziare il provvedimento, il governo avrebbe suggerito di tassare i depositi degli stranieri!<br \/>\n<strong><br \/>\n<\/strong>La dimostrazione che si pu\u00f2 fare politica in modo diverso<strong><br \/>\n<\/strong><br \/>\nUna bella differenza con la zona euro,\u00a0<a href=\"http:\/\/www.gaullistelibre.com\/2012\/03\/1000-milliards-pour-les-banques.html\">nella quale la BCE ha prestato alle banche 1.000 miliardi di euro al tasso dell\u20191%<\/a>. Non \u00e8 superfluo sottolineare che la massa di denaro in gioco \u2013 in rapporto al PIL\u00a0 \u2013 \u00e8 analoga. E ci\u00f2 mostra in modo chiaro\u00a0<a href=\"http:\/\/www.gaullistelibre.com\/2012\/03\/1000-milliards-pour-les-banques.html\">quali siano le priorit\u00e0 nelle due\u00a0aree: Islanda e zona euro<\/a>.<\/p>\n<p>La soluzione islandese \u00e8 interessante in quanto aiuta direttamente le famiglie e, nel farlo, contribuisce a dare sostegno all\u2019economia della nazione riducendo il loro indebitamento ed avvantaggiando anche le banche poich\u00e9 i loro clienti saranno maggiormente solvibili. L\u2019aiuto diretto ai cittadini \u2013 oltre al fatto che non c\u2019\u00e8 dubbio quando sia pi\u00f9 doveroso \u2013 sembra economicamente anche pi\u00f9 efficiente.<strong>\u00a0<\/strong>Visto i volumi in ballo, potrebbero essere finanziati grazie alla creazione di denaro da parte della Banca Centrale islandese, qualora governo e cittadini lo decidessero.<\/p>\n<p>In breve: l\u2019Islanda dimostra come sia perfettamente possibile portare avanti delle politiche diverse da quelle applicate nella zona euro, dimostrando inoltre che la svalutazione \u00e8 uno strumento potente per rilanciare la propria economia\u00a0<a href=\"http:\/\/gaulliste-villepiniste.hautetfort.com\/archive\/2010\/12\/28\/crise-potion-irlandaise-contre-potion-islandaise.html\">come gi\u00e0 notato da Paul Krugman nel 2010<\/a>nel paragonare il destino dell\u2019Islanda a quello dell\u2019Irlanda.<\/p>\n<p><a href=\"http:\/\/www.gaullistelibre.com\/2013\/02\/lislande-continue-defier-la-finance.html\">Gli Stati possono decisamente dettare le proprie condizioni alla finanza<\/a>, a patto solo di volerlo veramente. Grazie dunque all\u2019Islanda, a questa Stella del Nord che d\u00e0\u00a0<a href=\"http:\/\/www.gaullistelibre.com\/2012\/09\/islande-lexemple-venu-du-froid.html\">una luce di speranza ai popoli europei sottoposti a politiche assurde che avvantaggiano solo le<\/a>\u00a0\u00e9lite.<\/p>\n<p>Traduzione per EFFEDIEFFE.com a cura di Massimo Frulla<strong><\/strong><\/p>\n<p>Fonte &gt;\u00a0\u00a0<a href=\"http:\/\/www.gaullistelibre.com\/2013\/12\/lislande-aide-ses-citoyens-pas-les.html\">Gaulliste Libre<\/a><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/07\/rubrica-di-contro-informazione-a-cura-di-bepi-anguilla\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/07\/rubrica-di-contro-informazione-a-cura-di-bepi-anguilla\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u201cItalia sott\u2019occhio, mondo col cannocchiale\u201d L\u2019Islanda aiuta i cittadini al posto delle banche &#8211;\u00a0Gaulliste Libre04 Dicembre 2013 &#8211;\u00a0Quando sono gli Stati che dettano legge alla finanza. Decisamente\u00a0gli Islandesi non si comportano come gli altri. Non solo\u00a0hanno deciso democraticamente di non far pagare al popolo per rimediare agli errori delle banche, ma oltre a ci\u00f2, mantengono [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22384"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22384"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22384\/revisions"}],"predecessor-version":[{"id":22453,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22384\/revisions\/22453"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}