{"id":224579,"date":"2023-12-18T15:24:56","date_gmt":"2023-12-18T14:24:56","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=224579"},"modified":"2023-12-18T15:25:00","modified_gmt":"2023-12-18T14:25:00","slug":"restare-umani-sul-palco-la-convention-aziendale-maldarizzi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/18\/restare-umani-sul-palco-la-convention-aziendale-maldarizzi\/","title":{"rendered":"RESTARE UMANI: SUL PALCO LA CONVENTION AZIENDALE MALDARIZZI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"828\" height=\"621\" class=\"wp-image-224580\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/170289084196a599_l-logo-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/170289084196a599_l-logo-1.jpg 828w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/170289084196a599_l-logo-1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/170289084196a599_l-logo-1-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/170289084196a599_l-logo-1-400x300.jpg 400w\" sizes=\"(max-width: 828px) 100vw, 828px\" \/><strong>Domenica 17 dicembre, nella sede di AncheCinema a Bari, si \u00e8 svolto l\u2019evento annuale della Maldarizzi Automotive. Protagoniste le persone tra talent, incentivi, progetti e riconoscimenti<\/strong><\/p>\n\n\n\n<p>BARI, 18 dicembre 2023 &#8211; Restare umani: cos\u00ec si potrebbe riassumere in due parole la convention 2023 della Maldarizzi Automotive. \u201cJust one night\u201d \u00e8 stato il nome dell\u2019evento annuale che si \u00e8 svolto ieri, domenica 17 dicembre, nella sede di AncheCinema a Bari.<\/p>\n\n\n\n<p>\u201cSiamo pi\u00f9 di 300 \u2013 ha dichiarato sul palco il Cavaliere del Lavoro Francesco Maldarizzi, Presidente della Maldarizzi Automotive S.p.a. \u2013 e&nbsp;<a href=\"javascript:mails_addtocal(1,&quot;oggi&quot;);\">oggi<\/a>&nbsp;condividiamo quello che si \u00e8 fatto nel 2023 e i progetti del 2024, con l\u2019acquisizione di ulteriori brand e l\u2019inizio dei lavori nella nostra nuova sede. La convention \u00e8 dedicata in particolar modo al welfare aziendale ma abbiamo avuto il piacere della testimonianza dei presidenti delle case automobilistiche che rappresentiamo e che ci confermano fiducia per i prossimi anni. Siamo leader del mercato sul territorio, l\u2019unica concessionaria che presenzia direttamente su tutte le province pugliesi e su Matera. Tra gli obiettivi raggiunti nel 2023 c\u2019\u00e8 il consolidamento dell\u2019azienda sul territorio leccese e nuovi brand\u201d. Nel corso dell\u2019evento \u00e8 stato fatto un focus anche sul ruolo dell\u2019Intelligenza Artificiale nel mondo del lavoro. \u201cIl mondo dell\u2019IA \u00e8 partito velocemente \u2013 ha spiegato il Dott. Maldarizzi \u2013 e in meno di cinque anni cambier\u00e0 oltre il 75% delle attitudini di tutti, tanto da essere considerato una protesi del mondo del lavoro. Chi si dedicher\u00e0 alla lettura e all\u2019informazione avr\u00e0 una possibilit\u00e0 di crescita meritocratica grazie all\u2019ascensore sociale. L&#8217;ascensore sociale vede la possibilit\u00e0 di migliorare la posizione sociale o economica attraverso l&#8217;educazione, l&#8217;accesso a nuove opportunit\u00e0 o altri mezzi di accrescimento personale. Attraverso sforzi personali, educazione e opportunit\u00e0, chiunque potr\u00e0 migliorare il proprio stato sociale, salendo da una posizione socioeconomica pi\u00f9 bassa a una pi\u00f9 alta. In questo contesto, l&#8217;ascensore sociale dell&#8217;intelligenza artificiale indica il ruolo che l&#8217;IA pu\u00f2 svolgere nel favorire l&#8217;accesso a opportunit\u00e0 sociali o professionali\u201d.<\/p>\n\n\n\n<p>Negli anni dell\u2019IA e del cambiamento continuo, l\u2019azienda mantiene solida la risorsa umana, dandole valore per una crescita che sia nell\u2019ottica del ben-essere di tutti. In scena, le persone Maldarizzi: tra discorsi, numeri e momenti di musica intrattenuti da chi compone l\u2019azienda, tra talk ed esibizioni alla talent show, la serata ha visto tutte e tutti protagonisti. Il 2023 della Maldarizzi Automotive ha visto 51 nuove risorse inserite in azienda, 55 studenti ospitati per stage e percorsi di alternanza scuola-lavoro. Le lavoratrici e i lavoratori dell\u2019azienda hanno avuto la possibilit\u00e0 di dedicarsi alla formazione linguistica, ai corsi sulla sicurezza per il prodotto elettrico e a s\u00e9 stessi con il progetto Well-be grazie a due psicologhe sempre a disposizione. Durante la convention sono stati svelati anche alcuni progetti per il 2024: formazione sulla fiscalit\u00e0 e ancora formazione linguistica. Da gennaio ci sar\u00e0 una nuova piattaforma tecnologica, che consentir\u00e0 di raccogliere e misurare, in maniera anonima e costante il Sentiment dei lavoratori in relazione ad alcuni aspetti, come lo stress, la motivazione, la fiducia e il coinvolgimento verso l\u2019organizzazione, tra le migliori soluzioni a livello mondiale per analizzare scientificamente il clima aziendale in modo innovativo ed efficace.<\/p>\n\n\n\n<p>Il welfare aziendale resta un punto fermo della Maldarizzi Automotive, che ha rinnovato ed implementato anche una serie di convenzioni per rendere pi\u00f9 attrattivo lo shopping di ogni dipendente.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1707\" class=\"wp-image-224581\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/convention2-1-scaled.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/convention2-1-scaled.jpg 2560w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/convention2-1-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/convention2-1-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/convention2-1-768x512.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/convention2-1-1536x1024.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/convention2-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/18\/restare-umani-sul-palco-la-convention-aziendale-maldarizzi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/18\/restare-umani-sul-palco-la-convention-aziendale-maldarizzi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Domenica 17 dicembre, nella sede di AncheCinema a Bari, si \u00e8 svolto l\u2019evento annuale della Maldarizzi Automotive. Protagoniste le persone tra talent, incentivi, progetti e riconoscimenti BARI, 18 dicembre 2023 &#8211; Restare umani: cos\u00ec si potrebbe riassumere in due parole la convention 2023 della Maldarizzi Automotive. \u201cJust one night\u201d \u00e8 stato il nome dell\u2019evento annuale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":224580,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224579"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=224579"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224579\/revisions"}],"predecessor-version":[{"id":224582,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224579\/revisions\/224582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/224580"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=224579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=224579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=224579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}