{"id":224613,"date":"2023-12-19T16:07:39","date_gmt":"2023-12-19T15:07:39","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=224613"},"modified":"2023-12-19T16:07:42","modified_gmt":"2023-12-19T15:07:42","slug":"stop-alle-sigarette-elettroniche-una-minaccia-per-la-salute-e-lambiente","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/19\/stop-alle-sigarette-elettroniche-una-minaccia-per-la-salute-e-lambiente\/","title":{"rendered":"STOP ALLE SIGARETTE ELETTRONICHE, \u201duna minaccia per la salute e l\u2019ambiente\u201d"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"275\" height=\"183\" class=\"wp-image-224614\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/download-7.jpg\" alt=\"\">Riceviamo e volentieri pubblichiamo. Da Roma, Francesco Serangeli, per conto dell\u2019associazione Codici, Centro per i Diritti del Cittadino, ci manda il seguente comunicato  _______\u00a0<\/p>\n\n\n\n<p><strong>Codici: stop alle sigarette elettroniche usa e getta,&nbsp;<\/strong><strong>sono una minaccia per la salute e l\u2019ambiente<\/strong><\/p>\n\n\n\n<p>Se ne parla tanto, alcuni Paesi stanno studiando delle azioni ed anche l\u2019Italia dovrebbe muoversi. Il riferimento \u00e8 alle sigarette elettroniche usa e getta. Per l\u2019associazione Codici rappresentano una minaccia sia per la salute dei consumatori che per l\u2019ambiente.<\/p>\n\n\n\n<p>\u201cA livello internazionale \u2013 dichiara Ivano Giacomelli, Segretario Nazionale di Codici \u2013 \u00e8 in corso una riflessione sulle sigarette elettroniche usa e getta. Si sta ragionando su uno stop alla vendita, come in Francia, ed all\u2019importazione, come in Australia. Riteniamo che anche l\u2019Italia debba affrontare l\u2019argomento, perch\u00e9 presenta aspetti tanto importanti quanto delicati. Come associazione siamo impegnati nella lotta al fumo perch\u00e9 riteniamo fondamentale tutelare la salute dei consumatori. Rientra in quest\u2019ottica l\u2019azione contro le pubblicit\u00e0 scorrette di societ\u00e0 che cercano di far passare il concetto che le sigarette elettroniche non fanno male. Abbiamo gi\u00e0 ottenuto importanti vittorie in tribunale e continueremo a vigilare e ad intervenire in caso di comportamenti scorretti. Nel caso delle sigarette elettroniche usa e getta si aggiunge un altro tema a quello della salute, ovvero la questione ambientale. Questi dispositivi, infatti, rappresentano un problema non indifferente dal punto di vista dello smaltimento tra batteria ed involucro. Finisce tutto indiscriminatamente in discarica e questo \u00e8 un problema che non bisogna sottovalutare. Ci auguriamo che anche in Italia si inizi a ragionare seriamente sulle sigarette elettroniche usa e getta, pensando ad uno stop come stanno facendo in altri Paesi\u201d.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/19\/stop-alle-sigarette-elettroniche-una-minaccia-per-la-salute-e-lambiente\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/19\/stop-alle-sigarette-elettroniche-una-minaccia-per-la-salute-e-lambiente\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Da Roma, Francesco Serangeli, per conto dell\u2019associazione Codici, Centro per i Diritti del Cittadino, ci manda il seguente comunicato _______\u00a0 Codici: stop alle sigarette elettroniche usa e getta,&nbsp;sono una minaccia per la salute e l\u2019ambiente Se ne parla tanto, alcuni Paesi stanno studiando delle azioni ed anche l\u2019Italia dovrebbe muoversi. Il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":224614,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224613"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=224613"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224613\/revisions"}],"predecessor-version":[{"id":224615,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224613\/revisions\/224615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/224614"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=224613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=224613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=224613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}