{"id":224888,"date":"2023-12-26T15:25:45","date_gmt":"2023-12-26T14:25:45","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=224888"},"modified":"2023-12-26T16:03:33","modified_gmt":"2023-12-26T15:03:33","slug":"la-polemica-te-piace-o-presepe-ma-anche-no-natale-in-casa-bonino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/26\/la-polemica-te-piace-o-presepe-ma-anche-no-natale-in-casa-bonino\/","title":{"rendered":"LA POLEMICA \/ \u201cTe piace \u2018o presepe?\u201d &#8230;MA ANCHE NO! NATALE IN CASA BONINO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1360\" height=\"2048\" class=\"wp-image-224889\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/401095525_898434224977875_5684880310974580102_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/401095525_898434224977875_5684880310974580102_n.jpg 1360w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/401095525_898434224977875_5684880310974580102_n-199x300.jpg 199w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/401095525_898434224977875_5684880310974580102_n-680x1024.jpg 680w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/401095525_898434224977875_5684880310974580102_n-768x1157.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/401095525_898434224977875_5684880310974580102_n-1020x1536.jpg 1020w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/>(Rdl) ______ <\/p>\n\n\n\n<p>+Europa, il partito europeista e liberale, nato dalle ceneri dei Radicali, di cui \u00e8 leader Emma Bonino, ha fatto gli auguri di Natale tramite web con una illustrazione multipla, in cui si vedono \u00a0diverse \u201cvarianti\u201d del presepe, tra cui una con due Giuseppe e una con due Maria.<\/p>\n\n\n\n<p>Omettiamo di riprodurla&nbsp;semplicemente per questione di buon gusto.<\/p>\n\n\n\n<p>E stato  un boomerang.<\/p>\n\n\n\n<p>La pi\u00f9 scandalizzata, proprio una  iscritta  a +Europa, <strong>Anita Likmeta<\/strong> (nella foto), giovane imprenditrice italo-albanese, nata a Durazzo, durante il regime comunista ed emigrata con successo in Italia, dove \u00e8 particolarmente attiva nel settore delle cosiddette statupp, la qale  ha affidato a Facebook il proprio  sdegno, annunciando di voler abbandore il  partito<strong>:<\/strong> <em><strong>\u201dSe +Europa pensa di difendere la diversit\u00e0 con ammiccamenti ipocriti alla tradizione, io per il ruolo della Madonna lesbica non sono disponibile. Addio a +Europa e buon suicidio politico (non assistito)\u201d<\/strong><\/em>.<\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/26\/la-polemica-te-piace-o-presepe-ma-anche-no-natale-in-casa-bonino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/26\/la-polemica-te-piace-o-presepe-ma-anche-no-natale-in-casa-bonino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) ______ +Europa, il partito europeista e liberale, nato dalle ceneri dei Radicali, di cui \u00e8 leader Emma Bonino, ha fatto gli auguri di Natale tramite web con una illustrazione multipla, in cui si vedono \u00a0diverse \u201cvarianti\u201d del presepe, tra cui una con due Giuseppe e una con due Maria. Omettiamo di riprodurla&nbsp;semplicemente per questione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":224889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224888"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=224888"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224888\/revisions"}],"predecessor-version":[{"id":224899,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/224888\/revisions\/224899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/224889"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=224888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=224888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=224888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}