{"id":225087,"date":"2023-12-31T15:44:51","date_gmt":"2023-12-31T14:44:51","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=225087"},"modified":"2023-12-31T15:46:09","modified_gmt":"2023-12-31T14:46:09","slug":"225087","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/31\/225087\/","title":{"rendered":"ARRESTATO PER SPACCIO DI DROGA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"197\" class=\"wp-image-225088\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2023\/12\/ostu-300x197-1.jpg\" alt=\"\"><\/p>\n\n\n\n<p>(e.l.) ______&nbsp; L<strong>&#8216;<\/strong>&nbsp;altro giorno gli agenti del locale Commissariato (nella foto) hanno arrestato un giovane di 23 anni di Ostuni, gi\u00e0 noto alle forze dell\u2019ordine.<\/p>\n\n\n\n<p>Durante un serviio di controllo del territorio, \u00e8 stato trovato in possesso di centocinquanta grammi di marijuana e di materiale utile al confezionamento delle dosi. <\/p>\n\n\n\n<p>Dopo l<strong>&#8216;<\/strong>&nbsp;arresto in flagranza di reato, il pm di turno presso la Procura della Repubblica ha disposto i domiciliari e nella successiva udienza di convalida dell<strong>&#8216;<\/strong>arresto il gip del Tribunale di Brindisi ha deciso a carico del giovane la misura cautelare dell\u2019obbligo di dimora.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/31\/225087\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2023\/12\/31\/225087\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______&nbsp; L&#8216;&nbsp;altro giorno gli agenti del locale Commissariato (nella foto) hanno arrestato un giovane di 23 anni di Ostuni, gi\u00e0 noto alle forze dell\u2019ordine. Durante un serviio di controllo del territorio, \u00e8 stato trovato in possesso di centocinquanta grammi di marijuana e di materiale utile al confezionamento delle dosi. Dopo l&#8216;&nbsp;arresto in flagranza di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":225088,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/225087"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=225087"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/225087\/revisions"}],"predecessor-version":[{"id":225090,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/225087\/revisions\/225090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/225088"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=225087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=225087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=225087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}