{"id":22529,"date":"2013-12-10T12:27:39","date_gmt":"2013-12-10T12:27:39","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22529"},"modified":"2013-12-10T12:27:39","modified_gmt":"2013-12-10T12:27:39","slug":"ti-posso-impiantare-un-gioiello-nel-cervello","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/10\/ti-posso-impiantare-un-gioiello-nel-cervello\/","title":{"rendered":"TI POSSO IMPIANTARE UN GIOIELLO &#8230;NEL CERVELLO?"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/gioiello-occhio.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/gioiello-occhio-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-22530\" \/><\/a>Una tendenza molto pericolosa si fa strada tra i pi\u00f9 giovani: impiantare gioielli all&#8217;interno degli occhi. Sembra strano, ma molti ragazzi sono gi\u00e0 andati sotto i ferri per sottoporsi a questo tipo di operazione chirurgica.<\/p>\n<p>Questa moda \u00e8 nata in Europa, in particolare nell&#8217; Istituto per l&#8217;innovazione della chirurgia oculare a Rotterdam, che ha fatto alcuni impianti di questo tipo e ha pubblicato i propri risultati. Raggiungendo la conclusione che l&#8217;impianto di gioielli di platino nel bulbo oculare non causa alcun rischio per la salute.<\/p>\n<p>Ci\u00f2 accadeva nel 2003, ma l&#8217;installazione di questo tipo di decorazione nell&#8217;occhio dopo che \u00e8 stato trasmesso in diretta tv negli USA ha sub\u00ecto un exploit, specie tra i giovani yankee.<\/p>\n<p>In particolare, il dottor Emil Chynn, esperto di questa chirurgia, attraverso la televisione ha mostrato a milioni di telespettatori come attraverso una piccola spaccatura nella membrana esterna trasparente dell&#8217;occhio si possa inserire un sottile frammento di gioiello. Un intervento che dura circa 10-15 minuti e costa tra i 3.000 e 4.000 dollari (2.200 o 2.900 euro).<\/p>\n<p>Il paziente che si \u00e8 sottoposto all\u2019operazione \u201ctelevisiva\u201d ha comunicato in seguito di sentire un leggero fastidio solo i primi giorni, ma che poi con il tempo non si accorgeva pi\u00f9 di nulla.<\/p>\n<p>Gli oculisti hanno immediatamente preso posizione descrivendo questa nuova moda come un fenomeno da \u201cpazzi\u201d ed hanno elencati i rischi: infezioni sino alla cecit\u00e0, emorragia, emorragia subcongiuntivale, perforazione dell&#8217;occhio e congiuntivite.<\/p>\n<p>Una tecnica rischiosa che solo il tempo potr\u00e0 dir\u00e0 se si estender\u00e0 o se sar\u00e0 dimenticata a causa dei notevoli rischi per la salute, a meno che, rileva Giovanni D&#8217;Agata,\u00a0non si decida la scelta pi\u00f9 opportuna: vietarla completamente.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/10\/ti-posso-impiantare-un-gioiello-nel-cervello\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/10\/ti-posso-impiantare-un-gioiello-nel-cervello\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Una tendenza molto pericolosa si fa strada tra i pi\u00f9 giovani: impiantare gioielli all&#8217;interno degli occhi. Sembra strano, ma molti ragazzi sono gi\u00e0 andati sotto i ferri per sottoporsi a questo tipo di operazione chirurgica. Questa moda \u00e8 nata in Europa, in particolare nell&#8217; Istituto per l&#8217;innovazione della chirurgia oculare a Rotterdam, che ha fatto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22530,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22529"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22529"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22529\/revisions"}],"predecessor-version":[{"id":22531,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22529\/revisions\/22531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/22530"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}