{"id":22575,"date":"2013-12-11T09:26:42","date_gmt":"2013-12-11T09:26:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22575"},"modified":"2013-12-11T09:26:42","modified_gmt":"2013-12-11T09:26:42","slug":"fugge-al-controllo-arrestato-sorvegliato-speciale-arrestati-ladri-di-legna","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/11\/fugge-al-controllo-arrestato-sorvegliato-speciale-arrestati-ladri-di-legna\/","title":{"rendered":"FUGGE AL CONTROLLO: ARRESTATO SORVEGLIATO SPECIALE &#8211; ARRESTATI LADRI DI LEGNA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/legna.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/legna-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-22576\" \/><\/a>Questa notte, i Carabinieri della Stazione di Nociglia, hanno tratto in arresto per violazione degli obblighi della sorveglianza speciale di pubblica sicurezza\u00a0<strong>Carangelo Vittorio<\/strong>, 49enne di Taurisano. Quest\u2019ultimo, sorvegliato speciale di P.S. con obbligo di soggiorno nel comune di Taurisano, ieri sera, durante un normale controllo da parte dei militari, \u00e8 stato trovato a bordo di un autocarro, per le vie del centro del comune di Nociglia. Quest\u2019ultimo, con numerosissimi precedenti per reati contro la persona e contro il patrimonio in particolare, dopo essere stato fermato dalla pattuglia, in un primo momento ha fornito ai militari generalit\u00e0 false, ma accortosi che i Carabinieri stavano andando a fondo nel controllo, e che avrebbero scoperto le sue violazioni, ha deciso di intraprendere una disperata fuga a piedi per le vie circostanti. Sono cos\u00ec cominciate le ricerche da parte dei carabinieri, coadiuvati anche dai colleghi di Taurisano, che hanno consentito, dopo una serrata battuta, di scovare il fuggitivo, all\u2019interno della propria abitazione, raggiunta poco prima dal malcapitato. Quest\u2019ultimo, a seguito delle operazioni di identificazione, \u00e8 stato tratto in arresto per i reati di false dichiarazioni sull\u2019identit\u00e0 personale e violazione degli obblighi attinenti la sorveglianza speciale di pubblica sicurezza con obbligo di soggiorno. Infatti, tra le prescrizioni inerenti la misura di prevenzione a carico di Carangelo, vi \u00e8 anche l\u2019obbligo di soggiorno nel comune di Taurisano, dal quale il medesimo non avrebbe dovuto allontanarsi senza la richiesta autorizzazione. Il Carangelo al termine delle formalit\u00e0 di rito, \u00e8 stato associato alla Casa Circondariale di Lecce a disposizione del Pubblico Ministero, Dott.ssa Guglielmi.<\/p>\n<p align=\"center\"><em>\u00a0<\/em><\/p>\n<p>\u00a0<em>IN DUE ARRESTATI PER FURTO DI LEGNA<\/em><\/p>\n<p>Nel pomeriggio di ieri 09 dicembre 2013 i militari della Stazione CC di Casarano hanno proceduto all\u2019arresto in flagranza del reato di danneggiamento aggravato e tentato furto aggravato di due persone di Casarano:<\/p>\n<ul>\n<li>Causo Quintino cl. 64, di Casarano, non occupato, gi\u00e0 Noto alle FF.PP.;<\/li>\n<li>De Blasi Lucio Nicola cl.\u00a0 69 di Casarano, coniugato, non occupato, gi\u00e0 noto alle FF.PP.<\/li>\n<\/ul>\n<p>Erano le prime ore del pomeriggio quando perveniva alla Stazione CC di Casarano una segnalazione\u00a0 circa un presunto furto di legna che si stava consumando nella contrada Cal\u00f2. Acquisita la notizia, immediatamente gli uomini dell\u2019Arma si avviavano verso quella localit\u00e0 per riscontrare quanto poco prima appurato ed effettivamente al loro arrivo i militari notavano, all\u2019interno di un terreno pieno di alberi di olivo, due soggetti intenti a tagliarne diversi con una motosega. Alla vista dei Carabinieri una delle due persone, successivamente identificata nel CAUSO, cercava di allontanarsi a passo veloce per la stessa campagna ma veniva prontamente fermato mentre l\u2019altra, il De Blasi,\u00a0 vistosi ormai scoperto, poneva a terra la motosega e rimaneva sul posto. I due avevano gi\u00e0 tagliato diversi alberi e si stavano adoperando a ridurre la legna in piccoli pezzi trasportabili su un motocarro. Successivi accertamenti permettevano di acclarare che il terreno fosse di propriet\u00e0 Comunale e che i due non avevano ricevuta alcuna autorizzazione per tagliare gli alberi ed appropriarsi della legna. Dell\u2019intero accaduto \u00e8 stato prontamente informato il PM di Turno presso la Procura della Repubblica di Lecce che disponeva il trattenimento dei due in regime di arresti domiciliari presso le proprie abitazioni. La legna \u00e8 stata restituita all\u2019Amministrazione Comunale. La motosega utilizzata per tagliare gli alberi \u00e8 stata posta sotto sequestro.<\/p>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/11\/fugge-al-controllo-arrestato-sorvegliato-speciale-arrestati-ladri-di-legna\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/11\/fugge-al-controllo-arrestato-sorvegliato-speciale-arrestati-ladri-di-legna\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Questa notte, i Carabinieri della Stazione di Nociglia, hanno tratto in arresto per violazione degli obblighi della sorveglianza speciale di pubblica sicurezza\u00a0Carangelo Vittorio, 49enne di Taurisano. Quest\u2019ultimo, sorvegliato speciale di P.S. con obbligo di soggiorno nel comune di Taurisano, ieri sera, durante un normale controllo da parte dei militari, \u00e8 stato trovato a bordo di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22576,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22575"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22575"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22575\/revisions"}],"predecessor-version":[{"id":22577,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22575\/revisions\/22577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/22576"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}