{"id":22594,"date":"2013-12-11T14:57:57","date_gmt":"2013-12-11T14:57:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22594"},"modified":"2013-12-11T14:57:57","modified_gmt":"2013-12-11T14:57:57","slug":"impresa-edile-non-dichiara-ricavi-per-oltre-330-000-euro-per-non-chiudere-i-batttenti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/11\/impresa-edile-non-dichiara-ricavi-per-oltre-330-000-euro-per-non-chiudere-i-batttenti\/","title":{"rendered":"IMPRESA EDILE NON DICHIARA RICAVI PER OLTRE 330.000 EURO&#8230; per non chiudere i batttenti"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/Unknown.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/Unknown-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-22595\" \/><\/a>La Compagnia della Guardia di Finanza di Lecce ha scoperto che un\u2019impresa edile del capoluogo salentino ha occultato al fisco ricavi per oltre 332.000 euro ed evaso I.V.A. per oltre 66.000 euro.<br \/>\nIn particolare, al termine di una verifica fiscale conclusa nei confronti della ditta individuale di un imprenditore operante nel settore della costruzione di ville e appartamenti residenziali, le Fiamme Gialle leccesi hanno constatato tali violazioni per il biennio 2009\/2010.<br \/>\nInoltre, \u00e8 emersa anche l\u2019omessa presentazione delle prescritte dichiarazioni fiscali che qualifica il contribuente ispezionato come \u201cevasore totale\u201d.<br \/>\nPer tale motivo, il titolare dell\u2019impresa edile \u00e8 stato segnalato all\u2019Autorit\u00e0 Giudiziaria per violazione dell\u2019art. 5 del d.lgs. n. 74\/2000.<br \/>\nL&#8217;interessato raggiunto telefonicamente ha dichiarato che era l&#8217;unico modo per non chiudere i battenti \u00a0e pagare le maestranze, data la crisi del settore, e le tasse inique che attanagliano le piccole imprese.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/11\/impresa-edile-non-dichiara-ricavi-per-oltre-330-000-euro-per-non-chiudere-i-batttenti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/11\/impresa-edile-non-dichiara-ricavi-per-oltre-330-000-euro-per-non-chiudere-i-batttenti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La Compagnia della Guardia di Finanza di Lecce ha scoperto che un\u2019impresa edile del capoluogo salentino ha occultato al fisco ricavi per oltre 332.000 euro ed evaso I.V.A. per oltre 66.000 euro. In particolare, al termine di una verifica fiscale conclusa nei confronti della ditta individuale di un imprenditore operante nel settore della costruzione di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22595,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22594"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22594"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22594\/revisions"}],"predecessor-version":[{"id":22597,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22594\/revisions\/22597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/22595"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}