{"id":22636,"date":"2013-12-13T00:16:24","date_gmt":"2013-12-13T00:16:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22636"},"modified":"2013-12-13T00:18:01","modified_gmt":"2013-12-13T00:18:01","slug":"i-forconi-visti-da-vicino-a-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/i-forconi-visti-da-vicino-a-lecce\/","title":{"rendered":"\u201cI FORCONI\u201d VISTI DA VICINO A LECCE"},"content":{"rendered":"<p><strong>\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-22636 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/i-forconi-visti-da-vicino-a-lecce\/forconi1\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/forconi1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/i-forconi-visti-da-vicino-a-lecce\/forconi2\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/forconi2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/i-forconi-visti-da-vicino-a-lecce\/forconi4\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/forconi4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/i-forconi-visti-da-vicino-a-lecce\/forconi5\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/forconi5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/i-forconi-visti-da-vicino-a-lecce\/forconi7\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/forconi7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Tutti a casa!<\/p>\n<p>Chiunque volesse identificare il movimento dei forconi &#8211; anche se loro gradiscono la parola coordinamento &#8211; in una qualsiasi figura politica attualmente esistente, sta sbagliando di grosso. Li ho visti a Lecce, li ho incontrati. Un gruppo di manifestanti, costituito da disoccupati, pensionati, precari, studenti, artigiani, commercianti soprattutto ambulanti, insomma tutto e il contrario di tutto.<\/p>\n<p>La loro non \u00e8 lotta politica, infatti si sono dichiarati subito apolitici, nel senso di apartitici, ma una lotta disperata di gente comune che non ce la fa pi\u00f9 ad andare avanti, a lottare contro le tasse, Equitalia, aumenti, tagli e sacrifici immani.<\/p>\n<p>Insomma vogliono una sola cosa: mandare a casa l&#8217;attuale classe politica &#8211; oramai completamente staccata dalla realt\u00e0 e sorda alle grida di disperazione che si alzano da molti strati del Paese &#8211; ed andare subito ad elezioni anticipate. In buona sostanza, quello che, in questo momento, vorrebbe la maggioranza degli italiani: &#8220;Tutti a casa!&#8221;<\/p>\n<p>Il Sistema logicamente ha preso le contromisure e si \u00e8 mosso subito attraverso il suo apparato costituito da un &#8216;informazione a senso unico. L&#8217;Italia \u00e8 al settantesimo posto nel mondo per libert\u00e0 di informazione. Cos\u00ec i &#8220;forconi&#8221; sono stati descritti come dei facinorosi, dei violenti, estremisti, fascisti e ultras che: &#8220;<em>vogliono solo il caos e mettere a ferro e fuoco le citt\u00e0<\/em>&#8220;. Tutti i media di regime hanno dato risalto alla notizia che il leader, Danilo Calvani, \u00e8 arrivato ad un comizio addirittura con una Jaguar: &#8220;come fa uno che parla contro gli sprechi della politica a girare con un&#8217; auto extra &#8211; lusso?&#8221; Poi si \u00e8 scoperto che l&#8217;auto non \u00e8 sua, ma di un amico e che non possiede alcuna auto, solo debiti. Cos\u00ec il movimento dei forconi \u00e8 stato prima censurato ed ora demonizzato. Da parte dei nostri governanti, chiusi nel Palazzo, che continuano indifferenti a sprecare e intrallazzare, si sta sottovalutando un fenomeno che \u00e8 la punta di un iceberg di un diffuso malessere sociale, di gente disperata.<\/p>\n<p><strong>Tonio Leuci<\/strong><\/p>\n<div><strong><br \/>\n<\/strong><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/i-forconi-visti-da-vicino-a-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/i-forconi-visti-da-vicino-a-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Tutti a casa! Chiunque volesse identificare il movimento dei forconi &#8211; anche se loro gradiscono la parola coordinamento &#8211; in una qualsiasi figura politica attualmente esistente, sta sbagliando di grosso. Li ho visti a Lecce, li ho incontrati. Un gruppo di manifestanti, costituito da disoccupati, pensionati, precari, studenti, artigiani, commercianti soprattutto ambulanti, insomma tutto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22636"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22636"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22636\/revisions"}],"predecessor-version":[{"id":22644,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22636\/revisions\/22644"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}