{"id":22649,"date":"2013-12-13T09:17:51","date_gmt":"2013-12-13T09:17:51","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22649"},"modified":"2013-12-13T09:28:42","modified_gmt":"2013-12-13T09:28:42","slug":"erika-dal-salento-allafrica-ci-racconta-una-storia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/erika-dal-salento-allafrica-ci-racconta-una-storia\/","title":{"rendered":"ERIKA, DAL SALENTO ALL&#8217;AFRICA, CI RACCONTA UNA STORIA."},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-22649 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/erika-dal-salento-allafrica-ci-racconta-una-storia\/africa\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/AFRICA-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/erika-dal-salento-allafrica-ci-racconta-una-storia\/africa1\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/AFRICA1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/erika-dal-salento-allafrica-ci-racconta-una-storia\/africa2\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/AFRICA2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Erica Zingaropoli, u<strong>na ragazza salentina che ha fatto una scelta di vita su cui \u00e8 prezioso per tutti noi riflettere almeno un po\u2019, <\/strong>ci racconta la storia di Miriam, emblema dell&#8217;infanzia sfortunata del Terzo Mondo.<\/p>\n<p>&nbsp;<\/p>\n<p>Miriam ha sei anni, \u00e8 una bambina allegra, instancabile, gli amici la chiamano scoiattolino, frequenta la primary e vive in un villaggio poco lontano da Mombasa.<\/p>\n<p>&nbsp;<\/p>\n<p>Prima di andare a scuola, tutte le mattine, corre verso il pozzo con il bidoncino vuoto da cinque litri, tira su l\u2019acqua con il secchio legato a una corda e riempie il suo tino che, una volta colmo, posa sul capo, poi lentamente torna a casa.<\/p>\n<p>&nbsp;<\/p>\n<p>Vive a pochi metri dal centro del villaggio, in una piccola insenatura che si affaccia sul bosco, i nuclei familiari sono solitamente divisi in piccoli compound. Le capanne sono disposte a cerchio, gli abitanti vivono in cinque in ogni casa, il fuoco \u00e8 al centro e di notte illumina le dimore disposte a mezzaluna.<\/p>\n<p>Le tre sorelle di Miriam sono iscritta alla high school. Pi\u00f9 di tutte lei ama Lilian, \u00e8 la terzogenita, ha diciassette anni e le somiglia molto, ha le gambe sottili, la pelle di bronzo e i capelli affusolati che tiene in ordine con lunghe treccine. Sono spesso insieme, Lilian \u00e8 pi\u00f9 silenziosa di lei, taciturna, composta.<\/p>\n<p>&nbsp;<\/p>\n<p>Due sere prima Miriam l\u2019aveva sentita discutere con un ragazzo, pare uscissero insieme da un po\u2019, sembrava arrabbiato, geloso di qualcosa che la sorella aveva fatto. Lilian aveva pranzato poco il giorno seguente e non aveva scambiato parola con nessuno. Miriam l\u2019aveva osservata per tutto il tempo, seduta sui gradini di una vecchia costruzione disabitata. Le aveva portato il t\u00e8, ma la sorella maggiore lo aveva a malapena assaggiato, riprendendo poi a ruotare la tazza e contemplando la sua ombra nell\u2019infuso scuro. Quella stessa sera, quel ragazzo era tornato da lei, Miriam era sgattaiolata fuori dal letto fino a raggiungere un albero dal quale poteva sentire e vedere la sorella che discuteva nuovamente con il ragazzo. Questa volta sembravano pi\u00f9 sereni, finch\u00e9 lui la prende per mano e le chiede di fare una passeggiata.<\/p>\n<p>Sono circa le dieci di sera e a quell\u2019ora nessuno \u00e8 in giro per il villaggio. I due ragazzi si dirigono verso il boschetto di pini e Miriam li segue. Nascosta dietro un sottile tronco, Miriam nota qualche scambio di baci e carezze tra i due ragazzi poco lontani da lei, abbassa lo sguardo e decide di tornare indietro. \u00c8 proprio in quel momento che avverte un tonfo, e nel voltarsi nota la sorella di spalle al ragazzo che le tiene una mano sulla bocca e ripetutamente le sbatte la testa contro il tronco di un albero, senza tregua, con forza.<\/p>\n<p>Lilian \u00e8 gi\u00e0 priva di sensi quando Miriam con un balzo corre incontro al ragazzo afferrandolo per il braccio e tirandolo a s\u00e9 per fargli mollare la presa. Lilian cade per terra priva di sensi, Miriam con le lacrime agli occhi cerca di dare addosso al ragazzo che la afferra per il collo e inizia a stringere, con forza, con entrambe le mani che lasciano scomparire l\u2019esile collo della bambina, finch\u00e9 lei, stanca, chiude gli occhi.<\/p>\n<p>&nbsp;<\/p>\n<p>Le due sorelle sono state ritrovate una settimana dopo dalla polizia prive degli occhi e dei genitali.<\/p>\n<p>Gli organi sono stati strappati via, i corpi erano pressoch\u00e9 in decomposizione quando i genitori sono stati interpellati per il riconoscimento dei cadaveri. C\u2019\u00e8 poca vita al villaggio, da un mese a questa parte la gente parla meno del solito, ma tutti sanno. Da anni, da tanti anni, ci sono credenze popolari derivanti da magia nera che sostengono che estirpare e vendere organi umani faccia arricchire gli esecutori. Gli organi vengono venduti per circa 700 euro a fattucchiere o seguaci di esse, con la promessa che l\u2019atto sacrificale verr\u00e0 ricompensato.<\/p>\n<p>L\u2019assassino non \u00e8 stato trovato, la gente racconta che sia scappato lontano, probabilmente in Tanzania.<\/p>\n<p>&nbsp;<\/p>\n<p>In Africa il parere e gli antidoti di maghi e streghe contano pi\u00f9 di un giudizio medico, se si soffre di una malattia l\u2019ammalato si reca dallo stregone di turno e solo in un secondo momento dal medico. La gente continua a chiedersi il perch\u00e9 di tali atti brutali, ma forse, prima di piangere assurde conseguenze, dovrebbe chiedersi quali siano i risultati nel crescere e far crescere con la consapevolezza che la magia possa salvare pi\u00f9 della medicina.<\/p>\n<p>Un inammissibile stato di incoerenza che caratterizza chi non ha e non ha mai avuto nulla e la vita non \u00e8 poi cos\u00ec preziosa e uccidere non \u00e8 un reato se lo stomaco \u00e8 a digiuno da giorni e tutti i giorni sono sempre gli stessi e una vita in pi\u00f9 o una vita in meno vissuta senza stimoli e alla continua ricerca di cibo, acqua, lavoro, pu\u00f2 essere spenta per quel divino denaro che pu\u00f2 comprare tutto.<\/p>\n<p>Un inammissibile stato di incoerenza, una colpa nel non avere colpe, pertanto, tacitamente, in segreto, giustificata.<\/p>\n<p><strong>Erica Zingaropoli<\/strong><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/erika-dal-salento-allafrica-ci-racconta-una-storia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/13\/erika-dal-salento-allafrica-ci-racconta-una-storia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Erica Zingaropoli, una ragazza salentina che ha fatto una scelta di vita su cui \u00e8 prezioso per tutti noi riflettere almeno un po\u2019, ci racconta la storia di Miriam, emblema dell&#8217;infanzia sfortunata del Terzo Mondo. &nbsp; Miriam ha sei anni, \u00e8 una bambina allegra, instancabile, gli amici la chiamano scoiattolino, frequenta la primary e vive [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22649"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22649"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22649\/revisions"}],"predecessor-version":[{"id":22654,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22649\/revisions\/22654"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}