{"id":226606,"date":"2024-02-18T11:47:36","date_gmt":"2024-02-18T10:47:36","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=226606"},"modified":"2024-02-25T12:54:52","modified_gmt":"2024-02-25T11:54:52","slug":"non-ho-ideologie-ma-ho-idee-alberto-siculella-si-racconta-a-leccecronaca-it-e-lancia-la-sfida-a-carlo-salvemini","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/18\/non-ho-ideologie-ma-ho-idee-alberto-siculella-si-racconta-a-leccecronaca-it-e-lancia-la-sfida-a-carlo-salvemini\/","title":{"rendered":"\u201cNon ho ideologie, ma ho idee\u201d. ALBERTO SICULELLA SI RACCONTA A leccecronaca.it E LANCIA LA SFIDA A CARLO SALVEMINI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1150\" height=\"1150\" class=\"wp-image-226610\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/cover.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/cover.jpeg 1150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/cover-300x300.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/cover-1024x1024.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/cover-150x150.jpeg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/cover-768x768.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/cover-60x60.jpeg 60w\" sizes=\"(max-width: 1150px) 100vw, 1150px\" \/><\/p>\n\n\n\n<p>di <strong>Giuseppe Puppo<\/strong> &nbsp;_______&nbsp;<\/p>\n\n\n\n<p><strong>\u2010&nbsp;<\/strong>Ma chi gliel&#8217;ha fatto fare, di candidarsi?<\/p>\n\n\n\n<p>Col sorriso sulle labbra, sparo la prima domanda a bruciapelo.<\/p>\n\n\n\n<p><strong>Alberto Siculella<\/strong>, 38 anni, di Lecce, ci pensa un attimo e poi mi risponde, serio in volto:<\/p>\n\n\n\n<p>Sono studioso, sono appassionato di politica. Non ho ideologie, ma ho tante idee.<\/p>\n\n\n\n<p><strong>\u2010&nbsp;<\/strong>Che studi ha fatto?<\/p>\n\n\n\n<p>&nbsp;Cresciuto nel quartiere San Pio, diplomato al Liceo Scientifico Banzi.<\/p>\n\n\n\n<p><strong>\u2010&nbsp;<\/strong>Io mi ricordo ai primi anni Settanta, al Palmieri, un Siculella mio coetaneo che si chiamava Alcino&#8230;<\/p>\n\n\n\n<p>Mi onoro di essere suo figlio\u2026<\/p>\n\n\n\n<p><strong>\u2010<\/strong>\u2026Figlio di un mitico professore amante del greco, che aveva dato ai suoi i nomi di Alcino, Agesandro e Atena\u2026<\/p>\n\n\n\n<p>\u2026Alberto, mio nonno\u2026 Io mi chiamo come lui\u2026<\/p>\n\n\n\n<p><strong>\u2010<\/strong>\u2026Perfetto\u2026 Bellissimo. Poi?<\/p>\n\n\n\n<p>Laurea triennale in Comunicazione d\u2019impresa e pubblicit\u00e0 presso l\u2019Universit\u00e0 Iulm di Milano, laurea magistrale in Organizzazione e marketing per le imprese presso La Sapienza di Roma e, sempre a Roma, un master in Gestione, marketing e programmazione delle imprese turistiche.<\/p>\n\n\n\n<p><strong>\u2010&nbsp;<\/strong>Prime esperienze lavorative?<\/p>\n\n\n\n<p>Lavoro da quando ho 16 anni, lavori stagionali prima, poi un continuo di varie esperienze in Italia e all\u2019estero, Malaga e Londra precisamente, dove ho perfezionato lo Spagnolo e l<strong>&#8216;<\/strong>Inglese. Consulente di marketing e comunicazione per le imprese, mi sono specializzato in marketing politico, turismo e commercio&nbsp;. Quindi il ritorno a Lecce&#8230;<\/p>\n\n\n\n<p><strong>\u2010&nbsp;<\/strong>E ora?<\/p>\n\n\n\n<p>Ho uno studio specializzato in consulenza di comunicazione e marketing per imprese.<\/p>\n\n\n\n<p>\u2010 Situazione sentimentale?<\/p>\n\n\n\n<p>Fidanzato.<\/p>\n\n\n\n<p>\u2010 Con\u2026<\/p>\n\n\n\n<p>Carlotta\u2026<\/p>\n\n\n\n<p>\u2010 E come l<strong>&#8216;<\/strong>ha presa, Carlotta, la storia della candidatura a sindaco?<\/p>\n\n\n\n<p>\u00c8 la mia prima sostenitrice, come lo \u00e8 la sua famiglia, come lo sono le mie sorelle e mia madre. L\u2019amore delle donne della mia vita mi da coraggio. Con Carlotta ci sposiamo l<strong>&#8216;<\/strong>estate prossima\u2026<\/p>\n\n\n\n<p>\u2010 Dopo la campagna elettorale che dovr\u00e0 affrontare\u2026 Ha pensato al come?<\/p>\n\n\n\n<p>La mia tesi di laurea, anche pubblicata, era sui nuovi strumenti di ricerca del consenso in politica, vale a dire internet e social media. La politica ha abusato dei social, la mia missione \u00e8 restituirla alla dimensione sociale. Partir\u00f2 da qui, dal sociale.&nbsp;<\/p>\n\n\n\n<p>\u2010 Capisco\u2026<\/p>\n\n\n\n<p>La mia prima campagna elettorale in prima persona, da protagonista, non da consulente\u2026Per passione, non per lavoro \u2026<\/p>\n\n\n\n<p>\u2010 Capisco..<\/p>\n\n\n\n<p>Per passione, ho seguito solo il Movimento 5 Stelle.<\/p>\n\n\n\n<p>\u2010 &nbsp;Che cosa valuta positivamente della loro esperienza politica?<\/p>\n\n\n\n<p>Tante cose.<\/p>\n\n\n\n<p>\u2010 &nbsp;Me ne dica una\u2026<\/p>\n\n\n\n<p>Il tema della legalit\u00e0. Aver messo finalmente la legalit\u00e0 al centro dell\u2019agenda politica. Mi reputo attivista attento e informato, ho partecipato ad incontri, iniziative e manifestazioni con realt\u00e0 associative e civiche della nostra citt\u00e0, con cui ho condiviso passioni e idee e che mi hanno portato ad esserne la sintesi, per una proposta di candidatura alternativa come primo cittadino di Lecce.<\/p>\n\n\n\n<p>\u2010 &nbsp;Mi dica allora una Sua tematica da candidato a sindaco\u2026<\/p>\n\n\n\n<p>Guardo a Lecce con la consapevolezza di viaggiare e aver vissuto altre realt\u00e0, questo mi ha dato la possibilit\u00e0, la voglia, di ripensare la nostra citt\u00e0, per utilizzare nuovi strumenti e per valorizzare il nostro patrimonio: cultura, turismo, tutela dell\u2019ambiente, le marine, ma non solo. \u00c8 ora di dare impulso ad un modello di sviluppo che guardi alle start up digitali, alle energie rinnovabili, alle nuove professioni, agli smart worker, al nomadismo digitale, offrendo le condizioni migliori per far rientrare cervelli, per ridare vita, ritrovare slancio. Ci sono nuovi strumenti, altrove gi\u00e0 ampiamente affermati e qui da noi invece ancora ai margini. &nbsp;<\/p>\n\n\n\n<p>\u2010 &nbsp;Mi dica un libro letto di recente\u2026<\/p>\n\n\n\n<p>&nbsp;\u201cLa Guerra di Pablo\u201d di Giancarlo Selmi, dal duplice valore, letterario, splendido, ed emotivo, visto che il ricavato serve per le cure dello splendido figlio Giulio, affetto da una malattia rara.<\/p>\n\n\n\n<p>\u2010 Genere musicale preferito\u2026<\/p>\n\n\n\n<p>Rock<\/p>\n\n\n\n<p>\u2010 &nbsp;Tipo?<\/p>\n\n\n\n<p>Genesis e Pink Floyd.<\/p>\n\n\n\n<p>\u2010 &nbsp;Cantante prediletto\u2026<\/p>\n\n\n\n<p>Daniele Silvestri.<\/p>\n\n\n\n<p>\u2010 &nbsp;Film del cuore, o, come dicono quelli che parlano bene l\u2019italiano, cult movie?<\/p>\n\n\n\n<p>\u201cInto the wild\u201d di Sean Penn, la storia vera di un giovane americano che subito dopo la laurea abbandon\u00f2 la famiglia e intraprese un lungo viaggio di due anni attraverso gli Stati Uniti, fino a raggiungere le terre sconfinate dei ghiacciai dell&#8217; Alaska.<\/p>\n\n\n\n<p>_______<\/p>\n\n\n\n<p>LA RICERCA nel nostro articolo del 13  febbraio scorso<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"oJ3NGMoAIq\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/13\/secondo-candidato-sindaco-a-lecceil-primo-sfidante-ufficiale-del-sindaco-uscentealberto-siculella\/\">ALBERTO SICULELLA SECONDO CANDIDATO SINDACO A LECCE, PRIMO SFIDANTE UFFICIALE DI CARLO SALVEMINI<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;ALBERTO SICULELLA SECONDO CANDIDATO SINDACO A LECCE, PRIMO SFIDANTE UFFICIALE DI CARLO SALVEMINI&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/13\/secondo-candidato-sindaco-a-lecceil-primo-sfidante-ufficiale-del-sindaco-uscentealberto-siculella\/embed\/#?secret=1IUlb0CQu1#?secret=oJ3NGMoAIq\" data-secret=\"oJ3NGMoAIq\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p> <\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/18\/non-ho-ideologie-ma-ho-idee-alberto-siculella-si-racconta-a-leccecronaca-it-e-lancia-la-sfida-a-carlo-salvemini\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/18\/non-ho-ideologie-ma-ho-idee-alberto-siculella-si-racconta-a-leccecronaca-it-e-lancia-la-sfida-a-carlo-salvemini\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo &nbsp;_______&nbsp; \u2010&nbsp;Ma chi gliel&#8217;ha fatto fare, di candidarsi? Col sorriso sulle labbra, sparo la prima domanda a bruciapelo. Alberto Siculella, 38 anni, di Lecce, ci pensa un attimo e poi mi risponde, serio in volto: Sono studioso, sono appassionato di politica. Non ho ideologie, ma ho tante idee. \u2010&nbsp;Che studi ha fatto? [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":226610,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/226606"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=226606"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/226606\/revisions"}],"predecessor-version":[{"id":226642,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/226606\/revisions\/226642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/226610"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=226606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=226606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=226606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}