{"id":226747,"date":"2024-02-23T15:12:19","date_gmt":"2024-02-23T14:12:19","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=226747"},"modified":"2024-02-23T15:12:45","modified_gmt":"2024-02-23T14:12:45","slug":"controlli-antidroga-della-finanza","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/23\/controlli-antidroga-della-finanza\/","title":{"rendered":"CONTROLLI ANTIDROGA DELLA FINANZA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1920\" height=\"1436\" class=\"wp-image-226748\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/23022024_084937_23.02.2024-stupefacenti.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/23022024_084937_23.02.2024-stupefacenti.jpg 1920w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/23022024_084937_23.02.2024-stupefacenti-300x224.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/23022024_084937_23.02.2024-stupefacenti-1024x766.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/23022024_084937_23.02.2024-stupefacenti-768x574.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/23022024_084937_23.02.2024-stupefacenti-1536x1149.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/02\/23022024_084937_23.02.2024-stupefacenti-400x300.jpg 400w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n\n\n\n<p>(e.l.) _______ Negli ultimi giorni la Guardia di Finanza di Taranto ha attuato sull\u2019intero territorio provinciale una serie di interventi finalizzati al contrasto dei traffici illeciti, con particolare riguardo allo spaccio di sostanze stupefacenti.<\/p>\n\n\n\n<p>I controlli antidroga, svolti con l\u2019ausilio delle unit\u00e0 cinofile, hanno interessato, nelle diverse fasce orarie della giornata, gli scali portuali e le stazioni ferroviarie nonch\u00e9 le strutture ricettive e i luoghi di aggregazione pi\u00f9 in voga tra i giovani.<\/p>\n\n\n\n<p>Le Fiamme Gialle hanno sequestrato numerose dosi di hashish, marijuana, eroina e cocaina, segnalando all\u2019Autorit\u00e0 prefettizia trenta persone.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/23\/controlli-antidroga-della-finanza\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/23\/controlli-antidroga-della-finanza\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) _______ Negli ultimi giorni la Guardia di Finanza di Taranto ha attuato sull\u2019intero territorio provinciale una serie di interventi finalizzati al contrasto dei traffici illeciti, con particolare riguardo allo spaccio di sostanze stupefacenti. I controlli antidroga, svolti con l\u2019ausilio delle unit\u00e0 cinofile, hanno interessato, nelle diverse fasce orarie della giornata, gli scali portuali e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":226748,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/226747"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=226747"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/226747\/revisions"}],"predecessor-version":[{"id":226749,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/226747\/revisions\/226749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/226748"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=226747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=226747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=226747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}