{"id":227007,"date":"2024-03-01T15:52:58","date_gmt":"2024-03-01T14:52:58","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=227007"},"modified":"2024-03-01T15:53:41","modified_gmt":"2024-03-01T14:53:41","slug":"i-promotori-dellistituzione-del-limite-di-velocita-di-30-allora-a-lecce-citta-danno-appuntamento-a-domenica-3","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/01\/i-promotori-dellistituzione-del-limite-di-velocita-di-30-allora-a-lecce-citta-danno-appuntamento-a-domenica-3\/","title":{"rendered":"I PROMOTORI DELL\u2019ISTITUZIONE DEL LIMITE DI VELOCITA\u2019 DI 30 ALL\u2019ORA A LECCE CITTA\u2019 DANNO APPUNTAMENTO A DOMENICA 3"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1977\" height=\"2048\" class=\"wp-image-227008\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/FLASHMOBPORTARUDIAE_13.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/FLASHMOBPORTARUDIAE_13.jpeg 1977w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/FLASHMOBPORTARUDIAE_13-290x300.jpeg 290w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/FLASHMOBPORTARUDIAE_13-989x1024.jpeg 989w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/FLASHMOBPORTARUDIAE_13-768x796.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/FLASHMOBPORTARUDIAE_13-1483x1536.jpeg 1483w\" sizes=\"(max-width: 1977px) 100vw, 1977px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. ______\u00a0<\/p>\n\n\n\n<p><strong><em>Domenica 3 marzo alle 11&nbsp;<\/em><\/strong><em>iniziativa per la campagna nazionale itinerante di Clean Cities<\/em><\/p>\n\n\n\n<p><em>\u201c<strong>Citt\u00e02030: le citt\u00e0 e la sfida del cambiamento<\/strong>\u201d<\/em><\/p>\n\n\n\n<p><strong>Flash mob in centro per Lecce30<\/strong><\/p>\n\n\n\n<p><em>Raccolta di firme per la petizione popolare<\/em><\/p>\n\n\n\n<p>Un allegro flashmob in centro per raccogliere firme per la campagna Lecce30, sulla&nbsp;<strong>petizione popolare<\/strong>&nbsp;per chiedere che&nbsp;<strong>Lecce diventi una citt\u00e0 30<\/strong>, promossa dal movimento di cittadinanza attiva&nbsp;<strong>LeccePedala&nbsp;<\/strong>a cui ha aderito un cartello di&nbsp;<strong>ben 36 associazioni e realt\u00e0 sociali<\/strong>&nbsp;della citt\u00e0. L\u2019appuntamento \u00e8 alle 11 in&nbsp;<strong>piazza Sant\u2019Oronzo<\/strong>&nbsp;dove gli attivisti si ritroveranno in bici per fare un breve giro in centro&nbsp;<strong>guidati da una cargobike<\/strong>.<\/p>\n\n\n\n<p>Questa iniziativa \u00e8 organizzata in occasione del passaggio in citt\u00e0 della campagna nazionale itinerante \u201c<strong>Citt\u00e02030: le citt\u00e0 e la sfida del cambiamento<\/strong>\u201d, organizzata da Legambiente nell\u2019ambito della&nbsp;<strong>Clean Cities Campaign&nbsp;<\/strong>per promuovere una&nbsp;<strong>mobilit\u00e0 sostenibile e a zero emissioni<\/strong>. La campagna arriva a Lecce dove marted\u00ec 5 marzo verranno presentati i dati sulla mobilit\u00e0 nel capoluogo.<\/p>\n\n\n\n<p>Lecce \u00e8 soffocata dal traffico sia per l\u2019alto tasso di motorizzazione (<strong>71 auto ogni cento abitanti<\/strong>) sia per l\u2019elevato numero di auto di pendolari e turisti che ogni giorno si riversano in citt\u00e0 (90mila al giorno secondo i dati del Comune di Lecce).<\/p>\n\n\n\n<p>A Lecce la velocit\u00e0 media nelle ore di punta, come \u00e8 facile constatare, \u00e8 ben al di sotto dei 30 km all\u2019ora. Ciononostante, dal 2014 al 2023 nell\u2019intero territorio comunale si sono registrati&nbsp;<strong>40 morti e 4.158 feriti in 4.198 incidenti stradali&nbsp;<\/strong>e la media di 4 morti e quasi 416 feriti all\u2019anno \u00e8 sottostimata perch\u00e9 sono inclusi gli anni di lockdown. Tra il 2014 e il 2023 nel territorio comunale sono stati coinvolti negli incidenti&nbsp;<strong>748 pedoni (8 morti e 696 feriti) e 454 ciclisti (3 morti e 411 feriti)<\/strong>. \u00c8 un prezzo troppo alto che la comunit\u00e0 non pu\u00f2 permettersi di pagare.<\/p>\n\n\n\n<p>C\u2019\u00e8 da sottolineare come buona parte degli&nbsp;<strong>spostamenti in ambito urbano&nbsp;<\/strong>spesso \u00e8 sotto i 2 km e a Lecce l\u2019indice di prossimit\u00e0 (DEDA NEXT) mostra che Lecce sarebbe gi\u00e0 una \u201c<strong>Citt\u00e0 15 minuti<\/strong>\u201d, se fossero garantiti sempre percorsi ciclopedonali sicuri e un trasporto pubblico pi\u00f9 efficiente, producendo cos\u00ec il risultato di una reale riduzione delle distanze (anche sociali), con comunit\u00e0 sempre pi\u00f9 inclusive e accessibili. Lecce potrebbe diventare senza problemi un ambiente urbano in cui il cittadino \u00e8 in grado di raggiungere, senza dover fare uso dell\u2019auto, la maggior parte dei luoghi di suo interesse (lavoro, scuola, negozi e altri servizi) nel giro di un quarto d\u2019ora, migliorando cos\u00ec la sua qualit\u00e0 della vita.<\/p>\n\n\n\n<p><strong><em>Adriana De Carlo e Andrea Alba<\/em><\/strong><\/p>\n\n\n\n<p><em>(Portavoce Lecce30\/LeccePedala)<\/em> ______\u00a0<\/p>\n\n\n\n<p>LA RICERCA nel nostro articolo del 23 febbraio scorso (con in coda i commenti nel frattempo ricevuti sul giornale)<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"9CQIuLRUqL\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/23\/una-petizione-per-chiedere-listituzione-del-limite-di-velocita-di-30-allora-a-lecce-citta-ecco-chi-lo-vuole-e-perche\/\">UNA PETIZIONE PER CHIEDERE L&#8217;ISTITUZIONE  DEL LIMITE DI VELOCITA&#8217; DI 30 ALL&#8217;ORA A LECCE CITTA&#8217;. ECCO CHI LO VUOLE E PERCHE&#8217;\u00a0<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;UNA PETIZIONE PER CHIEDERE L&#8217;ISTITUZIONE  DEL LIMITE DI VELOCITA&#8217; DI 30 ALL&#8217;ORA A LECCE CITTA&#8217;. ECCO CHI LO VUOLE E PERCHE&#8217;\u00a0&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/02\/23\/una-petizione-per-chiedere-listituzione-del-limite-di-velocita-di-30-allora-a-lecce-citta-ecco-chi-lo-vuole-e-perche\/embed\/#?secret=PjtxO7zZrf#?secret=9CQIuLRUqL\" data-secret=\"9CQIuLRUqL\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/01\/i-promotori-dellistituzione-del-limite-di-velocita-di-30-allora-a-lecce-citta-danno-appuntamento-a-domenica-3\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/01\/i-promotori-dellistituzione-del-limite-di-velocita-di-30-allora-a-lecce-citta-danno-appuntamento-a-domenica-3\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. ______\u00a0 Domenica 3 marzo alle 11&nbsp;iniziativa per la campagna nazionale itinerante di Clean Cities \u201cCitt\u00e02030: le citt\u00e0 e la sfida del cambiamento\u201d Flash mob in centro per Lecce30 Raccolta di firme per la petizione popolare Un allegro flashmob in centro per raccogliere firme per la campagna Lecce30, sulla&nbsp;petizione popolare&nbsp;per chiedere che&nbsp;Lecce [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":227008,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227007"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=227007"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227007\/revisions"}],"predecessor-version":[{"id":227009,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227007\/revisions\/227009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/227008"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=227007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=227007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=227007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}