{"id":22768,"date":"2013-12-19T15:59:09","date_gmt":"2013-12-19T15:59:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22768"},"modified":"2013-12-19T15:59:09","modified_gmt":"2013-12-19T15:59:09","slug":"i-lavori-del-consiglio-provinciale-odierno","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/19\/i-lavori-del-consiglio-provinciale-odierno\/","title":{"rendered":"I LAVORI DEL CONSIGLIO PROVINCIALE ODIERNO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/provincia-di-lecce.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/provincia-di-lecce-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-22769\" \/><\/a>Oggi \u00e8 tornato a riunirsi, per l\u2019ultima seduta del 2013, il Consiglio Provinciale di Palazzo dei Celestini.<br \/>\nIn apertura di seduta l\u2019assise consiliare, dopo un\u2019ampia discussione di merito, su proposta del presidente della Provincia <strong>Antonio Gabellone<\/strong>, ha deciso all\u2019<strong>unanimit\u00e0<\/strong> di ritirare i <strong>due ordini del giorno<\/strong> proposti dal consigliere <strong>Mario Pendinelli <\/strong>e dal consigliere <strong>Francesco Bruni<\/strong> (dimissionario), illustrato dal consigliere <strong>Roberto Marra<\/strong> (presidente della commissione consiliare Ambiente) relativi ad \u201c<strong>Iniziative per la tutela e difesa della salute pubblica. Sostegno alla registrazione ed analisi dei dati<\/strong>\u201d.<br \/>\nIl presidente <strong>Gabellone<\/strong> nel suo intervento ha fatto presente come \u201cl\u2019importante\u00a0 discussione e confronto avuto in sede di Consiglio assumano dimensioni e contenuti che rappresentano passi in avanti su temi di cos\u00ec stringente attualit\u00e0: quelli della salute e della dignit\u00e0 dei cittadini, che devono essere pi\u00f9 che mai salvaguardati. Il mio invito al Consiglio e alla competente commissione consiliare \u00e8 quello di tornare in sede di valutazioni, per trovare un punto di sintesi delle due istanze presentate, con un nuovo ed unico ordine del giorno in cui ognuno trovi il modo di soddisfare le proprie esigenze e la propria strategia politica\u201d.<br \/>\nIl Consiglio ha poi discusso la <strong>mozione<\/strong> presentata dal consigliere <strong>Adriana Poli Bortone <\/strong>in merito alla <strong>situazione del sistema dei trasporti del Salento, <\/strong>relativamente alla attuale gestione del <strong>Porto di Brindisi<\/strong> che, come si legge nel dispositivo \u201cha prodotto una situazione attuale generata da una gestione poco efficace del Porto\u201d. Con questa mozione, votata all\u2019<strong>unanimit\u00e0<\/strong>, il Consiglio impegna il presidente della Provincia a promuovere un incontro con il Ministro delle Infrastrutture e dei Trasporti per valutare adeguatamente la situazione in termini di ricaduta per il turismo salentino.<br \/>\nSempre all\u2019<strong>unanimit\u00e0<\/strong> \u00e8 stato approvato lo <strong>scioglimento, alla data del 31 dicembre prossimo, del Consorzio per la Tutela, la Valorizzazione e la promozione dell\u2019Artigianato Figulo Salentino<\/strong>, invitando il sindaco di Cutrofiano e i competenti organi del Consorzio, ove lo ritengano, ad operarsi in conseguenza.<br \/>\nContestualmente il Consiglio da indirizzo alla giunta affinch\u00e9, anche attraverso le occorrenti previsioni finanziarie annuali, utilizzi l\u2019importo della quota di partecipazione annuale al Consorzio (<strong>5.150 euro<\/strong>) quale contributo annuale diretto al Comune di Cutrofiano, subordinandolo alle effettive disponibilit\u00e0 di bilancio ed ad una concordata programmazione sugli interventi da mettere in essere. Detto contributo va finalizzato al conseguimento dei seguenti obiettivi: tutelare e valorizzare il prodotto artigianale figulo salentino mediante iniziative di carattere professionale, culturale e formativo; sostenere iniziative di controllo e autoregolamentazione dell\u2019attivit\u00e0 di produzione e commercializzazione del prodotto artigianale figulo salentino; svolgere attivit\u00e0 di marketing e pubbliche relazioni, tendente a supportare il comparto ceramico salentino, specialmente nella sua componente artistico-artigianale, con lo scopo ulteriore di valorizzare il Salento attraverso il suo prodotto ceramico. Il Consiglio, infine, invita il presidente della Provincia ad operarsi affinch\u00e9 anche la Camera di Commercio di Lecce accolga la proposta del Comune di Cutrofiano nei termini accolti dalla Provincia.<br \/>\nApprovata all\u2019<strong>unanimit\u00e0<\/strong> la <strong>bozza di convenzione per il sostegno ed il potenziamento delle attivit\u00e0 del Museo di Biologia Marina <\/strong>\u201c<strong>Pietro Parenzan<\/strong>\u201d. Con questa convezione l\u2019Universit\u00e0 del Salento, la Provincia di Lecce, il Comune di Porto Cesareo e l\u2019Area Marina Protetta \u201cPorto Cesareo\u201d si impegnano a promuovere la cultura del mare e la tutela dello stesso, a valorizzare le collezioni donate dal fondatore Pietro Parenzan all\u2019Universit\u00e0 del Salento, ubicate presso il Museo di Biologia Marina \u201cPietro Parenzan\u201d, nonch\u00e9 a sviluppare la conoscenza e divulgazione dei connessi valori ambientali e culturali mediante la programmazione e realizzazione di azioni comuni in materia. La Provincia di Lecce si impegna, dal suo canto, a contribuire al funzionamento del Museo di Biologia Marina con un impegno finanziario di <strong>5mila euro annui<\/strong>, impegnandosi a collaborare nel reperimento dei fondi e nella realizzazione di progetti con azioni comuni.<br \/>\nInfine, il Consiglio, a <strong>maggioranza<\/strong> (<strong>4 astenuti<\/strong>), ha deliberato l\u2019<strong>adesione <\/strong>al \u201c<strong>Politecnico del Made in Italy<\/strong>\u201d &#8211; scuola di Eccellenza del Calzaturiero, dell\u2019Abbigliamento, della Moda, del Manifatturiero e attivit\u00e0 connesse a tutela del Made in Italy, Societ\u00e0 Consortile a Responsabilit\u00e0 Limitata (S.C.A.R.L.), senza fini di lucro, nell\u2019ambito del Progetto avviato dalle sezioni dell\u2019Abbigliamento e delle Industrie Calzaturiere per la diffusione della formazione d\u2019eccellenza nei settori della moda e dell\u2019intero comparto manifatturiero, approvando la sottoscrizione della quota sociale pari a <strong>2 mila euro<\/strong>.<\/p>\n<p>\u00a0La Societ\u00e0 Consortile \u201cPolitecnico del Made in Italy\u201d, promossa da Confindustria Lecce, ha per oggetto sociale l\u2019istituzione di un\u2019organizzazione per lo sviluppo della formazione professionale tecnico e manageriale di eccellenza, con la certificazione delle competenze, la diffusione della cultura d\u2019impresa, lo sviluppo dell\u2019attivit\u00e0 di ricerca tecnologica, la promozione dell\u2019internalizzazione, controllo della qualit\u00e0 dei materiali, certificazione aziendale, servizi per la sicurezza dell\u2019ambiente di lavoro, per i Settori del Calzaturiero, dell\u2019Abbigliamento, della Moda, Oreficeria, Arredo, design e di tutte le attivit\u00e0 del manifatturiero ed attivit\u00e0 connesse, affini o complementari. Per il raggiungimento dello scopo sociale la Societ\u00e0 offre, tra l\u2019altro, ogni genere di servizi per la formazione professionale dei giovani, la riqualificazione e specializzazione del personale, la formazione ed aggiornamento degli imprenditori, l\u2019organizzazione di attivit\u00e0 formative per i servizi per il lavoro, ovvero formazione per il personale in Cassa Interazione Straordinaria, Ordinaria ed in Deroga. Tutto questo \u00e8 stato favorevolmente accolto dalla Provincia che ha nella formazione professionale uno dei capisaldi della propria attivit\u00e0 istituzionale, con funzioni di coordinamento e di programmazione territoriale nel settore e con interventi mirati all\u2019orientamento e formazione di giovani e adulti non occupati, e all\u2019erogazione di servizi in favore di lavoratori ed aziende.<\/p>\n<p>&nbsp;<\/p>\n<p>Lecce, 19 dicembre 2013<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/19\/i-lavori-del-consiglio-provinciale-odierno\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/19\/i-lavori-del-consiglio-provinciale-odierno\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Oggi \u00e8 tornato a riunirsi, per l\u2019ultima seduta del 2013, il Consiglio Provinciale di Palazzo dei Celestini. In apertura di seduta l\u2019assise consiliare, dopo un\u2019ampia discussione di merito, su proposta del presidente della Provincia Antonio Gabellone, ha deciso all\u2019unanimit\u00e0 di ritirare i due ordini del giorno proposti dal consigliere Mario Pendinelli e dal consigliere Francesco [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22769,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22768"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22768"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22768\/revisions"}],"predecessor-version":[{"id":22771,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22768\/revisions\/22771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/22769"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}