{"id":227709,"date":"2024-03-21T00:02:00","date_gmt":"2024-03-20T23:02:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=227709"},"modified":"2024-03-19T20:34:44","modified_gmt":"2024-03-19T19:34:44","slug":"battiato-lalieno-a-leverano-sabato-23","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/21\/battiato-lalieno-a-leverano-sabato-23\/","title":{"rendered":"\u201cBattiato l\u2019alieno\u201d A LEVERANO SABATO 23"},"content":{"rendered":"\n<p>Riceviamo e volentieri pubblichiamo.\u00a0 _______<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" class=\"wp-image-227710\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/download-1-1.jpg\" alt=\"\"><\/p>\n\n\n\n<p>LEVERANO (LE) &#8211; In occasione del 79\u00b0 anniversario della nascita di Franco Battiato, fa tappa a Leverano il tour europeo di presentazione del libro \u201cBATTIATO L\u2019ALIENO\u201d di Alessio Cantarella e Maurizio Di Bona, edizioni Mimesis, con la prefazione firmata da Syusy Blady. <\/p>\n\n\n\n<p>L\u2019 evento culturale si terr\u00e0 il 23 Marzo 2024 alle ore 18:00 presso la Biblioteca di Comunit\u00e0 \u201cPiazza Coperta \u2013 Leverano Centrale\u201d di Leverano e dialogheranno con l\u2019autore Vincenzo Ferrari, Direttore di TarantoBuonasera ed Umberto Cagnazzo, bibliotecario Libermedia. <\/p>\n\n\n\n<p>Un libro che racconta aneddoti ed amicizie del cantautore siciliano ed impreziosito dalle immagini realizzate dal cartoonist napoletano Maurizio di Bona, che scorrono al di l\u00e0 di spazio e tempo, evidenziandone l\u2019 indole autoironica e divertente, ancora ignorata da tanti. <\/p>\n\n\n\n<p>A riportare Battiato sulla Terra e ricomporre il quadro d\u2019insieme dell\u2019artista, dell\u2019uomo e del Maestro una miriade di ricordi scritti da chi lo ha conosciuto, ha collaborato con lui e gli ha voluto bene: Juri Camisasca, Mario Venuti, Antonella Ruggero, Stefano Pio, Filippo Destrieri, Umberto Broccoli ed altri amici e collaboratori. Una graphic novel che celebra le visioni, la musica, le sperimentazioni, le introspezioni e l\u2019ironia della vita dell\u2019artista, della sua arte e della sua anima ed accompagna il lettore verso \u201cmondi lontanissimi\u201d, ove \u201ctutto \u00e8 ordine e bellezza, calma e volutt\u00e0\u201d. Franco Battiato continua ancora a far smarrire i pensieri dei suoi instancabili ascoltatori con innumerevoli stratagemmi, ammaliandoli e traghettandoli verso nuove aperture, nuove vie che conducono \u201call\u2019essenza delle cose\u201d e seguire cos\u00ec \u201cle scie delle comete come avanguardie di un altro sistema solare!\u201d <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>GLI AUTORI <\/p>\n\n\n\n<p>Alessio Cantarella (1985) \u00e8 un ingegnere informatico catanese, appassionato di arte, cinema, viaggi e lingue. Per Manlio Sgalambro ha curato sito e profili social ed era amico di Franco Battiato, con cui ha collaborato per la realizzazione del film Niente \u00e8 come sembra (2007). <\/p>\n\n\n\n<p>Maurizio Di Bona (1971) \u00e8 un cartoonist napoletano. Ha realizzato Chi ha paura di Giordano Bruno (2006), Cose da Runners (2016), \u00c8 tutto un manga manga (con R. Corradi, 2020) e Supereroi (con R. Corradi, 2022).<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/21\/battiato-lalieno-a-leverano-sabato-23\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/21\/battiato-lalieno-a-leverano-sabato-23\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo.\u00a0 _______ LEVERANO (LE) &#8211; In occasione del 79\u00b0 anniversario della nascita di Franco Battiato, fa tappa a Leverano il tour europeo di presentazione del libro \u201cBATTIATO L\u2019ALIENO\u201d di Alessio Cantarella e Maurizio Di Bona, edizioni Mimesis, con la prefazione firmata da Syusy Blady. L\u2019 evento culturale si terr\u00e0 il 23 Marzo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":227710,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227709"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=227709"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227709\/revisions"}],"predecessor-version":[{"id":227711,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227709\/revisions\/227711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/227710"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=227709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=227709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=227709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}