{"id":227869,"date":"2024-03-24T11:52:50","date_gmt":"2024-03-24T10:52:50","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=227869"},"modified":"2024-03-24T12:00:37","modified_gmt":"2024-03-24T11:00:37","slug":"227869","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/24\/227869\/","title":{"rendered":"INCIDENTE STRADALE MORTALE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"206\" height=\"206\" class=\"wp-image-227872\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/download-4.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/download-4.jpg 206w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/download-4-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/download-4-60x60.jpg 60w\" sizes=\"(max-width: 206px) 100vw, 206px\" \/><\/p>\n\n\n\n<p>(e.l.) ______\u00a0Questa notte sulla provinciale per Sava c\u2018\u00e8 stato un incidente stradale mortale. La vittima \u00e8 Luigi Chetta, 29 anni, di Torricella.<\/p>\n\n\n\n<p>Guidava una Fiat Idea che, per cause ancora da accertare, \u00e8 uscita dalla carreggiata e si \u00e8 schiantata violentemente contro un muro di tufi che in quel tratto delimita la strada.<\/p>\n\n\n\n<p>E\u2018 morto sul colpo.<\/p>\n\n\n\n<p>Indagini dei Carabinieri in corso di svolgimento per accertare dinamica e cause di quanto accaduto.<\/p>\n\n\n\n<p>Tanti messaggi di condivisione del lutto, affetto, incredulit\u00e0 e sgomento si stanno susseguendo in queste ore.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/24\/227869\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/24\/227869\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0Questa notte sulla provinciale per Sava c\u2018\u00e8 stato un incidente stradale mortale. La vittima \u00e8 Luigi Chetta, 29 anni, di Torricella. Guidava una Fiat Idea che, per cause ancora da accertare, \u00e8 uscita dalla carreggiata e si \u00e8 schiantata violentemente contro un muro di tufi che in quel tratto delimita la strada. E\u2018 morto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":227872,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227869"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=227869"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227869\/revisions"}],"predecessor-version":[{"id":227873,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227869\/revisions\/227873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/227872"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=227869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=227869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=227869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}