{"id":227944,"date":"2024-03-26T10:28:00","date_gmt":"2024-03-26T09:28:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=227944"},"modified":"2024-03-26T16:24:42","modified_gmt":"2024-03-26T15:24:42","slug":"aperto-pure-a-pasqua-e-pasquetta-il-marta-di-taranto-invita-a-visitare-accanto-agli-splendori-della-magna-grecia-di-sempre-le-nuove-proposte-della-scuola-napoletana-del-seicento","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/26\/aperto-pure-a-pasqua-e-pasquetta-il-marta-di-taranto-invita-a-visitare-accanto-agli-splendori-della-magna-grecia-di-sempre-le-nuove-proposte-della-scuola-napoletana-del-seicento\/","title":{"rendered":"APERTO PURE A PASQUA E PASQUETTA, IL MARTA DI TARANTO INVITA A VISITARE, ACCANTO AGLI SPLENDORI DELLA MAGNA GRECIA DI SEMPRE, LE NUOVE PROPOSTE APPENA ALLESTITE DELLA SCUOLA NAPOLETANA DEL SEICENTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2092\" height=\"2560\" class=\"wp-image-227946\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/Il-Redentore-di-Andrea-Vaccaro.-Olio-su-tela-XVII-sec-scaled.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/Il-Redentore-di-Andrea-Vaccaro.-Olio-su-tela-XVII-sec-scaled.jpg 2092w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/Il-Redentore-di-Andrea-Vaccaro.-Olio-su-tela-XVII-sec-245x300.jpg 245w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/Il-Redentore-di-Andrea-Vaccaro.-Olio-su-tela-XVII-sec-837x1024.jpg 837w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/Il-Redentore-di-Andrea-Vaccaro.-Olio-su-tela-XVII-sec-768x940.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/Il-Redentore-di-Andrea-Vaccaro.-Olio-su-tela-XVII-sec-1255x1536.jpg 1255w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/Il-Redentore-di-Andrea-Vaccaro.-Olio-su-tela-XVII-sec-1674x2048.jpg 1674w\" sizes=\"(max-width: 2092px) 100vw, 2092px\" \/><\/p>\n\n\n\n<p>(m.b.)&nbsp;_______&nbsp;La domenica di Pasqua e il luned\u00ec di Pasquetta, il Museo Archeologico Nazionale di Taranto schiuder\u00e0 le sue porte al pubblico di visitatori che vorranno passare una giornata di festa all\u2019insegna della cultura e della scoperta.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"275\" height=\"183\" class=\"wp-image-227945\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/images-1.jpg\" alt=\"\"><\/p>\n\n\n\n<p><em>Siamo nella settimana Maggiore tarantina<\/em>&nbsp;\u2013 dice&nbsp;<strong>Stella Falzone, direttrice del MArTA<\/strong>&nbsp;(foto sopra) \u2013&nbsp;<em>e questo appuntamento con i Riti \u00e8 l\u2019occasione che riconette, da sempre, la citt\u00e0 alla propria storia, alla propria identit\u00e0, ma \u00e8 anche il momento dell\u2019anno che richiama sul territorio turisti e visitatori provenienti da altri territori italiani e esteri. Il MArTA aperto nel giorno di Pasqua e nel tradizionale Luned\u00ec dell\u2019Angelo dedicato alle gite e alle esplorazioni \u00e8, dunque, la prosecuzione di questo impegno verso la promozione e valorizzazione degli elementi identitari di una citt\u00e0 che ha voglia di riscatto, e a cui come neo direttrice voglio rivolgere il mio pi\u00f9 sentito augurio di resurrezione.<\/em><\/p>\n\n\n\n<p>Il Museo Archeologico Nazionale di Taranto, in tal senso, proprio in queste settimane \u00e8 un vero e proprio cantiere di nuova progettualit\u00e0 che servir\u00e0 ad ampliare le collezioni di reperti in esposizione, ma anche a riprogrammare servizi e utilities per una sempre migliore fruizione di questo grande patrimonio culturale.<\/p>\n\n\n\n<p>Anche nelle giornate festive, dunque, il Museo tarantino osserver\u00e0 l\u2019orario di apertura dalle 8.30 alle 19.30 (ultimo ingresso alle ore 19.00) per consentire a visitatori e turisti di poter godere delle collezioni permanenti del MArTA e dell\u2019approfondimento offerto al pubblico sulla prestigiosa Collezione Ricciardi.<\/p>\n\n\n\n<p>Alle 10.30, 11.30, 16.30 e 17.30, di domenica e luned\u00ec, nel costo del biglietto di ingresso, sar\u00e0 possibile partecipare all\u2019approfondimento della durata di circa 30 minuti dedicato alle opere a soggetto religioso della Collezione Ricciardi. La visita rivolta ad un massimo di 20 partecipanti, consentir\u00e0 l\u2019esplorazione del piano ammezzato del MArTA, in cui sono custodite le opere rivenienti dalla donazione all\u2019allora Regione Museo di Taranto (1908) dei dipinti della Collezione appertenuta a Mons. Giuseppe Ricciardi.<\/p>\n\n\n\n<p>La collezione comprende un\u2019icona bizantina, ascritta tra la fine del XV e gli inizi del XVI sec, la lastra in zinco recante un\u2019 Addolorata piangente, databile al XVI-XVII sec., le produzioni del senese Rutilio Manetti e quelle di Federico Barrocci e Guido Reni, e molte opere riconducibili alla scuola napoletana di Luca Giordano, Francesco Solimena, Paolo De Matteis e Francesco De Mura. <\/p>\n\n\n\n<p>Della scuola napoletana anche il bellissimo \u201cIl Redentore\u201d (XVII sec.) di Andrea Vaccaro (ella fitifoto di copertina).<\/p>\n\n\n\n<p>L\u2019attivit\u00e0 di approfondimento \u00e8 compresa nel biglietto di ingresso al museo al costo di 10 euro, salvo le gratuit\u00e0 o le riduzioni previste dalla legge e dalle convenzioni. Per prenotare il percorso dedicato alla Collezione Ricciardi si pu\u00f2 chiamare il&nbsp;<strong>centralino<\/strong>&nbsp;del Museo allo&nbsp;<strong>099.4532112<\/strong>.<\/p>\n\n\n\n<p>Nelle stesse giornate \u00e8 possibile prenotare attivit\u00e0 di visita guidata a pagamentoa cura della societ\u00e0&nbsp;<strong>Aditus<\/strong>&nbsp;concessionaria per i servizi aggiuntivi del MArTA. Per l\u2019acquisto dei ticket di ingresso o per l\u2019acquisto di ulteriori visite guidate si pu\u00f2 consultare il sito&nbsp;<a href=\"http:\/\/www.museotaranto.cultura.gov.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.museotaranto.cultura.gov.it<\/a>&nbsp;e accedere all\u2019area \u201c<strong>Biglietteria<\/strong>\u201d.<\/p>\n\n\n\n<p>Museo Archeologico Nazionale di Taranto &#8211; MArTA<br>Via Cavour, 10<br>74123 TARANTO<br>Tel. +39 099 4532112&nbsp;&nbsp; Fax +39 099 4594946<br>E-mail: man-ta.comunicazione@beniculturali.it&lt;mailto:man-ta.comunicazione@beniculturali.it&gt;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/26\/aperto-pure-a-pasqua-e-pasquetta-il-marta-di-taranto-invita-a-visitare-accanto-agli-splendori-della-magna-grecia-di-sempre-le-nuove-proposte-della-scuola-napoletana-del-seicento\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/26\/aperto-pure-a-pasqua-e-pasquetta-il-marta-di-taranto-invita-a-visitare-accanto-agli-splendori-della-magna-grecia-di-sempre-le-nuove-proposte-della-scuola-napoletana-del-seicento\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(m.b.)&nbsp;_______&nbsp;La domenica di Pasqua e il luned\u00ec di Pasquetta, il Museo Archeologico Nazionale di Taranto schiuder\u00e0 le sue porte al pubblico di visitatori che vorranno passare una giornata di festa all\u2019insegna della cultura e della scoperta. Siamo nella settimana Maggiore tarantina&nbsp;\u2013 dice&nbsp;Stella Falzone, direttrice del MArTA&nbsp;(foto sopra) \u2013&nbsp;e questo appuntamento con i Riti \u00e8 l\u2019occasione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":227946,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227944"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=227944"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227944\/revisions"}],"predecessor-version":[{"id":227957,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227944\/revisions\/227957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/227946"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=227944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=227944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=227944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}