{"id":227958,"date":"2024-03-26T17:25:19","date_gmt":"2024-03-26T16:25:19","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=227958"},"modified":"2024-03-26T17:25:46","modified_gmt":"2024-03-26T16:25:46","slug":"incidenti-fra-ultras-a-brindisi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/26\/incidenti-fra-ultras-a-brindisi\/","title":{"rendered":"INCIDENTI FRA ULTRAS A BRINDISI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"540\" class=\"wp-image-227959\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/434075847_806729688155425_2011422610725770758_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/434075847_806729688155425_2011422610725770758_n.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/434075847_806729688155425_2011422610725770758_n-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/03\/434075847_806729688155425_2011422610725770758_n-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n\n\n\n<p>(e.l.) _______ La Polizia di Stato, al termine dell\u2019incontro di calcio Lega Pro Brindisi-Taranto disputatosi domenica scorsa, ha evitato il contatto diretto tra le opposte tifoserie, arrestando tre supporter della compagine jonica e denunciandone cinque, di cui quattro della squadra locale.<\/p>\n\n\n\n<p>Difatti, al termine della partita, conclusasi con la sconfitta del Brindisi, il Responsabile del servizio di ordine pubblico, in linea con le disposizioni del Questore Giampietro Lionetti, ha scortato un gruppo di tifosi ospiti che viaggiava a bordo di una cinquantina di autovetture fino all\u2019uscita della citt\u00e0, garantendo, altres\u00ec, dei presidi nelle aree di maggior transito.&nbsp;<\/p>\n\n\n\n<p>Un primo gruppo di tifosi tarantini superava l\u2019intersezione tra la SS379 e la SS7 senza alcuna conseguenza, mentre il restante corteo, giunto a quella rotatoria, arrestava la marcia creando problemi alla circolazione stradale con lanci di bombe carta e fumogeni.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Lo schieramento delle pattuglie della Questura e del contingente del Reparto Mobile di Taranto \u00e8 stato immediato, consentendo di disperdere i facinorosi.<\/p>\n\n\n\n<p>I poliziotti della DIGOS e dell\u2019UPGSP riuscivano a bloccarne quattro che avevano raggiunto una stazione di servizio poco distante, rinvenendo a bordo del veicolo bombe carta e oggetti atti ad offendere. Tre di essi, gi\u00e0 colpiti da DASPO &#8211; provvedimento amministrativo applicato a soggetti segnalati per aver provocato o partecipato a disordini nel corso di manifestazioni sportive -, venivano arrestati e il quarto deferito in stato di libert\u00e0.<\/p>\n\n\n\n<p>Allo stesso tempo, altre pattuglie della Polizia di Stato, notata la presenza di un gruppo di ultras locali all\u2019inizio di via Appia pronti a scontrarsi con i tifosi jonici, intervenivano immediatamente inducendo i brindisini a disperdersi. Nella circostanza quattro di essi, tra cui un minorenne, sono stati denunciati in stato di libert\u00e0 per oltraggio e resistenza a P.U., per aver insultato e oltraggiato i poliziotti che li avevano trovati in possesso di oggetti utilizzabili come corpi contundenti.<\/p>\n\n\n\n<p>Tutto il materiale rinvenuto \u00e8 stato sottoposto a sequestro da personale della DIGOS che provveder\u00e0, nei prossimi giorni, ad inoltrare alla Divisione Polizia Anticrimine le richieste per l\u2019aggravamento del DASPO per chi ne era gi\u00e0 gravato e l\u2019avvio del procedimento per i restanti denunciati.<\/p>\n\n\n\n<p>Quanto avvenuto nella serata di domenica scorsa non pu\u00f2, di certo, essere ricondotto ai valori dello sport rappresentati <em>in primis<\/em> nel rispetto dell\u2019avversario e nell\u2019accettazione della sconfitta. Peraltro, le stesse famiglie che frequentano lo stadio hanno fortemente stigmatizzato l\u2019accaduto.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/26\/incidenti-fra-ultras-a-brindisi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/03\/26\/incidenti-fra-ultras-a-brindisi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) _______ La Polizia di Stato, al termine dell\u2019incontro di calcio Lega Pro Brindisi-Taranto disputatosi domenica scorsa, ha evitato il contatto diretto tra le opposte tifoserie, arrestando tre supporter della compagine jonica e denunciandone cinque, di cui quattro della squadra locale. Difatti, al termine della partita, conclusasi con la sconfitta del Brindisi, il Responsabile del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":227959,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227958"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=227958"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227958\/revisions"}],"predecessor-version":[{"id":227960,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/227958\/revisions\/227960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/227959"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=227958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=227958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=227958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}