{"id":22804,"date":"2013-12-21T11:52:15","date_gmt":"2013-12-21T11:52:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22804"},"modified":"2013-12-21T11:52:15","modified_gmt":"2013-12-21T11:52:15","slug":"la-poesia-nei-jukebox","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/21\/la-poesia-nei-jukebox\/","title":{"rendered":"LA POESIA NEI JUKEBOX"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><span style=\"font-family: verdana, sans-serif\"><em><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/eva-clesis.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/eva-clesis-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-22805\" \/><\/a>L&#8217;ultima serata ospita, tra gli altri, Elena da Ora, Mery Fiore, Leitmotiv, Le Salentine, Maggiore, Luigi Bruno, Loredana de Vitis, Eva Clesis, Mino Pica. Alle 19.00 Mario Desiati presenter\u00e0 &#8220;Il libro dell&#8217;amore proibito&#8221;. In serata spazio alla tradizione con Brizio Montinaro, Claudio Cavallo Giagnotti, Gianni Amati, un ricordo di Antonio Verri con Rossano Astremo e i fratelli De Santis. In chiusura il concerto del Canzoniere Grecanico Salentino. All\u2019interno della Mediateca sar\u00e0 aperto Il vecchio e il nuovo, mercatino del libro, del disco, del vinile e del fumetto con stand con tutte le novit\u00e0 delle etichette e delle case editrici pugliesi e banchetti dedicati all\u2019usato.<br \/>\n<\/em><\/span><\/p>\n<div><span style=\"font-family: verdana, sans-serif\"><em><br \/>\n<\/em><\/span><\/p>\n<div align=\"justify\"><span style=\"font-family: verdana, sans-serif\"><strong>Domenica 22 dicembre<\/strong>\u00a0negli spazi delle\u00a0<strong>Officine Cantelmo di Lecce<\/strong>\u00a0si conclude \u201c<strong>La poesia nei jukebox<\/strong>\u201c, una tre giorni ad ingresso gratuito dedicata alla musica e ai libri con oltre 30 incontri, presentazioni di libri, cd e dvd, concerti, mostre, workshop, reading e un mercatino dedicato alle case editrici e alle etichette pugliesi.<strong><\/p>\n<p><\/strong><strong>Dalle 10 alle 20<\/strong>\u00a0all\u2019interno della\u00a0<strong>Mediateca<\/strong>\u00a0sar\u00e0 aperto\u00a0<strong>Il vecchio e il nuovo, mercatino del libro, del disco, del vinile e del fumetto<\/strong>\u00a0con stand con tutte le novit\u00e0 delle etichette e delle case editrici pugliesi e banchetti dedicati all\u2019usato. Natale si avvicina e molti sono indecisi sui regali da fare. Un libro, un cd, un vecchio vinile, un fumetto sono sempre un\u2019ottima idea. Dalle 11 alle 13 e dalle 16 alle 20 nuovi incontri e showcase con\u00a0<strong>Elena da Ora<\/strong>,\u00a0<strong>Mery Fiore<\/strong>,\u00a0<strong>Leitmotiv<\/strong>\u00a0e la presentazione delle carte\u00a0<strong>Le Salentine<\/strong>, che chiude la mattinata. Nel pomeriggio spazio ai cantautori\u00a0<strong>Maggiore<\/strong>,\u00a0<strong>Molla<\/strong>e\u00a0<strong>Luigi Bruno<\/strong>\u00a0e agli scrittori e scrittrici\u00a0<strong>Loredana De Vitis<\/strong>\u00a0\u2013 \u201cStorie d\u2019amore inventato\u201d (Editrice 20090),\u00a0<strong>Eva Clesis<\/strong>\u00a0\u2013 \u201cParole Sante\u201d &#8211;\u00a0\u00a0(Perdisa editore),\u00a0<strong>Mino Pica<\/strong>\u00a0\u2013 \u201cHotel\u201d (Lupo editore). Alle 19 appuntamento con\u00a0<strong>Mario Desiati<\/strong>, che presenter\u00e0 \u201cIl libro dell\u2019amore proibito\u201d, uscito poche settimane fa per Mondadori affiancato da\u00a0<strong>Simona Toma<\/strong>. \u201cL\u2019amore per crescere ha bisogno di muri, proprio come l\u2019edera\u201d. Nonna Comasia ha insegnato questo a Francesco, detto Veleno, e lui lo ricorda ogni giorno. Timido e solitario, fino ai quattordici anni \u00e8 vissuto immaginando vite eroiche e ammirando i coetanei pi\u00f9 intraprendenti. Il suo universo quotidiano, nel paese pugliese dove vive, \u00e8 quello della scuola, con regole e muri che sembrano fatti per essere invalicabili, non certo per nascondere gioie proibite. Fino all\u2019incontro con Donatella Telesca, professoressa di Educazione tecnica.<\/span><\/div>\n<div align=\"justify\"><span style=\"font-family: verdana, sans-serif\"><br \/>\n<\/span><span style=\"font-family: verdana, sans-serif\">Nella sala delle Cantelmo la serata, a cura di Vincenzo Santoro, si apre invece alle 18.00 con la proiezione di \u201c<strong>Sente la voce mia, la riconosce<\/strong>\u201c, tre documentari di Marcello Fersini, Roberto Inciocchi e Luis Padilla, a seguire spazio all\u2019incontro Il tamburello nelle tradizioni musicali salentine e spagnole con la presentazione della rivista \u201c<strong>Melissi \u2013 Le culture popolari<\/strong>\u201d (Besa) e del volume\u00a0<strong>\u201cLa pandereta. Suoni e identit\u00e0 della Cantabria<\/strong>\u201d di Grazia Tuzi (Note). All\u2019incontro, che sar\u00e0 coordinato da\u00a0<strong>Sergio Torsello<\/strong>, interverranno anche\u00a0<strong>Gianni Amati<\/strong>,\u00a0<strong>Claudio \u201cCavallo\u201d Giagnotti<\/strong>\u00a0e\u00a0<strong>Vincenzo Santoro<\/strong>. Subito dopo (ore 20) l\u2019appuntamento \u00e8 con la presentazione del periodico della fondazione\u00a0<strong>Terra D\u2019Otranto<\/strong>\u00a0e l\u2019esibizione del gruppo di musica etnica popolare\u00a0<strong>Petrameridie<\/strong>. Interverr\u00e0\u00a0<strong>Brizio Montinaro<\/strong>\u00a0che parler\u00e0 anche delle sue ultime ricerche sul tarantismo. Alle 21.00 la manifestazione ricorder\u00e0\u00a0<strong>Antonio Verri, a 20 anni dalla scomparsa del poeta salentino<\/strong>. Dopo la presentazione del volume \u201cCon gli occhi al cielo aspetto la neve\u201d di\u00a0<strong>Rossano Astremo<\/strong>\u00a0(Manni) spazio al reading-concerto con\u00a0<strong>Rocco e Gianni De Santis<\/strong>\u00a0dal titolo \u201c<strong>Il pane sotto la neve, il vento sotto la paglia<\/strong>\u201c. La tre giorni si chiuder\u00e0 alle 22.30 con uno speciale concerto \u201cnatalizio\u201d del\u00a0<strong>Canzoniere Grecanico Salentino<\/strong>. Fondato nel 1975 dalla scrittrice Rina Durante, \u00e8 il pi\u00f9 importante gruppo di musica popolare salentina, il primo ad essersi formato in Puglia. L\u2019affascinante dicotomia tra tradizione e modernit\u00e0 caratterizza la musica del CGS: il gruppo \u00e8 composto dai principali protagonisti dell\u2019attuale scena pugliese, che reinterpretano in chiave moderna le tradizioni che ruotano attorno alla celebre pizzica tarantata rituale, che aveva il potere di curare attraverso la musica, la trance e la danza il morso della leggendaria Taranta. Gli spettacoli del CGS sono un\u2019esplosione di energia, passione, ritmo e magia, che trascinano in un viaggio dal passato al presente sul battito del tamburello, cuore pulsante della tradizione salentina. Guidato dal tamburellista e violinista Mauro Durante, che ha ereditato la leadership dal padre Daniele nel 2007, il CGS continua a innovare e a rappresentare la musica italiana nel mondo, collaborando con artisti del calibro di Ludovico Einaudi, Piers Faccini, Ballake Sissoko, Ibrahim Maalouf, Fanfara Tirana, Stewart Copeland dei Police, e portando la voce di un territorio musicale che con la pizzica ha sempre manifestato la propria identit\u00e0.<\/span><\/p>\n<p><span style=\"font-family: verdana, sans-serif\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-family: verdana, sans-serif\">Nella mediateca prosegue l&#8217;allestimento di \u201c<strong>Fotografia in musica<\/strong>\u201d, mostra fotografica a cura di ShotALive. Una serie di ritratti e momenti salienti di live ed eventi musicali nazionali e internazionali fotografati da ShotALive nel corso dell&#8217;ultimo anno e stampati a colori su tele 90&#215;60 cm. Le Cantelmo ospiteranno anche una mostra di foto storiche sul tamburello nella Puglia meridionale e un&#8217;esposizione di tamburelli artigianali a cura di Gianni Amati.Gli interventi luminosi saranno a cura di\u00a0<strong>Scie Urbane<\/strong>, un collettivo di designer dedicato a sperimentare e promuovere soluzioni per rendere pi\u00f9 ergonomica e sociale la citt\u00e0, attraverso workshop, azioni sul campo, sviluppo di progetti, di spazio e prodotto, mobilitazione.<\/p>\n<p>L\u2019appuntamento \u00e8 organizzato dal\u00a0<strong>Comune di Lecce<\/strong>\u00a0in collaborazione con\u00a0<strong>FolkBooks\u00a0<\/strong>e\u00a0<strong>Cepell<\/strong>\u00a0\u2013 Centro per il libro e la lettura del ministero per i beni e le attivit\u00e0 culturali, nell\u2019ambito dei progetti\u00a0<strong>Officine della Musica<\/strong>, promosso dall\u2019Assessorato alle politiche giovanili del Comune di Lecce in collaborazione con Officine Cantelmo e Coolclub con il sostegno di\u00a0<strong>Puglia Sounds<\/strong>, e \u201c<strong>Lecce Legge<\/strong>\u201d, a cura dell\u2019Assessorato alla Pubblica Istruzione. L\u2019evento \u00e8 a sostegno della candidatura di Lecce a\u00a0<strong>Capitale della Cultura 2019<\/strong>.\u00a0<\/span><\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/21\/la-poesia-nei-jukebox\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/21\/la-poesia-nei-jukebox\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>L&#8217;ultima serata ospita, tra gli altri, Elena da Ora, Mery Fiore, Leitmotiv, Le Salentine, Maggiore, Luigi Bruno, Loredana de Vitis, Eva Clesis, Mino Pica. Alle 19.00 Mario Desiati presenter\u00e0 &#8220;Il libro dell&#8217;amore proibito&#8221;. In serata spazio alla tradizione con Brizio Montinaro, Claudio Cavallo Giagnotti, Gianni Amati, un ricordo di Antonio Verri con Rossano Astremo e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22805,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22804"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22804"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22804\/revisions"}],"predecessor-version":[{"id":22806,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22804\/revisions\/22806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/22805"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}