{"id":228295,"date":"2024-04-05T13:26:57","date_gmt":"2024-04-05T11:26:57","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=228295"},"modified":"2024-04-05T13:38:47","modified_gmt":"2024-04-05T11:38:47","slug":"spettacolo-di-teatro-per-ragazzi-a-giuggianello-sabato-13","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/05\/spettacolo-di-teatro-per-ragazzi-a-giuggianello-sabato-13\/","title":{"rendered":"SPETTACOLO DI TEATRO PER RAGAZZI A GIUGGIANELLO SABATO 13"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"634\" class=\"wp-image-228296\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/renato-grilli-e-rocco-nigro-2.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/renato-grilli-e-rocco-nigro-2.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/renato-grilli-e-rocco-nigro-2-300x198.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/renato-grilli-e-rocco-nigro-2-768x507.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n\n\n\n<p>(r.p.) _______ Una intrigante rappresentazione, che coinvolge tutto il pubblico e si fa applaudire, \u00e8 in programma\u00a0il 13 aprile\u00a0 a Giuggianello, dove ritorna la stagione di teatro ragazzi itinerante KLAPP il teatro \u00e8 dei ragazzi, con Operetta di Schlemil, spettacolo per ragazzi di e con Renato Grilli, presso la Sala consiliare del Comune (sipario ore 18.00).\u00a0 Per la stagione sono programmati otto spettacoli, da febbraio a maggio, nei tre comuni partner di progetto, Alezio Giuggianello e Galatone, che vedranno in scena cinque compagnie per differenti linguaggi teatrali, teatro di figura, teatro di narrazione e musica.<\/p>\n\n\n\n<p>Questo spettacolo, in particolare,&nbsp; \u00e8 ispirato all\u2019operetta popolare, dove tra scena e platea, tra attori e pubblico non c\u2019\u00e8 gran distinzione, n\u00e9 separazione netta tra chi dice e chi ascolta. Melodie e canzoni, poesie e storielle sono spesso note a tutti, sono patrimonio comune e festosa occasione di condivisione. E chi non le conosce le pu\u00f2 imparare subito, tanto facili sono da imparare\u2026<\/p>\n\n\n\n<p>Lo svolgersi dello spettacolo comincia con il Direttore della Compagnia dell\u2019Operetta di Chelm che si scusa con il pubblico in sala, ma purtroppo l\u2019annunciato spettacolo \u201cOperetta di Schlemil\u201d non potr\u00e0 andare in scena: i suoi attori e i suoi musicisti, i cantanti e le ballerine, le sarte ed attrezzisti non ce l&#8217;hanno fatta ad arrivare. Il loro bel pulmino ha avuto un grave guasto durante il viaggio. E tutti gli artisti se ne sono dovuti tornare a casa. Ma il Direttore della Compagnia, il Doktor Krik, e il Primo Musicista, Maestro Krok, hanno promesso di tornare &#8211; appena sar\u00e0 possibile &#8211; per rappresentare la loro \u201cOperetta di Schlemil\u201d. A meno che invece, tra il pubblico, non ci siano per caso degli \u201cartisti\u201d? Cantanti e cantanti, ballerine e ballerini, attrici e attori, pronti a prendere il posto di quelli che mancano e fare la loro parte\u2026<\/p>\n\n\n\n<p>E qui comincia il vero e proprio spettacolo, ideato e realizzato da Rocco Nigro e Renato Grilli&nbsp;(nella foto)  che hanno cominciato a collaborare alla creazione di spettacoli e recital quasi venti anni fa. Tra le idee e i progetti comuni, il primo &#8211; e il pi\u00f9 duraturo &#8211; \u00e8 stato intorno a quel miracolo culturale che \u00e8 stata la Musica Klezmer. Melodie e danze sempre sospese tra tragedia e farsa, tra profano e sacro, tra eroico e ridicolo, motivi cos\u00ec semplici e orecchiabili da farsi riconoscere al primo ascolto.<\/p>\n\n\n\n<p>La stagione KLAPP il teatro \u00e8 dei ragazzi fa parte del pi\u00f9 ampio progetto Keep Love in Your (He)Art, ideato dall\u2019associazione Tracce Creative nell\u2019ambito dell\u2019Avviso pubblico \u2018Puglia Capitale Sociale 3.0\u2019 indetto dalla Regione Puglia, e vede la partecipazione ed il sostegno dei Comuni di Alezio, Galatone, Giuggianello e Ortelle. Le attivit\u00e0 prevedono inoltre percorsi laboratoriali educativo-formativi in ambito artistico-espressivo e di educazione alla cittadinanza per bambini e ragazzi di et\u00e0 compresa tra i 6 e 17 anni (laboratorio teatrale, circo, fumetto, musicale, artistico, d\u2019archeologia e valorizzazione dei beni culturali e storico-artistici). Saranno inoltre organizzate escursioni itineranti per conoscere il patrimonio culturale locale. I ragazzi saranno accompagnati da esperti in passeggiate per conoscere o riscoprire i dettagli colmi di bellezza delle evidenze storico artistiche del territorio.<\/p>\n\n\n\n<p>PORTA 17.30 &#8211; SIPARIO 18.00<\/p>\n\n\n\n<p><em>Ingresso gratuito<\/em><\/p>\n\n\n\n<p><em>Info e Prenotazioni:<\/em><\/p>\n\n\n\n<p>Prenotazione telefonica obbligatoria al 3297155894, anche con WhatsApp.<\/p>\n\n\n\n<p>SALA POLIVALENTE COMUNALE, Piazza degli Eroi, Giuggianello<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/05\/spettacolo-di-teatro-per-ragazzi-a-giuggianello-sabato-13\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/05\/spettacolo-di-teatro-per-ragazzi-a-giuggianello-sabato-13\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(r.p.) _______ Una intrigante rappresentazione, che coinvolge tutto il pubblico e si fa applaudire, \u00e8 in programma\u00a0il 13 aprile\u00a0 a Giuggianello, dove ritorna la stagione di teatro ragazzi itinerante KLAPP il teatro \u00e8 dei ragazzi, con Operetta di Schlemil, spettacolo per ragazzi di e con Renato Grilli, presso la Sala consiliare del Comune (sipario ore [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":228296,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228295"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=228295"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228295\/revisions"}],"predecessor-version":[{"id":228301,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228295\/revisions\/228301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/228296"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=228295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=228295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=228295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}