{"id":228439,"date":"2024-04-08T16:25:03","date_gmt":"2024-04-08T14:25:03","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=228439"},"modified":"2024-04-08T16:25:06","modified_gmt":"2024-04-08T14:25:06","slug":"fronte-verde-nella-lista-liberta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/08\/fronte-verde-nella-lista-liberta\/","title":{"rendered":"FRONTE VERDE NELLA LISTA Liberta\u2019"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1520\" height=\"720\" class=\"wp-image-228440\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/fronte-verde-liberta.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/fronte-verde-liberta.jpg 1520w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/fronte-verde-liberta-300x142.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/fronte-verde-liberta-1024x485.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/fronte-verde-liberta-768x364.jpg 768w\" sizes=\"(max-width: 1520px) 100vw, 1520px\" \/>Da  Alberto Crapanzano di Fronte Verde riceviamo e volentieri pubblichiamo. _______ <\/p>\n\n\n\n<p><strong>ELEZIONI EUROPEE 2024.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <\/strong><\/p>\n\n\n\n<p><strong>Alleanza politica tra Fronte Verde e la lista Libert\u00e0.<\/strong><\/p>\n\n\n\n<p>Si \u00e8 svolta a Roma sabato 6 aprile al Teatro Quirino stracolmo con pi\u00f9 di mille partecipanti l\u2019inizio della campagna elettorale della lista \u201cLibert\u00e0\u201d della quale ne fa parte anche il movimento ecologista \u201cFronte Verde\u201d, la cui adesione era stata ufficializzata in conferenza stampa presso l\u2019Hotel Nazionale a Piazza Montecitorio; in merito con un suo intervento Vincenzo Galizia Presidente Nazionale del movimento ecologista ha dichiarato alla stampa presente: \u201cSiamo molto felici di fare parte di questa coalizione che sar\u00e0 la vera novit\u00e0 politica di queste elezioni europee 2024, siamo certi che con l&#8217;on. Cateno De Luca, l&#8217;on. Laura Castelli e tutti gli altri partners della lista Libert\u00e0 riusciremo a realizzare un risultato storico e noi saremo l\u2019anima verde e sociale della coalizione\u201d.<\/p>\n\n\n\n<p>Le prossime conferenze stampa saranno Marted\u00ec 16 Aprile ore 16,00 a Palermo presso il Palazzo dei Normanni, Sala Rossa, Piazza del Parlamento 1; Mercoled\u00ec 17 Aprile ore 10,30 a Milano presso l\u2019Hotel dei Cavalieri, Sala Carmagnola, Piazza Giuseppe Missori 1; Gioved\u00ec 18 Aprile ore 11,00 a Roma presso il Teatro Quirino, Via delle Vergini 7; Venerd\u00ec 19 Aprile ore 16,00 a Napoli presso l\u2019Hotel Ramada, Via Galileo Ferraris 40; Sabato 20 Aprile ore 12,00 a Verona presso il Ristorante Liston 12, Piazza Bra 12.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"225\" class=\"wp-image-228441\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/logo-liberta.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/logo-liberta.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/logo-liberta-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/logo-liberta-60x60.jpg 60w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/08\/fronte-verde-nella-lista-liberta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/08\/fronte-verde-nella-lista-liberta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Da Alberto Crapanzano di Fronte Verde riceviamo e volentieri pubblichiamo. _______ ELEZIONI EUROPEE 2024.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228439"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=228439"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228439\/revisions"}],"predecessor-version":[{"id":228442,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228439\/revisions\/228442"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=228439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=228439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=228439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}