{"id":22849,"date":"2013-12-22T15:17:50","date_gmt":"2013-12-22T15:17:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22849"},"modified":"2013-12-22T15:17:50","modified_gmt":"2013-12-22T15:17:50","slug":"ancora-attentati-in-citta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/22\/ancora-attentati-in-citta\/","title":{"rendered":"ANCORA ATTENTATI IN CITTA&#8217;"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/incendio-furgone.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/incendio-furgone-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-22850\" \/><\/a>Il Vice-Presidente vicario del Gruppo PDL\/FI alla Regione Puglia Erio Congedo ha diffuso la seguente nota:<\/p>\n<p>si allunga la scia di attentati incendiari, spaccate, bombe, colpi di pistola, furti in Citt\u00e0. Episodi che non devono creare allarmismi esagerati, ma nemmeno atteggiamenti di sottovalutazione o di assuefazione da parte di chicchessia.<\/p>\n<p>Magistratura e forze dell&#8217;ordine hanno svolto in questi anni un lavoro encomiabile che ha prodotto risultati importanti nel contrasto all&#8217;illegalit\u00e0, e sono certo che sapranno fronteggiare adeguatamente questa recrudescenza della criminalit\u00e0, facendo chiarezza sugli episodi e assicurando i responsabili alla giustizia. Saranno i fatti la risposta pi\u00f9 efficace alla preoccupazione dei cittadini e alle insidie alla pacifica e civile convivenza a Lecce e nel Salento.<\/p>\n<p>L&#8217;occasione \u00e8 propizia per formulare gli auguri di buon lavoro ad Antonio Maiorano, neo questore della provincia di Lecce.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/22\/ancora-attentati-in-citta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/22\/ancora-attentati-in-citta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il Vice-Presidente vicario del Gruppo PDL\/FI alla Regione Puglia Erio Congedo ha diffuso la seguente nota: si allunga la scia di attentati incendiari, spaccate, bombe, colpi di pistola, furti in Citt\u00e0. Episodi che non devono creare allarmismi esagerati, ma nemmeno atteggiamenti di sottovalutazione o di assuefazione da parte di chicchessia. Magistratura e forze dell&#8217;ordine hanno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22850,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22849"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22849"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22849\/revisions"}],"predecessor-version":[{"id":22852,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22849\/revisions\/22852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/22850"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}