{"id":228555,"date":"2024-04-11T17:05:33","date_gmt":"2024-04-11T15:05:33","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=228555"},"modified":"2024-04-11T17:07:04","modified_gmt":"2024-04-11T15:07:04","slug":"la-piaga-della-droga-che-continua-a-rovinare-tanti-giovani-e-le-loro-famiglie-arrestato-a-lecce-citta-spacciatore-minorenne-ora-e-in-comnita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/11\/la-piaga-della-droga-che-continua-a-rovinare-tanti-giovani-e-le-loro-famiglie-arrestato-a-lecce-citta-spacciatore-minorenne-ora-e-in-comnita\/","title":{"rendered":"LA PIAGA DELLA DROGA CHE CONTINUA A ROVINARE TANTI GIOVANI E LE LORO FAMIGLIE.\u00a0ARRESTATO A LECCE CITTA\u2019 UNO SPACCIATORE MINORENNE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"850\" height=\"510\" class=\"wp-image-228557\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/sevv.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/sevv.jpg 850w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/sevv-300x180.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/sevv-768x461.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/p>\n\n\n\n<p>(Rdl) _______\u00a0 Preoccupa, messo in risalto dalla cronaca nera degli ultimi mesi, il crescente coinvolgimento  di minori a Lecce citt\u00e0 nei traffici di droga, che continua a rovinare tanti giovani e le loro famiglie. Da tossicodipendenti, a spacciatori, a criminali, \u00e8 un attimo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Questa notte, la sezione volanti della Questura di Lecce\u00a0ha arrestato in flagranza di reato un minore, perch\u00e9 ritenuto responsabile del reato di detenzione illecita di sostanze stupefacenti, nonch\u00e9 lo ha denunciato a piede libero per il reato di resistenza a pubblico ufficiale.<\/p>\n\n\n\n<p>Verso le 23.30,\u00a0 i poliziotti durante un servizio di controllo del territorio, notavano un gruppetto di cinque giovani avventori tra cui il minore, , tutti volti gi\u00e0 noti,intenti a consumare bevande nei pressi di un bar.<\/p>\n\n\n\n<p>Il ragazzo manifestava chiari segni di insofferenza e cercando pi\u00f9 volte di allontanarsi. Tale atteggiamento ha ulteriormente insospettito gli agenti che hanno deciso di procedere ad un controllo pi\u00f9 accurato. Il giovane  per\u00f2, all\u2019invito di avvicinarsi all\u2019autovettura di servizio, opponeva resistenza. <\/p>\n\n\n\n<p>I poliziotti riuscivano a convincerlo ad entrare nel veicolo e, alla richiesta se occultasse addosso oggetti o altro, il fermato estraeva dagli slip una bustina trasparente contenente undici pezzi di sostanza solida di colore marrone, singolarmente avvolti in cellophane trasparente, risultata poi essere sostanza stupefacente del tipo hashish, per un peso complessivo di circa venti grammi.<\/p>\n\n\n\n<p>Il pm di turno della Procura delle Repubblica presso il Tribunale per i Minori (nella foto) ha disposto la sua collocazione in una comunit\u00e0.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/11\/la-piaga-della-droga-che-continua-a-rovinare-tanti-giovani-e-le-loro-famiglie-arrestato-a-lecce-citta-spacciatore-minorenne-ora-e-in-comnita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/11\/la-piaga-della-droga-che-continua-a-rovinare-tanti-giovani-e-le-loro-famiglie-arrestato-a-lecce-citta-spacciatore-minorenne-ora-e-in-comnita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) _______\u00a0 Preoccupa, messo in risalto dalla cronaca nera degli ultimi mesi, il crescente coinvolgimento di minori a Lecce citt\u00e0 nei traffici di droga, che continua a rovinare tanti giovani e le loro famiglie. Da tossicodipendenti, a spacciatori, a criminali, \u00e8 un attimo. Questa notte, la sezione volanti della Questura di Lecce\u00a0ha arrestato in flagranza [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":228557,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228555"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=228555"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228555\/revisions"}],"predecessor-version":[{"id":228559,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228555\/revisions\/228559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/228557"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=228555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=228555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=228555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}