{"id":228776,"date":"2024-04-18T15:46:38","date_gmt":"2024-04-18T13:46:38","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=228776"},"modified":"2024-04-24T19:10:33","modified_gmt":"2024-04-24T17:10:33","slug":"appello-di-primula-meo-che-chiede-aiuto-per-la-nuova-ambulanza-veterinaria","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/18\/appello-di-primula-meo-che-chiede-aiuto-per-la-nuova-ambulanza-veterinaria\/","title":{"rendered":"APPELLO DI PRIMULA MEO DI \u201cTutela Ambiente e Animali\u201d\u00a0CHE\u00a0CHIEDE AIUTO PER LA NUOVA AMBULANZA VETERINARIA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1536\" height=\"2048\" class=\"wp-image-228777\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/Una-randagia-di-Lecce.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/Una-randagia-di-Lecce.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/Una-randagia-di-Lecce-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/Una-randagia-di-Lecce-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/Una-randagia-di-Lecce-1152x1536.jpg 1152w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo.&nbsp; _______&nbsp;&nbsp;<\/p>\n\n\n\n<p>SOCCORSO ANIMALI IN DIFFICOLTA\u2019, SERVE ANCORA AIUTO PER LA NUOVA AMBULANZA VETERINARIA<\/p>\n\n\n\n<p>Molti amici degli animali hanno gi\u00e0 donato, ma non \u00e8 bastato: i volontari dell\u2019associazione \u201cTutela Ambiente e Animali &#8211; Protezione Civile di Lecce Odv\u201d hanno ancora bisogno del nostro aiuto. Perch\u00e9 la nuova ambulanza veterinaria deputata al soccorso degli animali in difficolt\u00e0 \u00e8 arrivata. Ma i soldi finora raccolti grazie alla piattaforma gofundme.com sono bastati solo per l\u2019acconto del mezzo: poi toccher\u00e0 pagare le rate per la somma mancante.<\/p>\n\n\n\n<p>Cos\u00ec gli amici dell\u2019associazione, che effettua centinaia di interventi ogni anno, sperano ancora nell\u2019aiuto degli amanti degli animali, che per fortuna sono tanti e generosi: \u201cChiediamo a tutti voi che avete gi\u00e0 donato di diffondere e condividere la nostra raccolta fondi per aiutarci a pagare le rate e non trovarci in difficolt\u00e0\u201d: lancia un accorato appello la presidente dell\u2019associazione, Primula Meo. \u201cChiunque abbia voglia di sposare la causa e aiutare i volontari leccesi a raggiungere l&#8217;obiettivo pu\u00f2 farlo collegandosi al seguente link: <a href=\"https:\/\/gofund.me\/4b6fa26b2\">https:\/\/gofund.me\/4b6fa26b2<\/a> \u201d.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/18\/appello-di-primula-meo-che-chiede-aiuto-per-la-nuova-ambulanza-veterinaria\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/18\/appello-di-primula-meo-che-chiede-aiuto-per-la-nuova-ambulanza-veterinaria\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo.&nbsp; _______&nbsp;&nbsp; SOCCORSO ANIMALI IN DIFFICOLTA\u2019, SERVE ANCORA AIUTO PER LA NUOVA AMBULANZA VETERINARIA Molti amici degli animali hanno gi\u00e0 donato, ma non \u00e8 bastato: i volontari dell\u2019associazione \u201cTutela Ambiente e Animali &#8211; Protezione Civile di Lecce Odv\u201d hanno ancora bisogno del nostro aiuto. Perch\u00e9 la nuova ambulanza veterinaria deputata al soccorso [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":228777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228776"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=228776"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228776\/revisions"}],"predecessor-version":[{"id":228779,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/228776\/revisions\/228779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/228777"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=228776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=228776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=228776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}