{"id":229104,"date":"2024-04-29T12:37:37","date_gmt":"2024-04-29T10:37:37","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=229104"},"modified":"2024-04-29T12:37:40","modified_gmt":"2024-04-29T10:37:40","slug":"il-brutto-uccide","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/29\/il-brutto-uccide\/","title":{"rendered":"\u00a0\u201cIl brutto uccide\u201c"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"482\" class=\"wp-image-229105\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/06c51de91a02f88add5b2d654f4816f2.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/06c51de91a02f88add5b2d654f4816f2.jpg 700w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/04\/06c51de91a02f88add5b2d654f4816f2-300x207.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. L\u2019architetto Luca Fiocca ci scrive\u00a0______\u00a0<\/p>\n\n\n\n<p>Quando si \u00e8 cominciato a discutere della sostituzione della statua di Sant&#8217;Oronzo, correva l&#8217;anno 2019, contattavo Vittorio Sgarbi, che nell&#8217;occasione mi rassicurava perch\u00e9, a suo dire, si possono realizzare delle copie fedeli all&#8217;originale in vetroresina.<\/p>\n\n\n\n<p>Poi cos\u00ec non \u00e8 avvenuto, in quanto la nuova statua \u00e8 difforme, e lo ha anche ammesso il consulente tecnico nominato dal comune di Lecce, tale prof. Raffaele Casciaro.<\/p>\n\n\n\n<p>Chiss\u00e0 oggi Vittorio Sgarbi cosa direbbe a riguardo, mettendo a confronto le due statue?<\/p>\n\n\n\n<p>\u00c8 probabile che esclamerebbe la sua fatidica paroletta magica, che per gli addetti ai lavori, \u00e8 quanto di pi\u00f9 esplicito e significativo, si possa immaginare&#8230;<\/p>\n\n\n\n<p>La Citt\u00e0 di Lecce non \u00e8 comunque nuova ad annoverare disastri quando si presta un po&#8217; d&#8217;attenzione alle pratiche concernenti il recupero del patrimonio storico.<\/p>\n\n\n\n<p>Negli anni Settanta, \u00e8 riuscita a sgrattare la patina dalla meravigliosa statua bronzea del Cristo Risorto di Maccagnani presente nel cimitero, per poi verniciarla a smalto!<\/p>\n\n\n\n<p>Per dirla ancora una volta alla maniera di Sgarbi, &#8216;il brutto uccide&#8217;&#8230;<\/p>\n\n\n\n<p>Luca Fiocca<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/29\/il-brutto-uccide\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/04\/29\/il-brutto-uccide\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. L\u2019architetto Luca Fiocca ci scrive\u00a0______\u00a0 Quando si \u00e8 cominciato a discutere della sostituzione della statua di Sant&#8217;Oronzo, correva l&#8217;anno 2019, contattavo Vittorio Sgarbi, che nell&#8217;occasione mi rassicurava perch\u00e9, a suo dire, si possono realizzare delle copie fedeli all&#8217;originale in vetroresina. Poi cos\u00ec non \u00e8 avvenuto, in quanto la nuova statua \u00e8 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":229105,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229104"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=229104"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229104\/revisions"}],"predecessor-version":[{"id":229106,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229104\/revisions\/229106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/229105"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=229104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=229104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=229104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}