{"id":229265,"date":"2024-05-04T13:54:08","date_gmt":"2024-05-04T11:54:08","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=229265"},"modified":"2024-05-04T13:54:11","modified_gmt":"2024-05-04T11:54:11","slug":"il-lecce-a-cagliari-cerca-la-salvezza-matematica-si-gioca-domenica-5-ore-12-30-ecco-una-sintesi-delle-dichiarazioni-di-luca-gotti-nella-conferenza-stampa-della-vigilia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/04\/il-lecce-a-cagliari-cerca-la-salvezza-matematica-si-gioca-domenica-5-ore-12-30-ecco-una-sintesi-delle-dichiarazioni-di-luca-gotti-nella-conferenza-stampa-della-vigilia\/","title":{"rendered":"IL LECCE A CAGLIARI CERCA LA SALVEZZA MATEMATICA. SI GIOCA DOMENICA 5\u00a0ORE 12.30. ECCO UNA SINTESI DELLE DICHIARAZIONI DI LUCA GOTTI NELLA CONFERENZA STAMPA DELLA VIGILIA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"250\" height=\"201\" class=\"wp-image-229266\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/download.jpg\" alt=\"\">(Rdl) ______\u00a0 <\/p>\n\n\n\n<p>\u201cDiciamo che il Lecce forse \u00e8 gi\u00e0 salvo, probabilmente \u00e8 gi\u00e0 salvo, io penso che possa essere gi\u00e0 salvo. Ma la realt\u00e0 \u00e8 che oggi non lo \u00e8, lo dice la matematica. \u00c8 l\u2019unico modo giusto di vedere le cose&#8230;<\/p>\n\n\n\n<p>Si tratta di uno scontro diretto, le giornate diminuiscono, qesta e altre tre. Il Cagliari, come noi, andr\u00e0 alla ricerca di punti decisivi, in un contesto ambientale vicino alla squadra cos\u00ec come il nostro&#8230;.<\/p>\n\n\n\n<p>La partita di domani secondo me non sar\u00e0 tattica. Domani si va oltre l\u2019aspetto tattico, sar\u00e0 una gara molto di atteggiamento. Il Cagliari \u00e8 una squadra un po\u2019 britannica, intesa. Ci saranno dei canoni tattici precisi, so che succederanno delle cose, ma non sar\u00e0 una questione di preparazione minuziosa&#8230;<\/p>\n\n\n\n<p>Mi fanno piacere i complimenti rivoltimi da Ranieri.<br>Il Lecce visto in queste partite credo gli piaccia davvero, conoscendolo. Ranieri sa perfettamente come contrastare il Lecce, parliamo di un maestro. Nella sua carriera ha accettato sfide. \u00c8 un grande punto di riferimento per me, anche dal punto di vista del comportamento. Mi piacerebbe essere come Ranieri.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/04\/il-lecce-a-cagliari-cerca-la-salvezza-matematica-si-gioca-domenica-5-ore-12-30-ecco-una-sintesi-delle-dichiarazioni-di-luca-gotti-nella-conferenza-stampa-della-vigilia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/04\/il-lecce-a-cagliari-cerca-la-salvezza-matematica-si-gioca-domenica-5-ore-12-30-ecco-una-sintesi-delle-dichiarazioni-di-luca-gotti-nella-conferenza-stampa-della-vigilia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) ______\u00a0 \u201cDiciamo che il Lecce forse \u00e8 gi\u00e0 salvo, probabilmente \u00e8 gi\u00e0 salvo, io penso che possa essere gi\u00e0 salvo. Ma la realt\u00e0 \u00e8 che oggi non lo \u00e8, lo dice la matematica. \u00c8 l\u2019unico modo giusto di vedere le cose&#8230; Si tratta di uno scontro diretto, le giornate diminuiscono, qesta e altre tre. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":229266,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229265"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=229265"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229265\/revisions"}],"predecessor-version":[{"id":229267,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229265\/revisions\/229267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/229266"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=229265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=229265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=229265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}