{"id":229358,"date":"2024-05-05T18:03:49","date_gmt":"2024-05-05T16:03:49","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=229358"},"modified":"2024-05-05T18:06:10","modified_gmt":"2024-05-05T16:06:10","slug":"siculella-con-il-giudice-mandoi-in-una-tavola-rotonda-a-lecce-lunedi-6","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/05\/siculella-con-il-giudice-mandoi-in-una-tavola-rotonda-a-lecce-lunedi-6\/","title":{"rendered":"SICULELLA CON IL GIUDICE MANDOI IN UNA TAVOLA ROTONDA A LECCE LUNEDI\u2019\u00a06"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1199\" height=\"901\" class=\"wp-image-229359\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/image1.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/image1.jpeg 1199w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/image1-300x225.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/image1-1024x769.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/image1-768x577.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/image1-400x300.jpeg 400w\" sizes=\"(max-width: 1199px) 100vw, 1199px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo.\u00a0______<\/p>\n\n\n\n<p>\u00a0Legalit\u00e0 e trasparenza: Alberto Siculella dialoga con il Giudice antimafia Francesco Mandoi.<\/p>\n\n\n\n<p>Si terr\u00e0 luned\u00ec 6 maggio, alle 18.30, in via Costadura 30, l\u2019ultima tavola rotonda del candidato Sindaco di Lecce, Alberto Siculella, che ha presentato e discusso il programma in sei eventi distinti, come le aree strategiche di cui si costituisce il documento programmatico con cui si presenta alle elezioni.<\/p>\n\n\n\n<p>\u201cNon \u00e8 un caso che concludiamo questo splendido percorso con il tavolo tematico su legalit\u00e0 e trasparenza. Avvertiamo la necessit\u00e0 di invertire la rotta, abbracciare metodi chiari e trasparenti, escludere scelte ed interpreti inopportuni, in favore di una politica che parli di cambiamenti e non di trasformismi.\u201d Sostiene Alberto Siculella, candidato civico con il supporto di due liste, Mind e Aria.<\/p>\n\n\n\n<p>\u201cCi sono strumenti che possono incidere sulla trasparenza dell\u2019ente e ci sono accorgimenti che possono prevenire coni d\u2019ombra in cui \u00e8 facile che si generino dinamiche poco chiare o, nel peggiore dei casi, illegali. Non dimentichiamoci che a Lecce \u00e8 in corso una indagine su pass ztl e multe annullate in cambio di voti\u201d conclude Siculella, lasciando intendere che la guardia non va abbassata.<\/p>\n\n\n\n<p>A dialogare con Siculella ci sar\u00e0 il Giudice Mandoi magistrato antimafia fino a quando \u00e8 andato in pensione con la qualifica di Presidente Onorario di Sezione della Suprema Corte di Cassazione.<\/p>\n\n\n\n<p>Mandoi trasferitosi a Lecce nel 1988, ha svolto anche in quell\u2019Ufficio la funzione di Sostituto Procuratore fino al \u201894. Presso la Procura di Lecce \u00e8 stato delegato, insieme al collega Motta, a rappresentare l\u2019accusa nello storico processo alla Sacra Corona Unita con il quale \u00e8 stata affermata la caratteristica mafiosa della organizzazione salentina. Entrato a far parte della Direzione Distrettuale Antimafia di Lecce sin dalla sua formazione, il Giudice sar\u00e0 disponibile ad un confronto con la cittadinanza.<\/p>\n\n\n\n<p>\u00a0<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/05\/siculella-con-il-giudice-mandoi-in-una-tavola-rotonda-a-lecce-lunedi-6\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/05\/siculella-con-il-giudice-mandoi-in-una-tavola-rotonda-a-lecce-lunedi-6\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo.\u00a0______ \u00a0Legalit\u00e0 e trasparenza: Alberto Siculella dialoga con il Giudice antimafia Francesco Mandoi. Si terr\u00e0 luned\u00ec 6 maggio, alle 18.30, in via Costadura 30, l\u2019ultima tavola rotonda del candidato Sindaco di Lecce, Alberto Siculella, che ha presentato e discusso il programma in sei eventi distinti, come le aree strategiche di cui si [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":229359,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,31,75,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229358"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=229358"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229358\/revisions"}],"predecessor-version":[{"id":229362,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229358\/revisions\/229362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/229359"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=229358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=229358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=229358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}