{"id":229480,"date":"2024-05-09T16:30:55","date_gmt":"2024-05-09T14:30:55","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=229480"},"modified":"2024-05-09T16:43:21","modified_gmt":"2024-05-09T14:43:21","slug":"i-soldi-facili-della-droga-alla-criminalita-la-disperazione-a-tanti-giovani-e-alle-loro-famiglie-a-lecce-una-guerra-quotidiana-delle-forze-dellordine-per-contrastare-lo-spaccio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/09\/i-soldi-facili-della-droga-alla-criminalita-la-disperazione-a-tanti-giovani-e-alle-loro-famiglie-a-lecce-una-guerra-quotidiana-delle-forze-dellordine-per-contrastare-lo-spaccio\/","title":{"rendered":"I SOLDI FACILI DELLA DROGA ALLA CRIMINALITA\u2019, LA DISPERAZIONE A TANTI GIOVANI E ALLE LORO FAMIGLIE. A LECCE UNA GUERRA QUOTIDIANA DELLA POLIZIA E DEI CARABINIERI  PER CONTRASTARE LO SPACCIO, IERI SERA UN ALTRO ARRESTO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"677\" class=\"wp-image-229484\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/Sequestro-stupefcente.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/Sequestro-stupefcente.jpg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/Sequestro-stupefcente-300x226.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/Sequestro-stupefcente-768x578.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/Sequestro-stupefcente-400x300.jpg 400w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>(e.l.) ______ Ieri sera gli agenti della Squadra Mobile della Questura di Lecce hanno arrestato in flagranza di reato Gianni Solombrino, 62 anni, di\u00a0Merine, con precedenti specifici, con l\u2019accusa di detenzione ai fini di spaccio di sostanze stupefacenti.<\/p>\n\n\n\n<p>Dopo alcuni giorni di pedinamenti, che avevano rafforzato i sospetti degli inquirenti, l\u2019 uomo \u00e8 stato bloccato, perquisito e trovato in possesso di diciassette dosi di cocaina. <\/p>\n\n\n\n<p>Nella successiva perquisizione al suo domicilio, gli agenti hanno trovato altri sessanta grammi di cocaina (nella foto). Si trova ora nel carcere di Borgo San Nicola, come disposto dal\u00a0pm di turno presso la Procura della Repubblica.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/09\/i-soldi-facili-della-droga-alla-criminalita-la-disperazione-a-tanti-giovani-e-alle-loro-famiglie-a-lecce-una-guerra-quotidiana-delle-forze-dellordine-per-contrastare-lo-spaccio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/09\/i-soldi-facili-della-droga-alla-criminalita-la-disperazione-a-tanti-giovani-e-alle-loro-famiglie-a-lecce-una-guerra-quotidiana-delle-forze-dellordine-per-contrastare-lo-spaccio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Ieri sera gli agenti della Squadra Mobile della Questura di Lecce hanno arrestato in flagranza di reato Gianni Solombrino, 62 anni, di\u00a0Merine, con precedenti specifici, con l\u2019accusa di detenzione ai fini di spaccio di sostanze stupefacenti. Dopo alcuni giorni di pedinamenti, che avevano rafforzato i sospetti degli inquirenti, l\u2019 uomo \u00e8 stato bloccato, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":229484,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229480"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=229480"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229480\/revisions"}],"predecessor-version":[{"id":229489,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229480\/revisions\/229489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/229484"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=229480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=229480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=229480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}