{"id":22959,"date":"2013-12-26T15:35:31","date_gmt":"2013-12-26T15:35:31","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=22959"},"modified":"2013-12-26T15:35:44","modified_gmt":"2013-12-26T15:35:44","slug":"premio-scola-federiciana-a-cavallino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/26\/premio-scola-federiciana-a-cavallino\/","title":{"rendered":"PREMIO &#8220;SCOLA FEDERICIANA&#8221; A CAVALLINO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\">Il Premio \u00abSc\u00f2la Federiciana &#8211; Polis e Logos &#8211; Festival internazionale della lingua italiana\u00bb approda a Cavallino. Sar\u00e0 la sfarzosa Galleria del Palazzo Ducale dei Castromediano di Cavallino ad ospitare domani sera alle 20.30 l\u2019evento diretto e fondato dall\u2019attore e regista Enzo Pascal Pezzato, siglato da\u00a0 Kh\u00e0risma Cineproduzioni Laboratorio Nazionale di Lingua Italiana Parlata e promosso da Regione Puglia, Provincia e Comune di\u00a0 Lecce &#8211;\u00a0 Presidenza del Consiglio e Universit\u00e0 del Salento, con la direzione organizzativa di Anna Murolo e che si propone di riportare anche nel Salento le origini della lingua italiana, vista come elemento fondante di una nuova \u00abRes Publica Federiciana\u00bb. I premi di questa edizione andranno a Fouad Alzouheir \u2013 giurista e storico, docente emerito dell\u2019Universit\u00e0 di Strarburgo; Venni Rinaldi, insigne pittore, autore di cento dipinti danteschi raffiguranti la Divina Commedia; Gino Pisan\u00f2 \u2013 Premio alla memoria \u2013 per la lodevole attivit\u00e0 svolta in qualit\u00e0 di Presidente dell\u2019Istituto di Culture Mediterranee. Ospiti della serata Raffaella Liccardi e Maria Scogna (soprani), Pascal Pezzato (regista e attore), Bianca Tragni (giornalista e scrittrice), Antonio Scarinci (chitarrista) e Antonella Paglialonga (scenografa). In anteprima nazionale \u201cAntichi mestieri \u2013 cartapesta\/arte sartoriale\/pietra leccese, tre cortometraggi scritti e diretti da Pascal Pezzuto prodotti da Kh\u00e0risma Cineproduzioni per il progetto Inter Company Generation. Il comitato scientifico \u00e8 composto da: prof. Egidio Zacheo (presidente), Prof.ssa Sandrina Schito (vicepresidente), avv. Carlo Ciardo, prof. Alessandro Laporta, dr. Luigi Mazzei, prof. Pascal Pezzuto. Conduce Daniela Panzera.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/26\/premio-scola-federiciana-a-cavallino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/26\/premio-scola-federiciana-a-cavallino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il Premio \u00abSc\u00f2la Federiciana &#8211; Polis e Logos &#8211; Festival internazionale della lingua italiana\u00bb approda a Cavallino. Sar\u00e0 la sfarzosa Galleria del Palazzo Ducale dei Castromediano di Cavallino ad ospitare domani sera alle 20.30 l\u2019evento diretto e fondato dall\u2019attore e regista Enzo Pascal Pezzato, siglato da\u00a0 Kh\u00e0risma Cineproduzioni Laboratorio Nazionale di Lingua Italiana Parlata e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22959"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=22959"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22959\/revisions"}],"predecessor-version":[{"id":22961,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/22959\/revisions\/22961"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=22959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=22959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=22959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}