{"id":229788,"date":"2024-05-18T15:35:01","date_gmt":"2024-05-18T13:35:01","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=229788"},"modified":"2024-05-19T12:13:09","modified_gmt":"2024-05-19T10:13:09","slug":"cateno-de-luca-domenica-19-nel-salento-17-30-a-casalabate-20-00-a-copertino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/18\/cateno-de-luca-domenica-19-nel-salento-17-30-a-casalabate-20-00-a-copertino\/","title":{"rendered":"CATENO DE LUCA DOMENICA 19 ARRIVA NEL SALENTO, ALLE 17.30 A CASALABATE, ALLE 20.00 A COPERTINO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2048\" height=\"1536\" class=\"wp-image-229789\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/441548719_998042801679039_5551712526046179750_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/441548719_998042801679039_5551712526046179750_n.jpg 2048w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/441548719_998042801679039_5551712526046179750_n-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/441548719_998042801679039_5551712526046179750_n-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/441548719_998042801679039_5551712526046179750_n-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/441548719_998042801679039_5551712526046179750_n-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/441548719_998042801679039_5551712526046179750_n-400x300.jpg 400w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. ______&nbsp;&nbsp;<\/p>\n\n\n\n<p>EUROPEE, DOMENICA 19 MAGGIO IL CAMPER DELLA LISTA LIBERT\u00c0 CON CATENO DE LUCA FA TAPPA IN PUGLIA<\/p>\n\n\n\n<p>Partito il 13 maggio da Fiumedinisi in provincia di Messina il Camper della Libert\u00e0 arriva in Puglia dopo aver toccato Liguria, Lombardia, Emilia Romagna, Toscana, Marche, Campania e Molise. Cateno De Luca, leader di Sud chiama Nord e federatore della lista Libert\u00e0 sar\u00e0 alle 9 a Bari per un caff\u00e8 alla Caffetteria Barucchelli in via del Ferrarese, 3. A seguire alle 10 a Rutigliano previsto un incontro presso Sala Monsignor di Donna. Alle 11.30 a Grumo incontro presso Balera da Mezzanotte in via Sanmicandr, 6. Sar\u00e0 alle 14.30 per una pausa caff\u00e8 a Polignano a mare presso Fcazz e berr. <\/p>\n\n\n\n<p>Il camper si sposter\u00e0 a Monopoli alle 15:30 dove \u00e8 previsto un incontro presso Bar Napoli. <\/p>\n\n\n\n<p>In seguito il camper si sposter\u00e0 alle 17.30 presso Lu Container Casalabate a Marina di Trepuzzi (LE).Infine il tour si concluder\u00e0 alle 20.00 a Copertino \u2013 Comizio Piazza Umberto.<\/p>\n\n\n\n<p>Ufficio Stampa<\/p>\n\n\n\n<p>Sud chiama Nord ______&nbsp;<\/p>\n\n\n\n<p>LA RICERCA nel nostro articolo immediatamente precedente<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"UJjtwI1EKU\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/18\/la-riflessione-un-voto-per-la-pace\/\">LA RIFLESSIONE \/\u00a0UN VOTO PER LA PACE<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;LA RIFLESSIONE \/\u00a0UN VOTO PER LA PACE&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/18\/la-riflessione-un-voto-per-la-pace\/embed\/#?secret=NiGxAQ8lIw#?secret=UJjtwI1EKU\" data-secret=\"UJjtwI1EKU\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>L<a href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/18\/novita-discografiche-esce-venti-minuti-di-liberta-esordio-di-emanuele-presta\/\">\u2019&nbsp;<\/a>APPROFONDIMENTO nel nostro articolo del 13 maggio scorso<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"W6bmCWauLw\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/13\/lintervento-il-mio-voto-scaglionato\/\">L\u2019INTERVENTO \/\u00a0IL MIO VOTO SCAGLIONATO<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;L\u2019INTERVENTO \/\u00a0IL MIO VOTO SCAGLIONATO&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/13\/lintervento-il-mio-voto-scaglionato\/embed\/#?secret=N8ZdtUDDAZ#?secret=W6bmCWauLw\" data-secret=\"W6bmCWauLw\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/18\/cateno-de-luca-domenica-19-nel-salento-17-30-a-casalabate-20-00-a-copertino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/18\/cateno-de-luca-domenica-19-nel-salento-17-30-a-casalabate-20-00-a-copertino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. ______&nbsp;&nbsp; EUROPEE, DOMENICA 19 MAGGIO IL CAMPER DELLA LISTA LIBERT\u00c0 CON CATENO DE LUCA FA TAPPA IN PUGLIA Partito il 13 maggio da Fiumedinisi in provincia di Messina il Camper della Libert\u00e0 arriva in Puglia dopo aver toccato Liguria, Lombardia, Emilia Romagna, Toscana, Marche, Campania e Molise. Cateno De Luca, leader [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229788"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=229788"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229788\/revisions"}],"predecessor-version":[{"id":229791,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229788\/revisions\/229791"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=229788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=229788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=229788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}