{"id":229981,"date":"2024-05-24T16:07:31","date_gmt":"2024-05-24T14:07:31","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=229981"},"modified":"2024-05-24T16:07:50","modified_gmt":"2024-05-24T14:07:50","slug":"polizia-di-stato-ad-alto-impatto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/24\/polizia-di-stato-ad-alto-impatto\/","title":{"rendered":"POLIZIA DI STATO \u201cad alto impatto\u201d\u2019"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"601\" class=\"wp-image-229982\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/perquisizione.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/perquisizione.jpg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/perquisizione-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/perquisizione-768x513.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n\n\n\n<p>(e.l.)\u00a0 ______\u00a0<\/p>\n\n\n\n<p>Sono stati predisposti dalla Polizia di Stato e dall\u2019Arma dei Carabinieri degli specifici servizi di prevenzione e repressione, cosiddetti \u201cad alto impatto\u201d. Questa mattina la seconda  fase, eseguita dalla Polizia di Stato (nella foto) a Nard\u00f2, Gallipoli e Taurisano. <\/p>\n\n\n\n<p>\u00a0I pricipali risultati operativi sono stati i seguenti.<\/p>\n\n\n\n<p>A Galatone \u00e8 arrestato un uomo di 49 anni di Nard\u00f2 con l\u2019accusa  di ricettazione e detenzione illegali di armi, trovato in possesso di un fucile d\u2019assalto russo con selettore semi-automatico e raffica \u2013 un caricatore per fucile AK-47 rifornito di 5 (cinque) cartucce cal. 7,62&#215;39 e venticinque cartucce cal. 7,62&#215;39, una pistola semiautomatica cal. 9 corto avente matricola abrasa con caricatore; una pistola, cal. 9 corto, scarica, diverse munizioni appartenenti alle armi rinvenuti nonch\u00e9 munizioni appartenenti ad altre tipologie di armi.<\/p>\n\n\n\n<p>A Gallipoli \u00e8 stato arrestato un giovane di 31 anni con l\u2019accusa  di detenzione ai fini di spaccio di<strong> <\/strong>sostanze stupefacenti, trovato in possesso di 90 grammi di hashish e 41 di marijuana.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/24\/polizia-di-stato-ad-alto-impatto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/24\/polizia-di-stato-ad-alto-impatto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)\u00a0 ______\u00a0 Sono stati predisposti dalla Polizia di Stato e dall\u2019Arma dei Carabinieri degli specifici servizi di prevenzione e repressione, cosiddetti \u201cad alto impatto\u201d. Questa mattina la seconda fase, eseguita dalla Polizia di Stato (nella foto) a Nard\u00f2, Gallipoli e Taurisano. \u00a0I pricipali risultati operativi sono stati i seguenti. A Galatone \u00e8 arrestato un uomo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":229982,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229981"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=229981"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229981\/revisions"}],"predecessor-version":[{"id":229983,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/229981\/revisions\/229983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/229982"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=229981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=229981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=229981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}