{"id":230008,"date":"2024-05-25T15:08:20","date_gmt":"2024-05-25T13:08:20","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=230008"},"modified":"2024-05-25T15:08:23","modified_gmt":"2024-05-25T13:08:23","slug":"carabinieri-ad-alto-impatto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/25\/carabinieri-ad-alto-impatto\/","title":{"rendered":"CARABINIERI \u201cad alto impatto\u201d"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"739\" height=\"720\" class=\"wp-image-230010\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/Foto-1-2.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/Foto-1-2.png 739w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/05\/Foto-1-2-300x292.png 300w\" sizes=\"(max-width: 739px) 100vw, 739px\" \/>(e.l.)\u00a0 ______\u00a0 Sono stati predisposti dalla Polizia di Stato e dall\u2019Arma dei Carabinieri degli specifici servizi di prevenzione e repressione, cosiddetti \u201cad alto impatto\u201d. Questa mattina la terza fase, eseguita dai Carabiieri, con \u00a0serrati controlli in tutto il Salento, dall\u2019entroterra alle varie zone costiere, e sulle principali arterie in ingresso e in uscita dei centri abitati.<\/p>\n\n\n\n<p>Sono stati controllati 548 veicoli e oltre 750 persone di cui 79 quelle gi\u00e0 sottoposte a misure limitative della libert\u00e0 personale.<\/p>\n\n\n\n<p>Cinque persone sono state denunciate a piede libero di cui una per guida in stato di ebrezza.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/25\/carabinieri-ad-alto-impatto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/05\/25\/carabinieri-ad-alto-impatto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)\u00a0 ______\u00a0 Sono stati predisposti dalla Polizia di Stato e dall\u2019Arma dei Carabinieri degli specifici servizi di prevenzione e repressione, cosiddetti \u201cad alto impatto\u201d. Questa mattina la terza fase, eseguita dai Carabiieri, con \u00a0serrati controlli in tutto il Salento, dall\u2019entroterra alle varie zone costiere, e sulle principali arterie in ingresso e in uscita dei centri [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":230010,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230008"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=230008"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230008\/revisions"}],"predecessor-version":[{"id":230011,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230008\/revisions\/230011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/230010"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=230008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=230008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=230008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}