{"id":230236,"date":"2024-06-01T14:33:30","date_gmt":"2024-06-01T12:33:30","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=230236"},"modified":"2024-06-01T14:42:53","modified_gmt":"2024-06-01T12:42:53","slug":"paris-nous-arrivons-le-azzurre-del-volley-cercano-il-pass-per-le-olimpiadi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/01\/paris-nous-arrivons-le-azzurre-del-volley-cercano-il-pass-per-le-olimpiadi\/","title":{"rendered":"\u201dParis, nous arrivons\u201c&#8230; LE AZZURRE DEL VOLLEY CERCANO IL PASS PER LE OLIMPIADI, IN PROGRAMMA DAL 26 LUGLIO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"656\" height=\"492\" class=\"wp-image-230237\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/ppp.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/ppp.jpg 656w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/ppp-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2024\/06\/ppp-400x300.jpg 400w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/p>\n\n\n\n<p>(e.v.)&nbsp; ______&nbsp;&nbsp;<\/p>\n\n\n\n<p>Quinta vittoria in sei partite per le Azzurre della pallavolo allenate da Julio Velasco&nbsp;nel torneo Nations League, in corso di svolgimento in varie sedi in tutto il mondo. Molti i punti messi a segno dalla stella della Nazionale Paola Egonu, (nella foto), 25&nbsp;anni, di Cittadella, 1.95&nbsp;di altezza. Ora le sfide pi\u00f9 impegnative contro Cina e Brasile.&nbsp;Azzurre vicine al loro obiettivo: staccare il visto per le Olimpiadi.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/01\/paris-nous-arrivons-le-azzurre-del-volley-cercano-il-pass-per-le-olimpiadi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2024\/06\/01\/paris-nous-arrivons-le-azzurre-del-volley-cercano-il-pass-per-le-olimpiadi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.v.)&nbsp; ______&nbsp;&nbsp; Quinta vittoria in sei partite per le Azzurre della pallavolo allenate da Julio Velasco&nbsp;nel torneo Nations League, in corso di svolgimento in varie sedi in tutto il mondo. Molti i punti messi a segno dalla stella della Nazionale Paola Egonu, (nella foto), 25&nbsp;anni, di Cittadella, 1.95&nbsp;di altezza. Ora le sfide pi\u00f9 impegnative contro [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":230237,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230236"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=230236"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230236\/revisions"}],"predecessor-version":[{"id":230241,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/230236\/revisions\/230241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/230237"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=230236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=230236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=230236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}