{"id":23050,"date":"2013-12-30T09:59:47","date_gmt":"2013-12-30T09:59:47","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=23050"},"modified":"2013-12-30T09:59:54","modified_gmt":"2013-12-30T09:59:54","slug":"il-capodanno-di-gallipoli-due-giornate-tra-tradizione-e-musica","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/30\/il-capodanno-di-gallipoli-due-giornate-tra-tradizione-e-musica\/","title":{"rendered":"IL CAPODANNO DI GALLIPOLI: DUE GIORNATE TRA TRADIZIONE E MUSICA"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\"><strong>\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-23050 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/Folkabbestia01-bassa.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/Folkabbestia01-bassa-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/Pupo-2012_abassa.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/Pupo-2012_abassa-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/Pupo-2012_bassa.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/12\/Pupo-2012_bassa-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n<\/p>\n<p><\/strong><\/p>\n<p>Per \u201cFiamme di Stelle\u201d il 30 dicembre i vorticosi ritmi dei TAMURR\u00ecA, il 31 dicembre lo sparo dei \u201cPupi\u201d e l\u2019infuocato concerto dei FOLKABBESTIA<\/p>\n<p style=\"text-align: justify;\"><strong>Torna a Gallipoli la seconda edizione dell&#8217;evento &#8220;Fiamme di Stelle&#8221;, una due giorni che trova il giusto connubio tra la musica, l&#8217;arte e la tradizione<\/strong>. Dinanzi all\u2019imponente \u201cPupo\u201d, un&#8217;opera in cartapesta innalzata nei suoi 10 metri al cospetto dello Ionio sul\u00a0<strong>Lungomare Galileo Galilei<\/strong>, realizzata da oltre 15 anni dall\u2019associazione Ampalea dei Leoni,\u00a0<strong>luned\u00ec 30 dicembre<\/strong>\u00a0si balla trascinati dai vorticosi ritmi popolari dei\u00a0<strong>Tammurr\u00eca<\/strong>, pizziche e tarante.<\/p>\n<p style=\"text-align: justify;\"><strong>Marted\u00ec 31 dicembre,<\/strong>\u00a0a conclusione del grandioso evento, sar\u00e0 la volta del concerto dei\u00a0<strong>Folkabbestia<\/strong>,\u00a0 la band che \u00e8 entrata nei Guinness dei primati nel novembre del 2003, per aver suonato la stessa canzone per 30 ore consecutive, dal popolare rock alla canzone d&#8217;autore, dallo ska al punk. Le &#8220;bbestie&#8221; del folk, a cavallo della mezzanotte, travolgeranno il pubblico in un concerto carico di energia.<\/p>\n<p style=\"text-align: justify;\"><strong>Non solo fuochi d&#8217;artificio e musica, ma anche stand enogastronomici<\/strong>\u00a0per salutare l&#8217;anno vecchio e festeggiare nel migliore dei modi l&#8217;arrivo dell&#8217;anno nuovo,\u00a0<strong>tutto ad ingresso gratuito<\/strong>\u00a0<strong>con l\u2019inizio dei concerti previsto a partire dalle ore 23:00<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Quella del \u201cPupo\u201d \u00e8 una tradizione tutta gallipolina che si perde nella notte dei tempi; si festeggia cos\u00ec la fine dell&#8217;anno vecchio e l&#8217;inizio del nuovo anno: con lo sparo del &#8220;Pupo&#8221; allo scoccare della mezzanotte, la notte di San Silvestro, scacciando cos\u00ec, in modo figurato, i malesseri dell&#8217;anno passato a ritmo di musica e sotto un cielo illuminato dai fuochi d&#8217;artificio.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/30\/il-capodanno-di-gallipoli-due-giornate-tra-tradizione-e-musica\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/12\/30\/il-capodanno-di-gallipoli-due-giornate-tra-tradizione-e-musica\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Per \u201cFiamme di Stelle\u201d il 30 dicembre i vorticosi ritmi dei TAMURR\u00ecA, il 31 dicembre lo sparo dei \u201cPupi\u201d e l\u2019infuocato concerto dei FOLKABBESTIA Torna a Gallipoli la seconda edizione dell&#8217;evento &#8220;Fiamme di Stelle&#8221;, una due giorni che trova il giusto connubio tra la musica, l&#8217;arte e la tradizione. Dinanzi all\u2019imponente \u201cPupo\u201d, un&#8217;opera in cartapesta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23052,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23050"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=23050"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23050\/revisions"}],"predecessor-version":[{"id":23055,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/23050\/revisions\/23055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/23052"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=23050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=23050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=23050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}